{"id":54623,"date":"2022-11-02T12:07:27","date_gmt":"2022-11-02T15:07:27","guid":{"rendered":"https:\/\/kimgsta.com\/pt\/?p=54623&#038;preview=true&#038;preview_id=54623"},"modified":"2025-02-07T11:20:24","modified_gmt":"2025-02-07T14:20:24","slug":"listar-banco-de-dados-mysql","status":"publish","type":"post","link":"https:\/\/kimgsta.com\/pt\/blog\/listar-banco-de-dados-mysql\/","title":{"rendered":"Como Listar Bancos de Dados MySQL (Guia Passo a Passo com C\u00f3digo)"},"content":{"rendered":"<p>O <a href=\"https:\/\/kimgsta.com\/pt\/blog\/o-que-e-mysql\/\" target=\"_blank\" rel=\"noopener noreferrer\">MySQL<\/a> \u00e9 um dos sistemas de gerenciamento de banco de dados relacionais (RDBMS) mais utilizados atualmente. \u00c9 uma plataforma de banco de dados robusta que permite a cria\u00e7\u00e3o e o gerenciamento de bancos de dados escal\u00e1veis, principalmente usando uma linguagem de consulta estruturada (SQL).<\/p>\n<p>O servidor MySQL \u00e9 o ambiente no qual os bancos de dados residem &#8211; e onde eles s\u00e3o acessados. Como administrador do servidor, voc\u00ea frequentemente precisar\u00e1 recuperar detalhes sobre este ambiente &#8211; listando os bancos de dados que vivem no servidor, exibindo tabelas de um banco de dados em particular, visualizando fun\u00e7\u00f5es e privil\u00e9gios do usu\u00e1rio, restri\u00e7\u00f5es de acesso, e assim por diante.<\/p>\n<p>Este artigo explicar\u00e1 como listar bancos de dados MySQL atrav\u00e9s do prompt de comando.<\/p>\n<div><\/div><kinsta-auto-toc heading=\"Table of Contents\" exclude=\"last\" list-style=\"arrow\" selector=\"h2\" count-number=\"-1\"><\/kinsta-auto-toc>\n<h2>Pr\u00e9-requisitos para listar os bancos de dados MySQL<\/h2>\n<p>Voc\u00ea deve ter o servidor MySQL rodando na sua m\u00e1quina local para come\u00e7ar. Se voc\u00ea n\u00e3o tiver o MySQL, h\u00e1 algumas maneiras de instal\u00e1-lo:<\/p>\n<ul>\n<li>Instale o <a href=\"https:\/\/kimgsta.com\/pt\/blog\/alternativas-mamp\/#2-wampserver\" target=\"_blank\" rel=\"noopener noreferrer\">WAMPServer<\/a>, <a href=\"https:\/\/kimgsta.com\/pt\/blog\/alternativas-mamp\/#3-xampp\" target=\"_blank\" rel=\"noopener noreferrer\">XAMPP<\/a>, <a href=\"https:\/\/kimgsta.com\/pt\/blog\/alternativas-mamp\/#pros-and-cons-of-mamp-and-when-to-consider-an-alternative\" target=\"_blank\" rel=\"noopener noreferrer\">MAMP<\/a>, ou qualquer outra pilha de distribui\u00e7\u00e3o de software que inclua o MySQL.<\/li>\n<li>Baixe e execute o <a href=\"https:\/\/dev.mysql.com\/downloads\/installer\/\" target=\"_blank\" rel=\"noopener noreferrer\">instalador do MySQL<\/a> diretamente do seu site oficial, passando pelo processo de configura\u00e7\u00e3o para configurar e instalar o servidor MySQL e outras ferramentas.<\/li>\n<\/ul>\n<p>Para executar convenientemente os comandos MySQL atrav\u00e9s da linha de comando, voc\u00ea precisar\u00e1 adicionar o caminho para o execut\u00e1vel MySQL ao ambiente do seu sistema. Se voc\u00ea instalou o MySQL usando a segunda op\u00e7\u00e3o, esta etapa n\u00e3o \u00e9 necess\u00e1ria, ent\u00e3o voc\u00ea pode passar para a pr\u00f3xima se\u00e7\u00e3o.<\/p>\n<h2>Adicione o caminho do MySQL para vari\u00e1veis de ambiente do seu sistema<\/h2>\n<p>Nesta se\u00e7\u00e3o, orientamos voc\u00ea a adicionar o caminho execut\u00e1vel MySQL para a vari\u00e1vel do seu ambiente se voc\u00ea estiver executando XAMPP ou WAMP em um computador Windows.<\/p>\n<p>Primeiro, abra seu explorador de arquivos Windows e navegue at\u00e9 <strong>Este PC<\/strong>. Clique no drive onde voc\u00ea instalou o pacote WAMP ou XAMPP (<strong>C:<\/strong>).<\/p>\n<p>Se voc\u00ea estiver executando XAMPP, navegue at\u00e9 <strong>xampp<\/strong> &gt; <strong>mysql<\/strong> &gt; <strong>bin<\/strong> e copie o caminho completo para a pasta <strong>bin<\/strong>. Para WAMP, navegue por <strong>{seu-wamp-vers\u00e3o}<\/strong> &gt; <strong>bin<\/strong> &gt; <strong>mysql<\/strong> &gt; <strong>{seu-mysql-vers\u00e3o}<\/strong> &gt; <strong>bin<\/strong> at\u00e9 o seu caminho completo.<\/p>\n<figure style=\"text-align: center\">\n<p><figure style=\"width: 647px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/kimgsta.com\/wp-content\/uploads\/2022\/10\/cli-mysql-fullpath.png\" alt=\"O caminho completo at\u00e9 a pasta bin.\" width=\"647\" height=\"244\"><figcaption class=\"wp-caption-text\">O caminho completo at\u00e9 a pasta bin.<\/figcaption><\/figure><\/figure>\n<p>Clique no menu <strong>Start<\/strong> e procure por &#8220;caminho&#8221;. Clique em <strong>Edit the system environment variable<\/strong>.<\/p>\n<p>Em seguida, clique em <strong>Environment Variables<\/strong> em <strong>Startup and Recovery<\/strong>, selecione a vari\u00e1vel PATH e clique em <strong>Edit<\/strong>.<\/p>\n<p>Em seguida, clique em <strong>New<\/strong> e cole o caminho completo para o seu execut\u00e1vel MySQL (que voc\u00ea copiou antes).<\/p>\n<figure style=\"text-align: center\">\n<p><figure style=\"width: 525px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/kimgsta.com\/wp-content\/uploads\/2022\/10\/edit-environment-variables-menu.png\" alt=\"Editando a vari\u00e1vel de ambiente.\" width=\"525\" height=\"206\"><figcaption class=\"wp-caption-text\">Editando a vari\u00e1vel de ambiente.<\/figcaption><\/figure><\/figure>\n<p>Ent\u00e3o, salve as mudan\u00e7as clicando em <strong>OK<\/strong>.<\/p>\n<p>Agora que o caminho foi adicionado, voc\u00ea pode executar os comandos do MySQL no terminal.<\/p>\n<h2>Login no MySQL<\/h2>\n<p>Para listar bancos de dados MySQL, o usu\u00e1rio deve estar autorizado a acessar todos os bancos de dados, ou voc\u00ea deve definir um privil\u00e9gio global <code>SHOW DATABASES<\/code> que conceda acesso a todos os usu\u00e1rios.<\/p>\n<p>Certifique-se de que seu servidor MySQL est\u00e1 rodando antes de entrar no sistema atrav\u00e9s do prompt de comando:<\/p>\n<pre><code class=\"language-bash\">mysql -u  -p<\/code><\/pre>\n<p>NOTA: substitua <code><\/code> pelo seu nome de usu\u00e1rio. O nome de usu\u00e1rio padr\u00e3o para o MySQL \u00e9 <code>root<\/code>, e a senha est\u00e1 vazia (n\u00e3o h\u00e1 senha por padr\u00e3o).<\/p>\n<figure style=\"text-align: center\">\n<p><figure style=\"width: 632px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/kimgsta.com\/wp-content\/uploads\/2022\/10\/MySQL-login-terminal.png\" alt=\"Login no MySQL\" width=\"632\" height=\"335\"><figcaption class=\"wp-caption-text\">Login no MySQL<\/figcaption><\/figure><\/figure>\n<h2>Mostrar bancos de dados no servidor MySQL<\/h2>\n<p>Agora que voc\u00ea est\u00e1 logado, voc\u00ea pode listar os bancos de dados MySQL presentes no servidor executando o comando <code>SHOW DATABASES<\/code>:<\/p>\n<pre><code class=\"language-sql\">SHOW DATABASES;<\/code><\/pre>\n<p>Em troca, voc\u00ea recebe todos os bancos de dados presentes no armazenamento:<\/p>\n<figure style=\"text-align: center\">\n<p><figure style=\"width: 220px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/kimgsta.com\/wp-content\/uploads\/2022\/10\/show-MySQL-databases.png\" alt=\"Uma lista de bancos de dados em armazenamento.\" width=\"220\" height=\"232\"><figcaption class=\"wp-caption-text\">Uma lista de bancos de dados em armazenamento.<\/figcaption><\/figure><\/figure>\n<p>Dos seis bancos de dados retornados, <code>information_schema<\/code> e <code>performance_schema<\/code> s\u00e3o os bancos de dados padr\u00e3o, gerados automaticamente quando voc\u00ea instala o MySQL.<\/p>\n<p>O banco de dados <code>information_schema<\/code> \u00e9 um banco de dados n\u00e3o modific\u00e1vel que armazena todas as informa\u00e7\u00f5es relacionadas a bancos de dados e outros objetos (visualiza\u00e7\u00f5es, privil\u00e9gios de usu\u00e1rios, tabelas, restri\u00e7\u00f5es, etc.) armazenados no servidor MySQL.<\/p>\n<h2>Filtrando os resultados da sa\u00edda do banco de dados<\/h2>\n<p>Anteriormente, todas as bases de dados no servidor MySQL eram exibidas com <code>SHOW DATABASES<\/code>, mas muitas vezes voc\u00ea tem que filtrar a sa\u00edda do banco de dados, principalmente quando h\u00e1 muitos bancos de dados no servidor.<\/p>\n<p>A cl\u00e1usula <code>LIKE<\/code> filtra o resultado de <code>SHOW DATABASE<\/code> com base em um padr\u00e3o especificado. Aqui est\u00e1 a sintaxe geral:<\/p>\n<pre><code class=\"language-sql\">SHOW DATABASES LIKE '';<\/code><\/pre>\n<p>Deve ser uma string representando o padr\u00e3o que voc\u00ea quer combinar. A string deve terminar com o s\u00edmbolo de porcentagem, <code>%<\/code>, que denota um ou mais caracteres.<\/p>\n<p>Por exemplo, se voc\u00ea quiser exibir apenas os bancos de dados cujos nomes come\u00e7am com a carta <code>w<\/code>, voc\u00ea o faz executando o seguinte:<\/p>\n<pre><code class=\"language-sql\">SHOW DATABASES LIKE 'w%';<\/code><\/pre>\n<p>Aqui est\u00e1 o resultado filtrado:<\/p>\n<figure style=\"text-align: center\">\n<p><figure style=\"width: 270px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/kimgsta.com\/wp-content\/uploads\/2022\/10\/filter-list-mysql-databases.png\" alt=\"A resposta filtrada do banco de dados ao usar 'w%'.\" width=\"270\" height=\"153\"><figcaption class=\"wp-caption-text\">A resposta filtrada do banco de dados ao usar &#8216;w%&#8217;.<\/figcaption><\/figure><\/figure>\n<h2>Usando o esquema de informa\u00e7\u00e3o para consultar os metadados da tabela<\/h2>\n<p>Anteriormente, voc\u00ea viu como o banco de dados <code>information_schema<\/code> armazena todas as informa\u00e7\u00f5es relacionadas a bancos de dados, tabelas e outros objetos no ambiente do servidor MySQL.<\/p>\n<p>O banco de dados <code>information_schema<\/code> usa a tabela de esquemas para armazenar informa\u00e7\u00f5es sobre todos os bancos de dados. Para filtragem de bancos de dados, voc\u00ea pode realizar uma pesquisa complexa para consultar a tabela de esquemas de bancos de dados espec\u00edficos.<\/p>\n<p>Por exemplo, se voc\u00ea quiser bancos de dados cujos nomes comecem com &#8220;samp&#8221; ou &#8220;word&#8221;, voc\u00ea pode combinar v\u00e1rias outras cl\u00e1usulas para fazer uma consulta complexa:<\/p>\n<pre><code class=\"language-sql\">SELECT schema_name FROM information_schema.schemata WHERE schema_name LIKE 'samp%' OR schema_name LIKE 'word%';<\/code><\/pre>\n<p>Aqui est\u00e1 o resultado:<\/p>\n<figure style=\"text-align: center\">\n<p><figure style=\"width: 247px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/kimgsta.com\/wp-content\/uploads\/2022\/10\/MySQL-SELECT-schema_name-FROM.png\" alt=\"Os resultados da complexa consulta.\" width=\"247\" height=\"161\"><figcaption class=\"wp-caption-text\">Os resultados da complexa consulta.<\/figcaption><\/figure><\/figure>\n<p>Al\u00e9m disso, voc\u00ea tem a tabela <code>tables<\/code> do banco de dados <code>information_schema<\/code>, que cont\u00e9m informa\u00e7\u00f5es sobre todas as tabelas. Da mesma forma, voc\u00ea pode realizar uma consulta para recuperar apenas as tabelas que correspondem a um padr\u00e3o especificado.<\/p>\n<p>Por exemplo, a consulta a seguir retorna as informa\u00e7\u00f5es do esquema apenas das <a href=\"https:\/\/kimgsta.com\/pt\/blog\/banco-de-dados-wordpress\/\" target=\"_blank\" rel=\"noopener noreferrer\">tabelas do WordPress<\/a> &#8211; apenas as tabelas cujos nomes come\u00e7am com &#8220;wp_&#8221;:<\/p>\n<pre><code class=\"language-sql\">SELECT * FROM information_schema.tables WHERE table_name LIKE 'wp_%';<\/code><\/pre>\n<p>Aqui est\u00e1 o resultado:<\/p>\n<figure style=\"text-align: center\">\n<p><figure style=\"width: 929px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/kimgsta.com\/wp-content\/uploads\/2022\/10\/wp_tables-list-MySQL-database.png\" alt=\"Os resultados das informa\u00e7\u00f5es do esquema apenas das tabelas do WordPress\" width=\"929\" height=\"515\"><figcaption class=\"wp-caption-text\">Os resultados das informa\u00e7\u00f5es do esquema apenas das tabelas do WordPress<\/figcaption><\/figure><\/figure>\n<p>Outras tabelas encontradas em <code>information_schema<\/code> incluem <code>columns<\/code>, <code>constraints<\/code>, <code>table_constraints<\/code>, <code>check_constraints<\/code>, e <code>referential_constraints<\/code>.<\/p>\n<h2>Problemas comuns e boas pr\u00e1ticas<\/h2>\n<p>Uma das causas mais comuns de erros ao executar SQL \u00e9 a falha em usar um ponto-e-v\u00edrgula no final das instru\u00e7\u00f5es.<\/p>\n<p>Outra \u00e9 o uso de sintaxe SQL inv\u00e1lida ou um nome de tabela\/coluna digitado incorretamente. Para evitar este problema, verifique a tabela ou o nome da coluna para ter certeza de que est\u00e1 escrito corretamente. Verifique tamb\u00e9m a sintaxe.<\/p>\n<p>Aqui est\u00e3o algumas outras melhores pr\u00e1ticas para ter em mente.<\/p>\n<h3>Use letras mai\u00fasculas para palavras-chave SQL<\/h3>\n<p>Ao escrever c\u00f3digo SQL, sempre use mai\u00fasculas para palavras-chave SQL e min\u00fasculas para nomes de tabelas e nomes de colunas. Isso torna seu c\u00f3digo mais leg\u00edvel e menos suscet\u00edvel a erros.<\/p>\n<p>Ent\u00e3o, ao inv\u00e9s disso:<\/p>\n<pre><code class=\"language-sql\">select * from information_schema.tables where table_name like 'wp_%';<\/code><\/pre>\n<p>Fa\u00e7a isso:<\/p>\n<pre><code class=\"language-sql\">SELECT * FROM information_schema.tables WHERE table_name LIKE 'wp_%';<\/code><\/pre>\n<h3>Evite Usar <code>SELECT *<\/code><\/h3>\n<p>Evite usar <code>SELECT *<\/code> em suas consultas SQL. Seu pedido n\u00e3o est\u00e1 claro porque voc\u00ea nem sempre pode saber o que ele retornar\u00e1. Ao inv\u00e9s disso, especifique as colunas que voc\u00ea deseja selecionar da tabela.<\/p>\n<p>Ent\u00e3o, ao inv\u00e9s disso:<\/p>\n<pre><code class=\"language-sql\">SELECT * EXCEPT(phone) FROM users.profile<\/code><\/pre>\n<p>Fa\u00e7a isso:<\/p>\n<pre><code class=\"language-sql\">SELECT name,\n    dob,\n    address,\n    country,\n    address,\nFROM user.profile<\/code><\/pre>\n<h3>Indique seu c\u00f3digo<\/h3>\n<p>Finalmente, outra dica para facilitar a busca de erros \u00e9 abreviar o c\u00f3digo porque o torna mais leg\u00edvel.<\/p>\n<h2>Gerenciamento do banco de dados<\/h2>\n<p>Alternativamente, voc\u00ea pode escolher gerenciar seus bancos de dados sem escrever SQL atrav\u00e9s do uso de um gerenciador de banco de dados. Isto permite aos usu\u00e1rios acessar as fun\u00e7\u00f5es de gerenciamento do banco de dados sem a necessidade de escrever consultas SQL. Este software se conecta a um servidor MySQL e fornece uma interface de usu\u00e1rio para expor as fun\u00e7\u00f5es do banco de dados. Uma vez conectado, a interface de usu\u00e1rio mostrar\u00e1 todos os bancos de dados no servidor. A apar\u00eancia e a sensa\u00e7\u00e3o variam entre as ferramentas de gerenciamento, mas o processo \u00e9 similar.<\/p>\n<figure id=\"attachment_95411\" aria-describedby=\"caption-attachment-95411\" style=\"width: 1200px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-95411 size-full\" src=\"https:\/\/kimgsta.com\/wp-content\/uploads\/2021\/05\/devkinsta-adminer.png\" alt=\"Gerenciamento do banco de dados da DevKinsta.\" width=\"1200\" height=\"624\"><figcaption id=\"caption-attachment-95411\" class=\"wp-caption-text\">Gerenciamento do banco de dados da DevKinsta.<\/figcaption><\/figure>\n<p>V\u00e1rias ferramentas est\u00e3o dispon\u00edveis para escolha, incluindo <a href=\"https:\/\/kimgsta.com\/pt\/docs\/hospedagem-de-wordpress\/gerenciamento-de-banco-de-dados\/acesso-ao-banco-de-dados-wordpress\/\" target=\"_blank\" rel=\"noopener noreferrer\">phpMyAdmin<\/a> e <a href=\"https:\/\/kimgsta.com\/pt\/topicos\/adminer\/\" target=\"_blank\" rel=\"noopener noreferrer\">Adminer<\/a>, ambas acess\u00edveis atrav\u00e9s da <a href=\"https:\/\/kimgsta.com\/pt\/devkinsta\/\" target=\"_blank\" rel=\"noopener noreferrer\">DevKinsta<\/a>. A ferramenta de gerenciamento padr\u00e3o para o DevKinsta \u00e9 Adminer, pois \u00e9 leve, f\u00e1cil e r\u00e1pida, <a href=\"https:\/\/kimgsta.com\/pt\/docs\/hospedagem-de-wordpress\/gerenciamento-de-banco-de-dados\/acesso-ao-banco-de-dados-wordpress\/\" target=\"_blank\" rel=\"noopener noreferrer\">mas o phpMyAdmin pode ser acessado com facilidade<\/a>.<\/p>\n<h2>Resumo<\/h2>\n<p>Como administrador do servidor, voc\u00ea precisa ser capaz de recuperar detalhes sobre os bancos de dados em seu servidor MySQL de forma eficiente e precisa. As habilidades para ver quais bancos de dados est\u00e3o no servidor, ver tabelas espec\u00edficas e as informa\u00e7\u00f5es de dentro delas e acessar informa\u00e7\u00f5es sobre as fun\u00e7\u00f5es e privil\u00e9gios do usu\u00e1rio s\u00e3o todas tarefas cruciais. O uso de SQL a partir da linha de comando pode simplificar muito este processo.<\/p>\n<p><em>Quando o gerenciamento do banco de dados vai al\u00e9m de consultar tabelas, Kinsta pode ajudar. Saiba mais sobre nossas <a href=\"https:\/\/sevalla.com\/application-hosting\/\">solu\u00e7\u00f5es escal\u00e1veis de hospedagem de banco de dados<\/a>!\u00a0<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O MySQL \u00e9 um dos sistemas de gerenciamento de banco de dados relacionais (RDBMS) mais utilizados atualmente. \u00c9 uma plataforma de banco de dados robusta que &#8230;<\/p>\n","protected":false},"author":117,"featured_media":54624,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_kinsta_gated_content":false,"_kinsta_gated_content_redirect":"","footnotes":""},"tags":[75,44],"topic":[948,990,962],"class_list":["post-54623","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","tag-mysql","tag-webdev","topic-adminer","topic-banco-de-dados-mysql","topic-devkinsta"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.6 (Yoast SEO v24.6) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Como Listar Bancos de Dados MySQL (Guia Passo a Passo com C\u00f3digo)<\/title>\n<meta name=\"description\" content=\"Habilite a administra\u00e7\u00e3o do seu servidor aprendendo as entradas e sa\u00eddas de como listar bancos de dados MySQL usando comandos no terminal.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/kimgsta.com\/pt\/blog\/listar-banco-de-dados-mysql\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Como Listar Bancos de Dados MySQL (Guia Passo a Passo com C\u00f3digo)\" \/>\n<meta property=\"og:description\" content=\"Habilite a administra\u00e7\u00e3o do seu servidor aprendendo as entradas e sa\u00eddas de como listar bancos de dados MySQL usando comandos no terminal.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kimgsta.com\/pt\/blog\/listar-banco-de-dados-mysql\/\" \/>\n<meta property=\"og:site_name\" content=\"Kinsta\u00ae\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/kinstapt\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-11-02T15:07:27+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-07T14:20:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/kimgsta.com\/pt\/wp-content\/uploads\/sites\/3\/2022\/11\/mysql-list-databases.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1460\" \/>\n\t<meta property=\"og:image:height\" content=\"730\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Salman Ravoof\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:description\" content=\"Habilite a administra\u00e7\u00e3o do seu servidor aprendendo as entradas e sa\u00eddas de como listar bancos de dados MySQL usando comandos no terminal.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/kimgsta.com\/pt\/wp-content\/uploads\/sites\/3\/2022\/11\/mysql-list-databases.png\" \/>\n<meta name=\"twitter:creator\" content=\"@salmanravoof\" \/>\n<meta name=\"twitter:site\" content=\"@kinsta_pt\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Salman Ravoof\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/kimgsta.com\/pt\/blog\/listar-banco-de-dados-mysql\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/kimgsta.com\/pt\/blog\/listar-banco-de-dados-mysql\/\"},\"author\":{\"name\":\"Salman Ravoof\",\"@id\":\"https:\/\/kimgsta.com\/pt\/#\/schema\/person\/9cafd2eedd617e640eeea4cf3a5fd987\"},\"headline\":\"Como Listar Bancos de Dados MySQL (Guia Passo a Passo com C\u00f3digo)\",\"datePublished\":\"2022-11-02T15:07:27+00:00\",\"dateModified\":\"2025-02-07T14:20:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/kimgsta.com\/pt\/blog\/listar-banco-de-dados-mysql\/\"},\"wordCount\":1541,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/kimgsta.com\/pt\/#organization\"},\"image\":{\"@id\":\"https:\/\/kimgsta.com\/pt\/blog\/listar-banco-de-dados-mysql\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/kimgsta.com\/pt\/wp-content\/uploads\/sites\/3\/2022\/11\/mysql-list-databases.png\",\"keywords\":[\"mySQL\",\"webdev\"],\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/kimgsta.com\/pt\/blog\/listar-banco-de-dados-mysql\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/kimgsta.com\/pt\/blog\/listar-banco-de-dados-mysql\/\",\"url\":\"https:\/\/kimgsta.com\/pt\/blog\/listar-banco-de-dados-mysql\/\",\"name\":\"Como Listar Bancos de Dados MySQL (Guia Passo a Passo com C\u00f3digo)\",\"isPartOf\":{\"@id\":\"https:\/\/kimgsta.com\/pt\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/kimgsta.com\/pt\/blog\/listar-banco-de-dados-mysql\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/kimgsta.com\/pt\/blog\/listar-banco-de-dados-mysql\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/kimgsta.com\/pt\/wp-content\/uploads\/sites\/3\/2022\/11\/mysql-list-databases.png\",\"datePublished\":\"2022-11-02T15:07:27+00:00\",\"dateModified\":\"2025-02-07T14:20:24+00:00\",\"description\":\"Habilite a administra\u00e7\u00e3o do seu servidor aprendendo as entradas e sa\u00eddas de como listar bancos de dados MySQL usando comandos no terminal.\",\"breadcrumb\":{\"@id\":\"https:\/\/kimgsta.com\/pt\/blog\/listar-banco-de-dados-mysql\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/kimgsta.com\/pt\/blog\/listar-banco-de-dados-mysql\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\/\/kimgsta.com\/pt\/blog\/listar-banco-de-dados-mysql\/#primaryimage\",\"url\":\"https:\/\/kimgsta.com\/pt\/wp-content\/uploads\/sites\/3\/2022\/11\/mysql-list-databases.png\",\"contentUrl\":\"https:\/\/kimgsta.com\/pt\/wp-content\/uploads\/sites\/3\/2022\/11\/mysql-list-databases.png\",\"width\":1460,\"height\":730},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/kimgsta.com\/pt\/blog\/listar-banco-de-dados-mysql\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/kimgsta.com\/pt\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Banco de dados MySQL\",\"item\":\"https:\/\/kimgsta.com\/pt\/topicos\/banco-de-dados-mysql\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Como Listar Bancos de Dados MySQL (Guia Passo a Passo com C\u00f3digo)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/kimgsta.com\/pt\/#website\",\"url\":\"https:\/\/kimgsta.com\/pt\/\",\"name\":\"Kinsta\u00ae\",\"description\":\"Solu\u00e7\u00f5es de hospedagem Premium, r\u00e1pida e segura\",\"publisher\":{\"@id\":\"https:\/\/kimgsta.com\/pt\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/kimgsta.com\/pt\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/kimgsta.com\/pt\/#organization\",\"name\":\"Kinsta\",\"url\":\"https:\/\/kimgsta.com\/pt\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\/\/kimgsta.com\/pt\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/kimgsta.com\/pt\/wp-content\/uploads\/sites\/3\/2023\/12\/kinsta-logo.jpeg\",\"contentUrl\":\"https:\/\/kimgsta.com\/pt\/wp-content\/uploads\/sites\/3\/2023\/12\/kinsta-logo.jpeg\",\"width\":500,\"height\":500,\"caption\":\"Kinsta\"},\"image\":{\"@id\":\"https:\/\/kimgsta.com\/pt\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/kinstapt\/\",\"https:\/\/x.com\/kinsta_pt\",\"https:\/\/www.instagram.com\/kinstahosting\/\",\"https:\/\/www.linkedin.com\/company\/kinsta\/\",\"https:\/\/www.pinterest.com\/kinstahosting\/\",\"https:\/\/www.youtube.com\/c\/Kinsta\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/kimgsta.com\/pt\/#\/schema\/person\/9cafd2eedd617e640eeea4cf3a5fd987\",\"name\":\"Salman Ravoof\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\/\/kimgsta.com\/pt\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/0c5885f75cb78473fb7408e5e49ad190?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/0c5885f75cb78473fb7408e5e49ad190?s=96&d=mm&r=g\",\"caption\":\"Salman Ravoof\"},\"description\":\"Salman Ravoof is a self-taught web developer, writer, creator, and a huge admirer of Free and Open Source Software (FOSS). Besides tech, he's excited by science, philosophy, photography, arts, cats, and food. Learn more about him on his website, and connect with Salman on Twitter.\",\"sameAs\":[\"https:\/\/salmanravoof.com\",\"https:\/\/www.linkedin.com\/in\/salman-ravoof-5a749133\/\",\"https:\/\/x.com\/salmanravoof\"],\"url\":\"https:\/\/kimgsta.com\/pt\/blog\/author\/salmanravoof\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Como Listar Bancos de Dados MySQL (Guia Passo a Passo com C\u00f3digo)","description":"Habilite a administra\u00e7\u00e3o do seu servidor aprendendo as entradas e sa\u00eddas de como listar bancos de dados MySQL usando comandos no terminal.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/kimgsta.com\/pt\/blog\/listar-banco-de-dados-mysql\/","og_locale":"pt_PT","og_type":"article","og_title":"Como Listar Bancos de Dados MySQL (Guia Passo a Passo com C\u00f3digo)","og_description":"Habilite a administra\u00e7\u00e3o do seu servidor aprendendo as entradas e sa\u00eddas de como listar bancos de dados MySQL usando comandos no terminal.","og_url":"https:\/\/kimgsta.com\/pt\/blog\/listar-banco-de-dados-mysql\/","og_site_name":"Kinsta\u00ae","article_publisher":"https:\/\/www.facebook.com\/kinstapt\/","article_published_time":"2022-11-02T15:07:27+00:00","article_modified_time":"2025-02-07T14:20:24+00:00","og_image":[{"width":1460,"height":730,"url":"https:\/\/kimgsta.com\/pt\/wp-content\/uploads\/sites\/3\/2022\/11\/mysql-list-databases.png","type":"image\/png"}],"author":"Salman Ravoof","twitter_card":"summary_large_image","twitter_description":"Habilite a administra\u00e7\u00e3o do seu servidor aprendendo as entradas e sa\u00eddas de como listar bancos de dados MySQL usando comandos no terminal.","twitter_image":"https:\/\/kimgsta.com\/pt\/wp-content\/uploads\/sites\/3\/2022\/11\/mysql-list-databases.png","twitter_creator":"@salmanravoof","twitter_site":"@kinsta_pt","twitter_misc":{"Escrito por":"Salman Ravoof","Tempo estimado de leitura":"9 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/kimgsta.com\/pt\/blog\/listar-banco-de-dados-mysql\/#article","isPartOf":{"@id":"https:\/\/kimgsta.com\/pt\/blog\/listar-banco-de-dados-mysql\/"},"author":{"name":"Salman Ravoof","@id":"https:\/\/kimgsta.com\/pt\/#\/schema\/person\/9cafd2eedd617e640eeea4cf3a5fd987"},"headline":"Como Listar Bancos de Dados MySQL (Guia Passo a Passo com C\u00f3digo)","datePublished":"2022-11-02T15:07:27+00:00","dateModified":"2025-02-07T14:20:24+00:00","mainEntityOfPage":{"@id":"https:\/\/kimgsta.com\/pt\/blog\/listar-banco-de-dados-mysql\/"},"wordCount":1541,"commentCount":0,"publisher":{"@id":"https:\/\/kimgsta.com\/pt\/#organization"},"image":{"@id":"https:\/\/kimgsta.com\/pt\/blog\/listar-banco-de-dados-mysql\/#primaryimage"},"thumbnailUrl":"https:\/\/kimgsta.com\/pt\/wp-content\/uploads\/sites\/3\/2022\/11\/mysql-list-databases.png","keywords":["mySQL","webdev"],"inLanguage":"pt-PT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/kimgsta.com\/pt\/blog\/listar-banco-de-dados-mysql\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/kimgsta.com\/pt\/blog\/listar-banco-de-dados-mysql\/","url":"https:\/\/kimgsta.com\/pt\/blog\/listar-banco-de-dados-mysql\/","name":"Como Listar Bancos de Dados MySQL (Guia Passo a Passo com C\u00f3digo)","isPartOf":{"@id":"https:\/\/kimgsta.com\/pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/kimgsta.com\/pt\/blog\/listar-banco-de-dados-mysql\/#primaryimage"},"image":{"@id":"https:\/\/kimgsta.com\/pt\/blog\/listar-banco-de-dados-mysql\/#primaryimage"},"thumbnailUrl":"https:\/\/kimgsta.com\/pt\/wp-content\/uploads\/sites\/3\/2022\/11\/mysql-list-databases.png","datePublished":"2022-11-02T15:07:27+00:00","dateModified":"2025-02-07T14:20:24+00:00","description":"Habilite a administra\u00e7\u00e3o do seu servidor aprendendo as entradas e sa\u00eddas de como listar bancos de dados MySQL usando comandos no terminal.","breadcrumb":{"@id":"https:\/\/kimgsta.com\/pt\/blog\/listar-banco-de-dados-mysql\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/kimgsta.com\/pt\/blog\/listar-banco-de-dados-mysql\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/kimgsta.com\/pt\/blog\/listar-banco-de-dados-mysql\/#primaryimage","url":"https:\/\/kimgsta.com\/pt\/wp-content\/uploads\/sites\/3\/2022\/11\/mysql-list-databases.png","contentUrl":"https:\/\/kimgsta.com\/pt\/wp-content\/uploads\/sites\/3\/2022\/11\/mysql-list-databases.png","width":1460,"height":730},{"@type":"BreadcrumbList","@id":"https:\/\/kimgsta.com\/pt\/blog\/listar-banco-de-dados-mysql\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/kimgsta.com\/pt\/"},{"@type":"ListItem","position":2,"name":"Banco de dados MySQL","item":"https:\/\/kimgsta.com\/pt\/topicos\/banco-de-dados-mysql\/"},{"@type":"ListItem","position":3,"name":"Como Listar Bancos de Dados MySQL (Guia Passo a Passo com C\u00f3digo)"}]},{"@type":"WebSite","@id":"https:\/\/kimgsta.com\/pt\/#website","url":"https:\/\/kimgsta.com\/pt\/","name":"Kinsta\u00ae","description":"Solu\u00e7\u00f5es de hospedagem Premium, r\u00e1pida e segura","publisher":{"@id":"https:\/\/kimgsta.com\/pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/kimgsta.com\/pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/kimgsta.com\/pt\/#organization","name":"Kinsta","url":"https:\/\/kimgsta.com\/pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/kimgsta.com\/pt\/#\/schema\/logo\/image\/","url":"https:\/\/kimgsta.com\/pt\/wp-content\/uploads\/sites\/3\/2023\/12\/kinsta-logo.jpeg","contentUrl":"https:\/\/kimgsta.com\/pt\/wp-content\/uploads\/sites\/3\/2023\/12\/kinsta-logo.jpeg","width":500,"height":500,"caption":"Kinsta"},"image":{"@id":"https:\/\/kimgsta.com\/pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/kinstapt\/","https:\/\/x.com\/kinsta_pt","https:\/\/www.instagram.com\/kinstahosting\/","https:\/\/www.linkedin.com\/company\/kinsta\/","https:\/\/www.pinterest.com\/kinstahosting\/","https:\/\/www.youtube.com\/c\/Kinsta"]},{"@type":"Person","@id":"https:\/\/kimgsta.com\/pt\/#\/schema\/person\/9cafd2eedd617e640eeea4cf3a5fd987","name":"Salman Ravoof","image":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/kimgsta.com\/pt\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/0c5885f75cb78473fb7408e5e49ad190?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0c5885f75cb78473fb7408e5e49ad190?s=96&d=mm&r=g","caption":"Salman Ravoof"},"description":"Salman Ravoof is a self-taught web developer, writer, creator, and a huge admirer of Free and Open Source Software (FOSS). Besides tech, he's excited by science, philosophy, photography, arts, cats, and food. Learn more about him on his website, and connect with Salman on Twitter.","sameAs":["https:\/\/salmanravoof.com","https:\/\/www.linkedin.com\/in\/salman-ravoof-5a749133\/","https:\/\/x.com\/salmanravoof"],"url":"https:\/\/kimgsta.com\/pt\/blog\/author\/salmanravoof\/"}]}},"acf":[],"_links":{"self":[{"href":"https:\/\/kimgsta.com\/pt\/wp-json\/wp\/v2\/posts\/54623","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kimgsta.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/kimgsta.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/kimgsta.com\/pt\/wp-json\/wp\/v2\/users\/117"}],"replies":[{"embeddable":true,"href":"https:\/\/kimgsta.com\/pt\/wp-json\/wp\/v2\/comments?post=54623"}],"version-history":[{"count":8,"href":"https:\/\/kimgsta.com\/pt\/wp-json\/wp\/v2\/posts\/54623\/revisions"}],"predecessor-version":[{"id":54853,"href":"https:\/\/kimgsta.com\/pt\/wp-json\/wp\/v2\/posts\/54623\/revisions\/54853"}],"alternate":[{"embeddable":true,"hreflang":"en","title":"English","href":"https:\/\/kimgsta.com\/pt\/wp-json\/kinsta\/v1\/posts\/54623\/translations\/en"},{"embeddable":true,"hreflang":"it","title":"Italian","href":"https:\/\/kimgsta.com\/pt\/wp-json\/kinsta\/v1\/posts\/54623\/translations\/it"},{"embeddable":true,"hreflang":"pt","title":"Portuguese","href":"https:\/\/kimgsta.com\/pt\/wp-json\/kinsta\/v1\/posts\/54623\/translations\/pt"},{"embeddable":true,"hreflang":"fr","title":"French","href":"https:\/\/kimgsta.com\/pt\/wp-json\/kinsta\/v1\/posts\/54623\/translations\/fr"},{"embeddable":true,"hreflang":"de","title":"German","href":"https:\/\/kimgsta.com\/pt\/wp-json\/kinsta\/v1\/posts\/54623\/translations\/de"},{"embeddable":true,"hreflang":"ja","title":"Japanese","href":"https:\/\/kimgsta.com\/pt\/wp-json\/kinsta\/v1\/posts\/54623\/translations\/jp"},{"embeddable":true,"hreflang":"nl","title":"Dutch","href":"https:\/\/kimgsta.com\/pt\/wp-json\/kinsta\/v1\/posts\/54623\/translations\/nl"},{"embeddable":true,"hreflang":"es","title":"Spanish","href":"https:\/\/kimgsta.com\/pt\/wp-json\/kinsta\/v1\/posts\/54623\/translations\/es"},{"embeddable":true,"hreflang":"sv","title":null,"href":"https:\/\/kimgsta.com\/pt\/wp-json\/kinsta\/v1\/posts\/54623\/translations\/se"},{"embeddable":true,"hreflang":"da","title":null,"href":"https:\/\/kimgsta.com\/pt\/wp-json\/kinsta\/v1\/posts\/54623\/translations\/dk"},{"href":"https:\/\/kimgsta.com\/pt\/wp-json\/kinsta\/v1\/posts\/54623\/tree"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/kimgsta.com\/pt\/wp-json\/wp\/v2\/media\/54624"}],"wp:attachment":[{"href":"https:\/\/kimgsta.com\/pt\/wp-json\/wp\/v2\/media?parent=54623"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/kimgsta.com\/pt\/wp-json\/wp\/v2\/tags?post=54623"},{"taxonomy":"topic","embeddable":true,"href":"https:\/\/kimgsta.com\/pt\/wp-json\/wp\/v2\/topic?post=54623"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}