{"id":25976,"date":"2019-06-04T06:02:49","date_gmt":"2019-06-04T13:02:49","guid":{"rendered":"https:\/\/kimgsta.com\/?post_type=knowledgebase&#038;p=18763"},"modified":"2026-05-28T05:56:16","modified_gmt":"2026-05-28T08:56:16","slug":"pci-compativel-hospedagem","status":"publish","type":"post","link":"https:\/\/kimgsta.com\/pt\/blog\/pci-compativel-hospedagem\/","title":{"rendered":"A Kinsta oferece hospedagem compat\u00edvel com PCI?"},"content":{"rendered":"<p>Recebemos frequentemente perguntas sobre se a Kinsta oferece hospedagem compat\u00edvel com PCI e, por isso, hoje vamos abordar esse tema. Muitas pessoas n\u00e3o percebem que toda loja de <strong>eCommerce que <a href=\"https:\/\/www.pcicomplianceguide.org\/faq\/#2\">processa, armazena ou transmite dados de cart\u00e3o de cr\u00e9dito<\/a> \u00e9 obrigada a estar em conformidade com o PCI<\/strong>, independentemente do volume anual de vendas. Portanto, \u00e9 importante dedicar um tempo para entender melhor a conformidade com PCI e como ela impacta o seu neg\u00f3cio.<\/p>\n<aside role=\"note\" class=\"wp-block-kinsta-notice is-style-info\">\n            <h3>Info<\/h3>\n        <p><strong>Aviso Legal sobre o Conte\u00fado<\/strong>: As informa\u00e7\u00f5es fornecidas neste artigo s\u00e3o apenas para fins informativos gerais e n\u00e3o devem ser interpretadas como aconselhamento jur\u00eddico. Recomendamos consultar um profissional jur\u00eddico qualificado para obter orienta\u00e7\u00f5es espec\u00edficas para o seu neg\u00f3cio ou site.<\/p>\n<\/aside>\n\n<h2>O que \u00e9 PCI?<\/h2>\n<p>O termo PCI significa &#8220;Payment Card Industry&#8221; (Ind\u00fastria de cart\u00f5es de pagamento) Voc\u00ea o ouvir\u00e1 com frequ\u00eancia no contexto do <a href=\"https:\/\/www.pcisecuritystandards.org\/\" target=\"_blank\" rel=\"noopener noreferrer\">PCI DSS<\/a> &#8211; o Padr\u00e3o de Seguran\u00e7a de Dados do Setor de Cart\u00f5es de Pagamento. Trata-se de um <strong>conjunto de padr\u00f5es de seguran\u00e7a para qualquer empresa que aceite, armazene ou transmita dados de cart\u00e3o de cr\u00e9dito<\/strong>, criado para proteger os consumidores e garantir que os dados de pagamento sejam tratados com seguran\u00e7a.<\/p>\n<p>Empresas como American Express, Discover, JCB International, MasterCard e Visa possuem seus pr\u00f3prios programas de conformidade, mas todas seguem as regras definidas pelo PCI Security Standards Council, do qual s\u00e3o membros fundadores.<\/p>\n<p>Em mar\u00e7o de 2022, foi lan\u00e7ada a <a href=\"https:\/\/east.pcisecuritystandards.org\/document_library?category=pcidss&#038;document=pci_dss\">vers\u00e3o 4.0 do PCI DSS<\/a>, substituindo o padr\u00e3o 3.2.1 mais antigo. A nova vers\u00e3o foca no fortalecimento da seguran\u00e7a e oferece mais flexibilidade sobre como as empresas podem atingir os objetivos de conformidade. As principais mudan\u00e7as incluem:<\/p>\n<ul>\n<li>Uma nova \u201cabordagem personalizada\u201d para conformidade, juntamente com o modelo tradicional baseado em checklist<\/li>\n<li>Autentica\u00e7\u00e3o multifator (MFA) obrigat\u00f3ria para todo acesso aos ambientes que armazenam dados de titulares de cart\u00f5es<\/li>\n<li>Maior foco na seguran\u00e7a como um processo cont\u00ednuo, e n\u00e3o como uma corre\u00e7\u00e3o pontual<\/li>\n<li>Requisitos aprimorados para proteger plataformas de eCommerce e aplicativos web, especialmente relevantes para sites WordPress e WooCommerce<\/li>\n<\/ul>\n<p>Caso voc\u00ea esteja gerenciando pagamentos ou dados de clientes no seu site WordPress, \u00e9 importante entender como essas mudan\u00e7as afetam suas responsabilidades no PCI DSS.<\/p>\n<h2>A Kinsta oferece hospedagem compat\u00edvel com PCI?<\/h2>\n<p>\u00c9 importante entender que apenas porque um provedor de hospedagem pode estar em conformidade com PCI, isso n\u00e3o significa automaticamente que o seu site tamb\u00e9m esteja. Isso acontece porque a conformidade com PCI DSS segue um modelo de responsabilidade compartilhada.<\/p>\n<p>Como provedora de hospedagem gerenciada para WordPress, a Kinsta \u00e9 respons\u00e1vel por proteger a infraestrutura do servidor, manter as atualiza\u00e7\u00f5es do sistema operacional em dia, aplicar prote\u00e7\u00f5es r\u00edgidas no n\u00edvel de rede e oferecer suporte a conex\u00f5es TLS (HTTPS) seguras. No entanto, tudo acima da camada de infraestrutura, como proteger sua instala\u00e7\u00e3o WordPress, gerenciar plugins e temas, lidar com informa\u00e7\u00f5es de pagamento e configurar corretamente o seu site, fica sob seu controle.<\/p>\n<p>Na pr\u00e1tica, isso significa que a maior parte da responsabilidade ainda recai sobre voc\u00ea, como propriet\u00e1rio do site. Por exemplo, se voc\u00ea estiver administrando uma <a href=\"https:\/\/kimgsta.com\/pt\/blog\/tutorial-woocommerce\/\">loja WooCommerce<\/a>, ser\u00e1 respons\u00e1vel por lidar com dados de clientes, processar cart\u00f5es de cr\u00e9dito, proteger contas de usu\u00e1rios e manter a base de c\u00f3digo do seu site.<\/p>\n<p>A Kinsta n\u00e3o garante conformidade com PCI e n\u00e3o podemos auditar seu site para verificar se sua implementa\u00e7\u00e3o atende aos requisitos. No entanto, isso n\u00e3o significa que voc\u00ea n\u00e3o possa estar em conformidade com PCI enquanto hospeda conosco.<\/p>\n<p>Muitos dos nossos clientes trabalharam com auditores terceirizados e conseguiram passar nas verifica\u00e7\u00f5es de conformidade PCI com sucesso. Em alguns casos, realizamos pequenos ajustes de infraestrutura mediante solicita\u00e7\u00e3o, mas as auditorias foram aprovadas por meio de uma combina\u00e7\u00e3o de configura\u00e7\u00f5es feitas pelo cliente e orienta\u00e7\u00e3o de terceiros.<\/p>\n<p>Embora n\u00e3o participemos diretamente do processo de auditoria, teremos prazer em ajudar com altera\u00e7\u00f5es espec\u00edficas quando necess\u00e1rio.<\/p>\n<h2>Como estar em conformidade<\/h2>\n<p>Aqui est\u00e3o algumas pr\u00e1ticas recomendadas para garantir que voc\u00ea esteja em conformidade na Kinsta:<\/p>\n<h3>1. Question\u00e1rio de autoavalia\u00e7\u00e3o PCI<\/h3>\n<p>Preencha um <a href=\"https:\/\/www.pcisecuritystandards.org\/document_library?category=saqs#results\" target=\"_blank\" rel=\"noopener noreferrer\">Question\u00e1rio de Autoavalia\u00e7\u00e3o<\/a> (SAQ) anualmente para ajudar voc\u00ea a determinar se sua configura\u00e7\u00e3o de processamento de pagamentos est\u00e1 em conformidade com PCI.<\/p>\n<h3>2. TLS e HTTPS<\/h3>\n<p>Disponibilize suas p\u00e1ginas de pagamento com seguran\u00e7a usando <a href=\"https:\/\/kimgsta.com\/pt\/blog\/tls-1-3\/\">TLS 1.3<\/a> (preferencial) ou TLS 1.2 para habilitar HTTPS (conex\u00f5es criptografadas). O <a href=\"https:\/\/east.pcisecuritystandards.org\/document_library?category=pcidss&#038;document=pci_dss\">PCI DSS 4.0<\/a> exige uma configura\u00e7\u00e3o TLS segura, incluindo conjuntos de cifras fortes e avalia\u00e7\u00f5es regulares de seguran\u00e7a. A Kinsta sempre mant\u00e9m as vers\u00f5es TLS atualizadas em nossos servidores, e voc\u00ea pode instalar facilmente um <a href=\"https:\/\/kimgsta.com\/pt\/docs\/hospedagem-de-wordpress\/dominios-wordpress\/certificados-ssl-wordpress\/\">certificado SSL<\/a> pelo painel MyKinsta.<\/p>\n<p>Veja como voc\u00ea pode <a href=\"https:\/\/kimgsta.com\/pt\/blog\/woocommerce-ssl\/\">instalar o certificado SSL no WooCommerce<\/a>.<\/p>\n<p>O PCI DSS 4.0 aceita certificados de valida\u00e7\u00e3o de dom\u00ednio (DV), desde que utilizem algoritmos de criptografia fortes, como SHA-256, e sejam mantidos corretamente. Na Kinsta, os certificados SSL, incluindo suporte a wildcard, s\u00e3o emitidos automaticamente por meio da nossa integra\u00e7\u00e3o gratuita com o Cloudflare, garantindo conex\u00f5es HTTPS seguras e compat\u00edveis por padr\u00e3o. Para maior garantia ou exig\u00eancias organizacionais, voc\u00ea tamb\u00e9m pode optar por instalar um certificado EV (Extended Validation) ou OV (Organization Validated) personalizado.<\/p>\n<p>N\u00e3o deixe de ler nosso guia sobre <a href=\"https:\/\/kimgsta.com\/pt\/blog\/tls-vs-ssl\/\">TLS vs SSL<\/a>.<\/p>\n<h3>3. Processe pagamentos por meio de um provedor terceirizado<\/h3>\n<p>Uma das maneiras mais f\u00e1ceis de simplificar a conformidade com PCI \u00e9 processar suas transa\u00e7\u00f5es de cart\u00e3o de cr\u00e9dito por meio de um provedor terceirizado. Voc\u00ea pode integrar facilmente sua loja WooCommerce ou Easy Digital Downloads com um <a href=\"https:\/\/kimgsta.com\/pt\/blog\/gateways-de-pagamento-woocommerce\/\">gateway de pagamento<\/a>, como Stripe ou PayPal. Ainda assim, voc\u00ea deve revisar as diretrizes de conformidade PCI desses provedores, pois apenas processar cart\u00f5es de cr\u00e9dito fora do site nem sempre garante conformidade. Podem haver etapas adicionais necess\u00e1rias.<\/p>\n<ul>\n<li><a href=\"https:\/\/example.com\/docs\/security\" target=\"_blank\" rel=\"noopener noreferrer\">Conformidade PCI com Stripe<\/a><\/li>\n<li><a href=\"https:\/\/www.paypal.com\/us\/webapps\/mpp\/pci-compliant-solution\" target=\"_blank\" rel=\"noopener noreferrer\">Conformidade PCI com PayPal<\/a><\/li>\n<li><a href=\"https:\/\/articles.braintreepayments.com\/risk-and-security\/compliance\/pci-compliance\" target=\"_blank\" rel=\"noopener noreferrer\">Conformidade PCI com Braintree<\/a><\/li>\n<\/ul>\n<h3>4. Implemente um firewall<\/h3>\n<p>O PCI DSS exige que sistemas que lidam com dados de titulares de cart\u00f5es sejam protegidos por firewalls configurados corretamente para controlar o tr\u00e1fego e bloquear acessos n\u00e3o autorizados.<\/p>\n<p>Na Kinsta, todos os sites se beneficiam de m\u00faltiplas camadas de prote\u00e7\u00e3o por firewall. Todo o tr\u00e1fego web \u00e9 roteado por meio da nossa integra\u00e7\u00e3o com o Cloudflare, que inclui um Web Application Firewall (WAF) totalmente gerenciado, com conjuntos de regras personalizados, filtragem inteligente de tr\u00e1fego e mitiga\u00e7\u00e3o integrada de DDoS na borda da rede.<\/p>\n<p>Essa abordagem oferece forte prote\u00e7\u00e3o padr\u00e3o contra amea\u00e7as comuns, como tentativas de acesso n\u00e3o autorizado, bots maliciosos e ataques na camada de aplicativos.<\/p>\n<p>Caso seu auditor PCI ou equipe de seguran\u00e7a exija personaliza\u00e7\u00f5es adicionais, voc\u00ea tamb\u00e9m pode integrar um Web Application Firewall (WAF) terceirizado, como Sucuri ou planos independentes do Cloudflare com regras personalizadas.<\/p>\n<ul>\n<li><a href=\"https:\/\/sucuri.net\/guides\/pci-compliance\/\" target=\"_blank\" rel=\"noopener noreferrer\">Conformidade PCI com Sucuri<\/a><\/li>\n<li><a href=\"https:\/\/www.cloudflare.com\/learning\/security\/pci-compliance\/\" target=\"_blank\" rel=\"noopener noreferrer\">Conformidade PCI com Cloudflare<\/a><\/li>\n<\/ul>\n<h3>5. Realize testes de seguran\u00e7a regularmente<\/h3>\n<p>O PCI DSS 4.0 inclui requisitos espec\u00edficos relacionados a testes cont\u00ednuos de seguran\u00e7a. Isso inclui varredura de vulnerabilidades, testes de invas\u00e3o e monitoramento de integridade de arquivos para detectar e corrigir poss\u00edveis amea\u00e7as de seguran\u00e7a antes que se tornem problemas.<\/p>\n<p>Na Kinsta, protegemos seu ambiente com recursos como mitiga\u00e7\u00e3o de DDoS, verifica\u00e7\u00e3o de malware, firewalls de hardware e outras prote\u00e7\u00f5es no n\u00edvel da infraestrutura. No entanto, voc\u00ea \u00e9 respons\u00e1vel por testar a camada de aplicativo, incluindo seu site WordPress, plugins, temas e qualquer c\u00f3digo personalizado.<\/p>\n<aside role=\"note\" class=\"wp-block-kinsta-notice is-style-important\">\n            <h3>Important<\/h3>\n        <p><strong>Importante: <\/strong>caso voc\u00ea utilize formul\u00e1rios de pagamento incorporados, como um iframe, ou redirecione usu\u00e1rios para um provedor de pagamento terceirizado, o PCI DSS 4.0 exige que voc\u00ea execute <strong>varreduras externas trimestrais de vulnerabilidades<\/strong> usando um Approved Scanning Vendor (ASV) aprovado pelo PCI. Isso se tornou obrigat\u00f3rio em <strong>31 de mar\u00e7o de 2025<\/strong>. Voc\u00ea precisar\u00e1:<\/p>\n<ul>\n<li>Selecionar um ASV da <a href=\"https:\/\/www.pcisecuritystandards.org\/assessors_and_solutions\/approved_scanning_vendors\" target=\"_blank\" rel=\"noopener noreferrer\">lista oficial do PCI SSC<\/a><\/li>\n<li>Corrigir todas as vulnerabilidades identificadas<\/li>\n<li>Manter a documenta\u00e7\u00e3o dos resultados da varredura para fins de conformidade<\/li>\n<\/ul>\n<p><\/p>\n<\/aside>\n\n<p>Al\u00e9m das varreduras ASV, tamb\u00e9m recomendamos testes internos regulares para reduzir riscos e se antecipar \u00e0s verifica\u00e7\u00f5es de conformidade:<\/p>\n<ul>\n<li>Use um scanner de vulnerabilidades para detectar plugins e temas desatualizados ou inseguros<\/li>\n<li>Agende testes de invas\u00e3o peri\u00f3dicos, especialmente caso voc\u00ea lide diretamente com dados de pagamento<\/li>\n<li>Habilite o monitoramento de altera\u00e7\u00f5es de arquivos usando um plugin de seguran\u00e7a WordPress<\/li>\n<\/ul>\n<p>Alguns processadores de pagamento ou empresas terceirizadas de seguran\u00e7a tamb\u00e9m podem fornecer ferramentas para ajudar voc\u00ea a atender esses requisitos de teste como parte do seu processo de conformidade PCI.<\/p>\n<h3>6. Autentica\u00e7\u00e3o multifator<\/h3>\n<p>A autentica\u00e7\u00e3o multifator (MFA) \u00e9 um m\u00e9todo de seguran\u00e7a que exige que os usu\u00e1rios forne\u00e7am dois ou mais tipos de credenciais antes de obter acesso, normalmente uma combina\u00e7\u00e3o de algo que voc\u00ea sabe, como uma senha, e algo que voc\u00ea possui, como um c\u00f3digo de um aplicativo autenticador no seu telefone.<\/p>\n<p>Isso \u00e9 frequentemente chamado de autentica\u00e7\u00e3o de dois fatores (2FA), que \u00e9 uma forma espec\u00edfica de MFA que utiliza exatamente dois fatores. Embora os termos sejam frequentemente usados de forma intercambi\u00e1vel, o PCI DSS 4.0 agora utiliza o termo mais amplo MFA e amplia as situa\u00e7\u00f5es em que ele \u00e9 obrigat\u00f3rio.<\/p>\n<p>No PCI DSS 4.0, MFA \u00e9 obrigat\u00f3rio para:<\/p>\n<ul>\n<li>Todo acesso ao ambiente de dados do titular do cart\u00e3o (CDE)<\/li>\n<li>Todo acesso remoto a sistemas que lidam com dados de pagamento<\/li>\n<li>Qualquer acesso administrativo a sistemas de processamento de pagamentos<\/li>\n<\/ul>\n<p>Na Kinsta, <a href=\"https:\/\/kimgsta.com\/pt\/changelog\/autenticacao-em-duas-etapas\/\">autentica\u00e7\u00e3o de dois fatores<\/a> (2FA) \u00e9 necess\u00e1ria para todos os logins do MyKinsta, adicionando uma camada extra de prote\u00e7\u00e3o ao seu painel de hospedagem. Voc\u00ea tamb\u00e9m pode habilitar a autentica\u00e7\u00e3o de dois fatores para sua \u00e1rea de administra\u00e7\u00e3o do WordPress para proteger ainda mais seu site.<\/p>\n<ul>\n<li><a href=\"https:\/\/kimgsta.com\/pt\/docs\/configuracoes-do-usuario\/fazendo-login\/#enable-two-factor-authentication-2-fa\" target=\"_blank\" rel=\"noopener noreferrer\">Habilitar a autentica\u00e7\u00e3o multifator no MyKinsta<\/a><\/li>\n<li><a href=\"https:\/\/kimgsta.com\/pt\/blog\/autenticacao-de-dois-fatores-wordpress\/#enable-wordpress-twofactor-authentication\" target=\"_blank\" rel=\"noopener noreferrer\">Habilitar a autentica\u00e7\u00e3o multifator em seu site WordPress<\/a><\/li>\n<\/ul>\n<h3>7. Seguran\u00e7a do centro de dados<\/h3>\n<p>A infraestrutura de nuvem da Kinsta foi projetada para atender requisitos rigorosos de seguran\u00e7a e conformidade para hospedar cargas de trabalho sens\u00edveis, incluindo ambientes que oferecem suporte aos esfor\u00e7os de conformidade com PCI DSS.<\/p>\n<p>Nossos centros de dados implementam controles f\u00edsicos de seguran\u00e7a em m\u00faltiplas camadas, como acesso controlado \u00e0s instala\u00e7\u00f5es, monitoramento cont\u00ednuo, sistemas de detec\u00e7\u00e3o de intrus\u00e3o e equipes de seguran\u00e7a no local. Todo acesso e atividade s\u00e3o registrados e auditados para oferecer suporte \u00e0 investiga\u00e7\u00e3o de incidentes e aos requisitos de conformidade.<\/p>\n<p>Os dados s\u00e3o criptografados em tr\u00e2nsito e em repouso usando padr\u00f5es fortes de criptografia, incluindo AES de 256 bits para dados armazenados. As chaves de criptografia s\u00e3o gerenciadas e rotacionadas regularmente como parte dos nossos controles gerais de seguran\u00e7a.<\/p>\n<p>A <strong>Kinsta est\u00e1 em conformidade com SOC 2<\/strong>. Voc\u00ea pode saber mais na nossa <a href=\"https:\/\/kimgsta.com\/pt\/docs\/informacoes-de-servico\/soc-2\/\">p\u00e1gina de conformidade SOC 2<\/a> ou visitar nossa p\u00e1gina de <a href=\"https:\/\/trust.kimgsta.com\/\">Relat\u00f3rio de Confian\u00e7a<\/a>.<\/p>\n<aside role=\"note\" class=\"wp-block-kinsta-notice is-style-important\">\n            <h3>Important<\/h3>\n        <p>As informa\u00e7\u00f5es acima est\u00e3o sendo fornecidas para ajudar voc\u00ea com d\u00favidas relacionadas \u00e0 conformidade PCI. No entanto, n\u00e3o somos respons\u00e1veis por avaliar sua conformidade. Isso deve sempre ser realizado por um auditor terceirizado.<\/p>\n<\/aside>\n\n","protected":false},"excerpt":{"rendered":"<p>Recebemos frequentemente perguntas sobre se a Kinsta oferece hospedagem compat\u00edvel com PCI e, por isso, hoje vamos abordar esse tema. Muitas pessoas n\u00e3o percebem que toda &#8230;<\/p>\n","protected":false},"author":38,"featured_media":25979,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_kinsta_gated_content":false,"_kinsta_gated_content_redirect":"","footnotes":""},"tags":[124,38],"topic":[983],"class_list":["post-25976","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","tag-pci","tag-websec","topic-servicos-kinsta"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.6 (Yoast SEO v24.6) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>A Kinsta oferece hospedagem compat\u00edvel com PCI? - Kinsta\u00ae<\/title>\n<meta name=\"description\" content=\"Clique aqui para saber mais sobre a Kinsta e quais s\u00e3o suas op\u00e7\u00f5es em rela\u00e7\u00e3o \u00e0 hospedagem compat\u00edvel com PCI para o seu site WordPress ou loja de com\u00e9rcio eletr\u00f4nico.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/kimgsta.com\/pt\/blog\/pci-compativel-hospedagem\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"A Kinsta oferece hospedagem compat\u00edvel com PCI?\" \/>\n<meta property=\"og:description\" content=\"Clique aqui para saber mais sobre a Kinsta e quais s\u00e3o suas op\u00e7\u00f5es em rela\u00e7\u00e3o \u00e0 hospedagem compat\u00edvel com PCI para o seu site WordPress ou loja de com\u00e9rcio eletr\u00f4nico.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kimgsta.com\/pt\/blog\/pci-compativel-hospedagem\/\" \/>\n<meta property=\"og:site_name\" content=\"Kinsta\u00ae\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/kinstapt\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/fm.brianleejackson\" \/>\n<meta property=\"article:published_time\" content=\"2019-06-04T13:02:49+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-28T08:56:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/kimgsta.com\/pt\/wp-content\/uploads\/sites\/3\/2024\/11\/PT-Homepage-featured-image.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"628\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Brian Jackson\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:description\" content=\"Clique aqui para saber mais sobre a Kinsta e quais s\u00e3o suas op\u00e7\u00f5es em rela\u00e7\u00e3o \u00e0 hospedagem compat\u00edvel com PCI para o seu site WordPress ou loja de com\u00e9rcio eletr\u00f4nico.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/kimgsta.com\/wp-content\/uploads\/2018\/02\/pci-compliant-hosting-1.png\" \/>\n<meta name=\"twitter:creator\" content=\"@brianleejackson\" \/>\n<meta name=\"twitter:site\" content=\"@kinsta_pt\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Brian Jackson\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/kimgsta.com\/pt\/blog\/pci-compativel-hospedagem\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/kimgsta.com\/pt\/blog\/pci-compativel-hospedagem\/\"},\"author\":{\"name\":\"Brian Jackson\",\"@id\":\"https:\/\/kimgsta.com\/pt\/#\/schema\/person\/079824c00ccc2b7141504f27ea63bef7\"},\"headline\":\"A Kinsta oferece hospedagem compat\u00edvel com PCI?\",\"datePublished\":\"2019-06-04T13:02:49+00:00\",\"dateModified\":\"2026-05-28T08:56:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/kimgsta.com\/pt\/blog\/pci-compativel-hospedagem\/\"},\"wordCount\":1912,\"publisher\":{\"@id\":\"https:\/\/kimgsta.com\/pt\/#organization\"},\"image\":{\"@id\":\"https:\/\/kimgsta.com\/pt\/blog\/pci-compativel-hospedagem\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/kimgsta.com\/pt\/wp-content\/uploads\/sites\/3\/2019\/06\/kinsta-oferece-hospedagem-compativel-pci.png\",\"keywords\":[\"PCI\",\"websec\"],\"inLanguage\":\"pt-PT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/kimgsta.com\/pt\/blog\/pci-compativel-hospedagem\/\",\"url\":\"https:\/\/kimgsta.com\/pt\/blog\/pci-compativel-hospedagem\/\",\"name\":\"A Kinsta oferece hospedagem compat\u00edvel com PCI? - Kinsta\u00ae\",\"isPartOf\":{\"@id\":\"https:\/\/kimgsta.com\/pt\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/kimgsta.com\/pt\/blog\/pci-compativel-hospedagem\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/kimgsta.com\/pt\/blog\/pci-compativel-hospedagem\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/kimgsta.com\/pt\/wp-content\/uploads\/sites\/3\/2019\/06\/kinsta-oferece-hospedagem-compativel-pci.png\",\"datePublished\":\"2019-06-04T13:02:49+00:00\",\"dateModified\":\"2026-05-28T08:56:16+00:00\",\"description\":\"Clique aqui para saber mais sobre a Kinsta e quais s\u00e3o suas op\u00e7\u00f5es em rela\u00e7\u00e3o \u00e0 hospedagem compat\u00edvel com PCI para o seu site WordPress ou loja de com\u00e9rcio eletr\u00f4nico.\",\"breadcrumb\":{\"@id\":\"https:\/\/kimgsta.com\/pt\/blog\/pci-compativel-hospedagem\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/kimgsta.com\/pt\/blog\/pci-compativel-hospedagem\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\/\/kimgsta.com\/pt\/blog\/pci-compativel-hospedagem\/#primaryimage\",\"url\":\"https:\/\/kimgsta.com\/pt\/wp-content\/uploads\/sites\/3\/2019\/06\/kinsta-oferece-hospedagem-compativel-pci.png\",\"contentUrl\":\"https:\/\/kimgsta.com\/pt\/wp-content\/uploads\/sites\/3\/2019\/06\/kinsta-oferece-hospedagem-compativel-pci.png\",\"width\":1460,\"height\":730,\"caption\":\"O Kinsta Oferece Hospedagem Compat\u00edvel com PCI?\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/kimgsta.com\/pt\/blog\/pci-compativel-hospedagem\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/kimgsta.com\/pt\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Servi\u00e7os Kinsta\",\"item\":\"https:\/\/kimgsta.com\/pt\/topicos\/servicos-kinsta\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"A Kinsta oferece hospedagem compat\u00edvel com PCI?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/kimgsta.com\/pt\/#website\",\"url\":\"https:\/\/kimgsta.com\/pt\/\",\"name\":\"Kinsta\u00ae\",\"description\":\"Solu\u00e7\u00f5es de hospedagem Premium, r\u00e1pida e segura\",\"publisher\":{\"@id\":\"https:\/\/kimgsta.com\/pt\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/kimgsta.com\/pt\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/kimgsta.com\/pt\/#organization\",\"name\":\"Kinsta\",\"url\":\"https:\/\/kimgsta.com\/pt\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\/\/kimgsta.com\/pt\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/kimgsta.com\/pt\/wp-content\/uploads\/sites\/3\/2023\/12\/kinsta-logo.jpeg\",\"contentUrl\":\"https:\/\/kimgsta.com\/pt\/wp-content\/uploads\/sites\/3\/2023\/12\/kinsta-logo.jpeg\",\"width\":500,\"height\":500,\"caption\":\"Kinsta\"},\"image\":{\"@id\":\"https:\/\/kimgsta.com\/pt\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/kinstapt\/\",\"https:\/\/x.com\/kinsta_pt\",\"https:\/\/www.instagram.com\/kinstahosting\/\",\"https:\/\/www.linkedin.com\/company\/kinsta\/\",\"https:\/\/www.pinterest.com\/kinstahosting\/\",\"https:\/\/www.youtube.com\/c\/Kinsta\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/kimgsta.com\/pt\/#\/schema\/person\/079824c00ccc2b7141504f27ea63bef7\",\"name\":\"Brian Jackson\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\/\/kimgsta.com\/pt\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/79623d815f4ed4c8c2457392d728cb16?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/79623d815f4ed4c8c2457392d728cb16?s=96&d=mm&r=g\",\"caption\":\"Brian Jackson\"},\"description\":\"Brian has a huge passion for WordPress, has been using it for over a decade, and even develops a couple of premium plugins. Brian enjoys blogging, movies, and hiking. Connect with Brian on Twitter.\",\"sameAs\":[\"https:\/\/www.facebook.com\/fm.brianleejackson\",\"https:\/\/www.linkedin.com\/in\/brianleejackson\",\"https:\/\/x.com\/brianleejackson\"],\"url\":\"https:\/\/kimgsta.com\/pt\/blog\/author\/brianjackson\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"A Kinsta oferece hospedagem compat\u00edvel com PCI? - Kinsta\u00ae","description":"Clique aqui para saber mais sobre a Kinsta e quais s\u00e3o suas op\u00e7\u00f5es em rela\u00e7\u00e3o \u00e0 hospedagem compat\u00edvel com PCI para o seu site WordPress ou loja de com\u00e9rcio eletr\u00f4nico.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/kimgsta.com\/pt\/blog\/pci-compativel-hospedagem\/","og_locale":"pt_PT","og_type":"article","og_title":"A Kinsta oferece hospedagem compat\u00edvel com PCI?","og_description":"Clique aqui para saber mais sobre a Kinsta e quais s\u00e3o suas op\u00e7\u00f5es em rela\u00e7\u00e3o \u00e0 hospedagem compat\u00edvel com PCI para o seu site WordPress ou loja de com\u00e9rcio eletr\u00f4nico.","og_url":"https:\/\/kimgsta.com\/pt\/blog\/pci-compativel-hospedagem\/","og_site_name":"Kinsta\u00ae","article_publisher":"https:\/\/www.facebook.com\/kinstapt\/","article_author":"https:\/\/www.facebook.com\/fm.brianleejackson","article_published_time":"2019-06-04T13:02:49+00:00","article_modified_time":"2026-05-28T08:56:16+00:00","og_image":[{"width":1200,"height":628,"url":"https:\/\/kimgsta.com\/pt\/wp-content\/uploads\/sites\/3\/2024\/11\/PT-Homepage-featured-image.png","type":"image\/png"}],"author":"Brian Jackson","twitter_card":"summary_large_image","twitter_description":"Clique aqui para saber mais sobre a Kinsta e quais s\u00e3o suas op\u00e7\u00f5es em rela\u00e7\u00e3o \u00e0 hospedagem compat\u00edvel com PCI para o seu site WordPress ou loja de com\u00e9rcio eletr\u00f4nico.","twitter_image":"https:\/\/kimgsta.com\/wp-content\/uploads\/2018\/02\/pci-compliant-hosting-1.png","twitter_creator":"@brianleejackson","twitter_site":"@kinsta_pt","twitter_misc":{"Escrito por":"Brian Jackson","Tempo estimado de leitura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/kimgsta.com\/pt\/blog\/pci-compativel-hospedagem\/#article","isPartOf":{"@id":"https:\/\/kimgsta.com\/pt\/blog\/pci-compativel-hospedagem\/"},"author":{"name":"Brian Jackson","@id":"https:\/\/kimgsta.com\/pt\/#\/schema\/person\/079824c00ccc2b7141504f27ea63bef7"},"headline":"A Kinsta oferece hospedagem compat\u00edvel com PCI?","datePublished":"2019-06-04T13:02:49+00:00","dateModified":"2026-05-28T08:56:16+00:00","mainEntityOfPage":{"@id":"https:\/\/kimgsta.com\/pt\/blog\/pci-compativel-hospedagem\/"},"wordCount":1912,"publisher":{"@id":"https:\/\/kimgsta.com\/pt\/#organization"},"image":{"@id":"https:\/\/kimgsta.com\/pt\/blog\/pci-compativel-hospedagem\/#primaryimage"},"thumbnailUrl":"https:\/\/kimgsta.com\/pt\/wp-content\/uploads\/sites\/3\/2019\/06\/kinsta-oferece-hospedagem-compativel-pci.png","keywords":["PCI","websec"],"inLanguage":"pt-PT"},{"@type":"WebPage","@id":"https:\/\/kimgsta.com\/pt\/blog\/pci-compativel-hospedagem\/","url":"https:\/\/kimgsta.com\/pt\/blog\/pci-compativel-hospedagem\/","name":"A Kinsta oferece hospedagem compat\u00edvel com PCI? - Kinsta\u00ae","isPartOf":{"@id":"https:\/\/kimgsta.com\/pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/kimgsta.com\/pt\/blog\/pci-compativel-hospedagem\/#primaryimage"},"image":{"@id":"https:\/\/kimgsta.com\/pt\/blog\/pci-compativel-hospedagem\/#primaryimage"},"thumbnailUrl":"https:\/\/kimgsta.com\/pt\/wp-content\/uploads\/sites\/3\/2019\/06\/kinsta-oferece-hospedagem-compativel-pci.png","datePublished":"2019-06-04T13:02:49+00:00","dateModified":"2026-05-28T08:56:16+00:00","description":"Clique aqui para saber mais sobre a Kinsta e quais s\u00e3o suas op\u00e7\u00f5es em rela\u00e7\u00e3o \u00e0 hospedagem compat\u00edvel com PCI para o seu site WordPress ou loja de com\u00e9rcio eletr\u00f4nico.","breadcrumb":{"@id":"https:\/\/kimgsta.com\/pt\/blog\/pci-compativel-hospedagem\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/kimgsta.com\/pt\/blog\/pci-compativel-hospedagem\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/kimgsta.com\/pt\/blog\/pci-compativel-hospedagem\/#primaryimage","url":"https:\/\/kimgsta.com\/pt\/wp-content\/uploads\/sites\/3\/2019\/06\/kinsta-oferece-hospedagem-compativel-pci.png","contentUrl":"https:\/\/kimgsta.com\/pt\/wp-content\/uploads\/sites\/3\/2019\/06\/kinsta-oferece-hospedagem-compativel-pci.png","width":1460,"height":730,"caption":"O Kinsta Oferece Hospedagem Compat\u00edvel com PCI?"},{"@type":"BreadcrumbList","@id":"https:\/\/kimgsta.com\/pt\/blog\/pci-compativel-hospedagem\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/kimgsta.com\/pt\/"},{"@type":"ListItem","position":2,"name":"Servi\u00e7os Kinsta","item":"https:\/\/kimgsta.com\/pt\/topicos\/servicos-kinsta\/"},{"@type":"ListItem","position":3,"name":"A Kinsta oferece hospedagem compat\u00edvel com PCI?"}]},{"@type":"WebSite","@id":"https:\/\/kimgsta.com\/pt\/#website","url":"https:\/\/kimgsta.com\/pt\/","name":"Kinsta\u00ae","description":"Solu\u00e7\u00f5es de hospedagem Premium, r\u00e1pida e segura","publisher":{"@id":"https:\/\/kimgsta.com\/pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/kimgsta.com\/pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/kimgsta.com\/pt\/#organization","name":"Kinsta","url":"https:\/\/kimgsta.com\/pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/kimgsta.com\/pt\/#\/schema\/logo\/image\/","url":"https:\/\/kimgsta.com\/pt\/wp-content\/uploads\/sites\/3\/2023\/12\/kinsta-logo.jpeg","contentUrl":"https:\/\/kimgsta.com\/pt\/wp-content\/uploads\/sites\/3\/2023\/12\/kinsta-logo.jpeg","width":500,"height":500,"caption":"Kinsta"},"image":{"@id":"https:\/\/kimgsta.com\/pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/kinstapt\/","https:\/\/x.com\/kinsta_pt","https:\/\/www.instagram.com\/kinstahosting\/","https:\/\/www.linkedin.com\/company\/kinsta\/","https:\/\/www.pinterest.com\/kinstahosting\/","https:\/\/www.youtube.com\/c\/Kinsta"]},{"@type":"Person","@id":"https:\/\/kimgsta.com\/pt\/#\/schema\/person\/079824c00ccc2b7141504f27ea63bef7","name":"Brian Jackson","image":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/kimgsta.com\/pt\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/79623d815f4ed4c8c2457392d728cb16?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/79623d815f4ed4c8c2457392d728cb16?s=96&d=mm&r=g","caption":"Brian Jackson"},"description":"Brian has a huge passion for WordPress, has been using it for over a decade, and even develops a couple of premium plugins. Brian enjoys blogging, movies, and hiking. Connect with Brian on Twitter.","sameAs":["https:\/\/www.facebook.com\/fm.brianleejackson","https:\/\/www.linkedin.com\/in\/brianleejackson","https:\/\/x.com\/brianleejackson"],"url":"https:\/\/kimgsta.com\/pt\/blog\/author\/brianjackson\/"}]}},"acf":[],"_links":{"self":[{"href":"https:\/\/kimgsta.com\/pt\/wp-json\/wp\/v2\/posts\/25976","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kimgsta.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/kimgsta.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/kimgsta.com\/pt\/wp-json\/wp\/v2\/users\/38"}],"replies":[{"embeddable":true,"href":"https:\/\/kimgsta.com\/pt\/wp-json\/wp\/v2\/comments?post=25976"}],"version-history":[{"count":16,"href":"https:\/\/kimgsta.com\/pt\/wp-json\/wp\/v2\/posts\/25976\/revisions"}],"predecessor-version":[{"id":75625,"href":"https:\/\/kimgsta.com\/pt\/wp-json\/wp\/v2\/posts\/25976\/revisions\/75625"}],"alternate":[{"embeddable":true,"hreflang":"en","title":"English","href":"https:\/\/kimgsta.com\/pt\/wp-json\/kinsta\/v1\/posts\/25976\/translations\/en"},{"embeddable":true,"hreflang":"es","title":"Spanish","href":"https:\/\/kimgsta.com\/pt\/wp-json\/kinsta\/v1\/posts\/25976\/translations\/es"},{"embeddable":true,"hreflang":"de","title":"German","href":"https:\/\/kimgsta.com\/pt\/wp-json\/kinsta\/v1\/posts\/25976\/translations\/de"},{"embeddable":true,"hreflang":"pt","title":"Portuguese","href":"https:\/\/kimgsta.com\/pt\/wp-json\/kinsta\/v1\/posts\/25976\/translations\/pt"},{"embeddable":true,"hreflang":"fr","title":"French","href":"https:\/\/kimgsta.com\/pt\/wp-json\/kinsta\/v1\/posts\/25976\/translations\/fr"},{"embeddable":true,"hreflang":"da","title":null,"href":"https:\/\/kimgsta.com\/pt\/wp-json\/kinsta\/v1\/posts\/25976\/translations\/dk"},{"embeddable":true,"hreflang":"it","title":"Italian","href":"https:\/\/kimgsta.com\/pt\/wp-json\/kinsta\/v1\/posts\/25976\/translations\/it"},{"embeddable":true,"hreflang":"sv","title":null,"href":"https:\/\/kimgsta.com\/pt\/wp-json\/kinsta\/v1\/posts\/25976\/translations\/se"},{"embeddable":true,"hreflang":"ja","title":"Japanese","href":"https:\/\/kimgsta.com\/pt\/wp-json\/kinsta\/v1\/posts\/25976\/translations\/jp"},{"href":"https:\/\/kimgsta.com\/pt\/wp-json\/kinsta\/v1\/posts\/25976\/tree"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/kimgsta.com\/pt\/wp-json\/wp\/v2\/media\/25979"}],"wp:attachment":[{"href":"https:\/\/kimgsta.com\/pt\/wp-json\/wp\/v2\/media?parent=25976"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/kimgsta.com\/pt\/wp-json\/wp\/v2\/tags?post=25976"},{"taxonomy":"topic","embeddable":true,"href":"https:\/\/kimgsta.com\/pt\/wp-json\/wp\/v2\/topic?post=25976"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}