{"id":67805,"date":"2023-04-05T08:50:24","date_gmt":"2023-04-05T07:50:24","guid":{"rendered":"https:\/\/kimgsta.com\/it\/?p=67805&#038;preview=true&#038;preview_id=67805"},"modified":"2023-04-14T14:39:59","modified_gmt":"2023-04-14T13:39:59","slug":"wordpress-functions-php","status":"publish","type":"post","link":"https:\/\/kimgsta.com\/it\/blog\/wordpress-functions-php\/","title":{"rendered":"Il File functions.php di WordPress: Guida Definitiva e Utili Snippet di Codice"},"content":{"rendered":"<p>Sapete cos&#8217;\u00e8 il file functions.php di WordPress o come usarlo?<\/p>\n<p>In poche parole, il file functions.php di WordPress permette di aggiungere snippet di codice al sito. Questi snippet possono essere utilizzati in molti modi, quindi capire come funziona il file functions.php pu\u00f2 aiutarvi a creare un sito WordPress migliore.<\/p>\n<p>E questa \u00e8 una guida definitiva al file functions.php di WordPress che vi illustrer\u00e0 tutto quello che c&#8217;\u00e8 da sapere al riguardo.<\/p>\n<p>Dopo aver spiegato tutto sul file functions.php, offriremo anche 17 utili snippet di codice per il functions.php per aiutarvi a personalizzare il vostro sito.<\/p>\n<div><\/div><kinsta-auto-toc heading=\"Table of Contents\" exclude=\"last\" list-style=\"arrow\" selector=\"h2\" count-number=\"-1\"><\/kinsta-auto-toc>\n<h2>Cosa Fa il File functions.php di WordPress?<\/h2>\n<p>Il file functions.php di WordPress \u00e8 un file del tema da utilizzare per aggiungere frammenti di codice personalizzati al proprio sito. Si possono utilizzare questi snippet per modificare il funzionamento di diverse aree del sito o per aggiungere nuovi contenuti o del codice.<\/p>\n<p>Anche se fa parte deel tema, il file functions.php di WordPress non si limita alla personalizzazione del tema stesso.<\/p>\n<p>\u00c8 possibile apportare modifiche a qualsiasi parte del sito, pi\u00f9 o meno come si fa con i plugin.<\/p>\n<p>Ecco alcuni tipi di modifiche che si possono effettuare utilizzando il file functions.php di WordPress:<\/p>\n<ul>\n<li>Modificare il comportamento predefinito di WordPress, ad esempio quanti post mostrare nella pagina dei risultati di ricerca o quali contenuti includere nel feed RSS del sito.<\/li>\n<li>Creare shortcode personalizzati.<\/li>\n<li>Aggiungere nuovi contenuti o script al sito, come ad esempio iniettare uno script del proprio servizio di live chat in alcune pagine o <a href=\"https:\/\/kimgsta.com\/it\/blog\/modificare-il-footer-in-wordpress\/\">modificare il footer del sito<\/a>.<\/li>\n<\/ul>\n<p>Ma questo \u00e8 solo una piccola parte.<\/p>\n<p>Dato che il file functions.php permette di aggiungere al sito snippet di codice PHP personalizzati anzich\u00e9 codice <a href=\"https:\/\/kimgsta.com\/it\/blog\/da-html-a-wordpress\/\">HTML statico<\/a>, le modifiche che si possono apportare sono pressoch\u00e9 infinite.<\/p>\n<h3>Dove si Trova il File functions.php di WordPress?<\/h3>\n<p>Il file functions.php di WordPress si trova nella cartella del tema attivo, insieme ad <a href=\"https:\/\/kimgsta.com\/it\/blog\/gerarchia-dei-template-wordpress\/\">altri file del tema<\/a>. Per trovare il file, basta collegarsi al server utilizzando l&#8217;FTP o uno strumento di gestione dei file e navigare in <strong>&#8230;\/wp-content\/themes\/[nome del tema attivo]\/functions.php<\/strong><\/p>\n<p>Ad esempio, se state utilizzando <a href=\"https:\/\/kimgsta.com\/it\/blog\/oceanwp\/\">il famoso tema OceanWP<\/a>, il file functions.php si trova in <strong>&#8230;\/wp-content\/themes\/oceanwp\/functions.php<\/strong><\/p>\n\n<h2>Lavorare in Sicurezza con il File functions.php<\/h2>\n<p>Poich\u00e9 lavorare con il file functions.php di WordPress comporta l&#8217;aggiunta di codice al proprio sito web, \u00e8 importante seguire alcuni accorgimenti prima di iniziare a fare qualsiasi modifica.<\/p>\n<p>Anche qualcosa di semplice come una virgola o un apostrofo mancante pu\u00f2 causare <a href=\"https:\/\/kimgsta.com\/it\/blog\/errori-wordpress\/\">errori sul sito<\/a>, come la <a href=\"https:\/\/kimgsta.com\/it\/blog\/schermo-bianco-della-morte-di-wordpress\/\">schermata bianca della morte (White Screen of Death) di WordPress<\/a>.<\/p>\n<p>Nelle versioni pi\u00f9 recenti di WordPress, questi errori vengono gestiti in modo pi\u00f9 accurato, ad esempio mostrando il <a href=\"https:\/\/kimgsta.com\/it\/blog\/si-e-verificato-un-errore-critico-sul-tuo-sito-web\/\"> messaggio &#8220;Si \u00e8 verificato un errore critico sul tuo sito web&#8221;<\/a> o verificando la presenza di errori PHP prima di salvare le modifiche.<\/p>\n<p>Ad ogni modo, per evitare che si verifichino problemi, vi consigliamo sempre di seguire queste best practice.<\/p>\n<h3>Testare il Codice del File functions.php su un Sito di Prova<\/h3>\n<p>Prima di aggiungere qualsiasi snippet di codice functions.php al proprio sito WordPress live, consigliamo sempre di testarlo su una versione di staging del sito. In questo modo potrete controllare eventuali errori e verificare che lo snippet funzioni come previsto.<\/p>\n<aside role=\"note\" class=\"wp-block-kinsta-notice is-style-info\">\n            <h3>Info<\/h3>\n        <p>Un &#8220;sito di staging&#8221; \u00e8 una copia identica del sito web live che si trova in una sandbox sicura e privata. Permette di testare le modifiche senza dover <a href=\"https:\/\/kimgsta.com\/it\/blog\/modalita-manutenzione-wordpress\/\">utilizzare la modalit\u00e0 di manutenzione sul sito live<\/a>.<\/p>\n<\/aside>\n\n<p>Se avete un hosting con Kinsta, <a href=\"https:\/\/kimgsta.com\/it\/docs\/hosting-wordpress\/ambienti-di-staging\/\">Kinsta offre un semplice strumento di staging a un solo clic<\/a> su tutti i piani, che \u00e8 uno dei <a href=\"https:\/\/kimgsta.com\/it\/hosting-wordpress\/\">vantaggi dell&#8217;utilizzo di un Hosting WordPress Gestito<\/a>.<\/p>\n<p>Se il vostro hosting \u00e8 di un altro tipo, consultate la <a href=\"https:\/\/kimgsta.com\/it\/blog\/wordpress-staging\/\">nostra guida sulla creazione di un sito di staging per WordPress<\/a>.<\/p>\n<h3>Eseguire il Backup del Sito Prima di Apportare Modifiche al File functions.php<\/h3>\n<p>Oltre a testare su un sito di staging, dovrete eseguire un backup del sito web live prima di aggiungere il frammento di codice al file functions.php del sito live.<\/p>\n<p>Questa \u00e8 una buona pratica da seguire quando si modificano <a href=\"https:\/\/kimgsta.com\/it\/blog\/file-di-wordpress\/\">i file di WordPress<\/a>.<\/p>\n<p>Se qualcosa dovesse andare storto con lo snippet, potrete ripristinare questo backup per far funzionare immediatamente il sito.<\/p>\n<p>Se il vostro hosting \u00e8 gestito da Kinsta, <a href=\"https:\/\/kimgsta.com\/it\/docs\/hosting-wordpress\/wordpress-backup\/#wordpress-backup\">Kinsta esegue automaticamente il backup del sito ogni giorno<\/a> ed \u00e8 anche possibile creare manualmente un backup in qualsiasi momento. Se il sito \u00e8 ospitato altrove, leggete la nostra <a href=\"https:\/\/kimgsta.com\/it\/blog\/backup-sito-wordpress\/\">guida su come eseguire il backup di un sito WordPress<\/a>.<\/p>\n<h3>Utilizzare Sempre un Child Theme Quando si Deve Modificare il File functions.php<\/h3>\n<p>Poich\u00e9 il file functions.php di WordPress si trova nel <a href=\"https:\/\/kimgsta.com\/it\/blog\/come-personalizzare-il-vostro-tema-wordpress\/\">codice del tema WordPress<\/a>, il tema sovrascriver\u00e0 il file functions.php quando <a href=\"https:\/\/kimgsta.com\/it\/blog\/come-aggiornare-un-tema-wordpress\/\">lo aggiornerete<\/a>.<\/p>\n<p>Per evitare che le modifiche apportate al file functions.php del tema vengano sovrascritte, \u00e8 sempre bene utilizzare un child theme di WordPress e aggiungere gli snippet di codice al file functions.php <em>del child theme<\/em>.<\/p>\n<p>Utilizzando un child theme, potrete comunque aggiornare il tema principale quando necessario, ma tutte le personalizzazioni del functions.php non saranno mai sovrascritte.<\/p>\n<p>Per saperne di pi\u00f9, consultate la nostra <a href=\"https:\/\/kimgsta.com\/it\/blog\/child-theme-wordpress\/\">guida completa su come creare un child theme per WordPress<\/a>.<\/p>\n<h2>2 Alternative al File functions.php<\/h2>\n<p>Sebbene il file functions.php di WordPress offra un modo semplice per aggiungere frammenti di codice al sito, esistono alcune alternative a functions.php che offrono una soluzione migliore nella maggior parte delle situazioni:<\/p>\n<ol>\n<li>Utilizzare un plugin per la gestione del codice<\/li>\n<li>Memorizzare gli snippet di codice in un plugin personalizzato<\/li>\n<\/ol>\n<p>Queste alternative possono presentare alcuni vantaggi rispetto all&#8217;utilizzo del file functions.php:<\/p>\n<ul>\n<li><strong>Non sono legate al tema<\/strong> &#8211; questo significa che se si dovesse cambiare tema, le personalizzazioni in functions.php saranno ancora presenti.<\/li>\n<li><strong>Migliore organizzazione <\/strong>&#8211; queste alternative rendono pi\u00f9 facile l&#8217;organizzazione dei frammenti di codice, il che pu\u00f2 essere utile se si ha intenzione di aggiungere molti snippet al sito.<\/li>\n<li><strong>Maggiore controllo <\/strong>&#8211; nel caso di un plugin per la gestione del codice, si avranno a disposizione opzioni utili come l&#8217;abilitazione\/disabilitazione di uno snippet tramite un pulsante, l&#8217;esecuzione di snippet solo sul frontend o sul backend e altro ancora.<\/li>\n<\/ul>\n<h3>Usare un Plugin per la Gestione del Codice<\/h3>\n<p>Un plugin per la gestione del codice \u00e8 un plugin che offre un&#8217;interfaccia facile da usare per aggiungere e modificare gli snippet di codice che altrimenti andrebbero nel file functions.php.<\/p>\n<p>Una delle opzioni pi\u00f9 popolari \u00e8 il <a href=\"https:\/\/wordpress.org\/plugins\/code-snippets\/\" target=\"_blank\" rel=\"noopener noreferrer\">plugin gratuito Code Snippets<\/a>, ma esistono altri plugin che offrono funzionalit\u00e0 simili.<\/p>\n<p>Con Code Snippets, \u00e8 possibile aggiungere gli snippet di codice functions.php dalla bacheca di WordPress, con tanto di opzioni per:<\/p>\n<ul>\n<li>Aggiungere un titolo e una descrizione.<\/li>\n<li>Organizzare gli snippet utilizzando dei tag.<\/li>\n<li>Eseguire lo snippet solo in una determinata parte del sito.<\/li>\n<\/ul>\n<figure id=\"attachment_150158\" aria-describedby=\"caption-attachment-150158\" style=\"width: 1024px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-150158\" src=\"https:\/\/kimgsta.com\/wp-content\/uploads\/2023\/03\/code-snippets-interface-1024x908.jpg\" alt=\"Aggiunta di uno snippet di codice nel plugin Code Snippets.\" width=\"1024\" height=\"908\"><figcaption id=\"caption-attachment-150158\" class=\"wp-caption-text\">Aggiunta di uno snippet di codice nel plugin Code Snippets.<\/figcaption><\/figure>\n<p>In questo modo potrete vedere tutti gli snippet in un elenco e attivarli\/disattivarli facilmente a seconda delle vostre necessit\u00e0.<\/p>\n<figure id=\"attachment_150157\" aria-describedby=\"caption-attachment-150157\" style=\"width: 1024px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-150157\" src=\"https:\/\/kimgsta.com\/wp-content\/uploads\/2023\/03\/code-snippets-code-list-1024x661.jpg\" alt=\"Come gestire gli snippet in Code Snippets.\" width=\"1024\" height=\"661\"><figcaption id=\"caption-attachment-150157\" class=\"wp-caption-text\">Come gestire gli snippet in Code Snippets.<\/figcaption><\/figure>\n<p>Poich\u00e9 Code Snippets \u00e8 un plugin, tutti gli snippet di codice saranno sempre presenti anche se <a href=\"https:\/\/kimgsta.com\/it\/blog\/cambiare-tema-wordpress\/\">cambierete tema di WordPress<\/a>.<\/p>\n<h3>Creare un Plugin di Funzioni Personalizzate<\/h3>\n<p>Un&#8217;altra alternativa all&#8217;uso del file functions.php di WordPress \u00e8 quella di creare un plugin personalizzato per ospitare gli snippet di codice.<\/p>\n<p>Anche se pu\u00f2 sembrare complicato, in realt\u00e0 \u00e8 molto pi\u00f9 semplice di quanto si pensi.<\/p>\n<p>Ecco come funziona:<\/p>\n<ol>\n<li>Create una cartella sul computer locale per il vostro plugin.<\/li>\n<li>Create un singolo file .php all&#8217;interno della cartella e modificatelo con il vostro editor di testo preferito.<\/li>\n<li>Aggiungete il modello di codice qui sotto al file.<\/li>\n<li>Aggiungete gli snippet di codice functions.php al file.<\/li>\n<\/ol>\n<pre><code class=\"language-php\">&lt;?php\n\n\/**\n* Plugin Name: My Custom Code Snippets\n* Description: This is a custom plugin to house code snippets.\n* Author: Kinsta\n* Version: 1.0\n*\/\n\n\/* Add the first code snippet below this comment - use the comment to explain what it does. *\/\n[CODE]\n\n\/* Add the second code snippet below this comment. *\/\n[CODE]\n\n\/* Continue as needed. *\/\n[CODE]\n\n?&gt;<\/code><\/pre>\n<p>A questo punto, non resta che installare e attivare il plugin su WordPress. Ecco due modi per farlo:<\/p>\n<ol>\n<li>Collegatevi al server tramite <a href=\"https:\/\/kimgsta.com\/it\/blog\/ftp-sftp\/\">FTP\/SFTP<\/a> e caricate la cartella del plugin personalizzato nella cartella <strong>wp-content\/plugins<\/strong>. Poi, andate nell&#8217;elenco dei <strong>plugin <\/strong>e attivate il plugin.<\/li>\n<li>Usate il computer per creare un file .zip della cartella. Quindi, andate su <strong>Plugin \u2192 Aggiungi nuovo<\/strong> e caricate il file .zip per installarlo come qualsiasi altro plugin.<\/li>\n<\/ol>\n<h2>Come Accedere al File functions.php di WordPress: 2 Opzioni<\/h2>\n<p>Esistono diversi modi per accedere e modificare il file functions.php di WordPress. Ecco due dei metodi pi\u00f9 versatili che funzionano con qualsiasi host:<\/p>\n<ol>\n<li>Editor del codice del tema della bacheca di WordPress.<\/li>\n<li>SFTP ed editor di codice.<\/li>\n<\/ol>\n<h3>1. Utilizzare l&#8217;Editor del Codice del Tema della Bacheca di WordPress<\/h3>\n<p>Per impostazione predefinita, WordPress permette di modificare tutto il codice del tema dalla bacheca di WordPress, compreso il file functions.php:<\/p>\n<ol>\n<li>Aprite la bacheca di WordPress.<\/li>\n<li>Andate su <strong>Aspetto \u2192 Editor dei file del tema<\/strong>.<\/li>\n<li>Selezionate il file <strong>Funzioni del tema (functions.php)<\/strong> nell&#8217;elenco dei <strong>file del tema<\/strong> sul lato destro.<\/li>\n<li>Aggiungete le modifiche nell&#8217;editor di codice.<\/li>\n<li>Cliccate sul pulsante <strong>Aggiorna file<\/strong> per salvare le modifiche.<\/li>\n<\/ol>\n<figure id=\"attachment_150162\" aria-describedby=\"caption-attachment-150162\" style=\"width: 1024px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-150162\" src=\"https:\/\/kimgsta.com\/wp-content\/uploads\/2023\/03\/edit-functionsphp-wp-dashboard-1024x961.jpg\" alt=\"Come modificare il file functions.php dalla bacheca di WordPress.\" width=\"1024\" height=\"961\"><figcaption id=\"caption-attachment-150162\" class=\"wp-caption-text\">Come modificare il file functions.php dalla bacheca di WordPress.<\/figcaption><\/figure>\n<p>Detto questo, molte persone preferiscono <a href=\"https:\/\/kimgsta.com\/it\/blog\/wordpress-e-sicurezza\/#16-disable-file-editing-in-wordpress-dashboard\">disabilitare la modifica dei file dalla bacheca di WordPress per aumentare la sicurezza<\/a>. In questo caso, si pu\u00f2 utilizzare il metodo seguente.<\/p>\n<h3>2. Usare SFTP + un Editor di Codice<\/h3>\n<p>Per modificare il file functions.php di WordPress, <a href=\"https:\/\/kimgsta.com\/it\/blog\/cosa-e-ftp\/\">collegatevi al vostro server tramite FTP\/SFTP<\/a> e modificate il file.<\/p>\n<p>Ecco come fare:<\/p>\n<ol>\n<li>Scaricate <a href=\"https:\/\/kimgsta.com\/it\/blog\/migliori-client-ftp\/\">un client FTP<\/a> se non l&#8217;avete ancora fatto &#8211; per gli screenshot useremo <a href=\"https:\/\/filezilla-project.org\/\" target=\"_blank\" rel=\"noopener noreferrer\">il client gratuito FileZilla<\/a>.<\/li>\n<li>Connettetevi al server utilizzando le credenziali FTP &#8211; ecco <a href=\"https:\/\/kimgsta.com\/it\/blog\/come-utilizzare-sftp\/\">come utilizzare l&#8217;SFTP per connettersi<\/a>.<\/li>\n<li>Utilizzate la struttura delle cartelle per navigare in <strong>&#8230;\/wp-content\/themes\/[your-active-child-theme]<\/strong>.<\/li>\n<li>Cliccate con il tasto destro del mouse sul file <strong>functions.php<\/strong> e selezionate <strong>Modifica<\/strong>.<\/li>\n<\/ol>\n<figure id=\"attachment_150161\" aria-describedby=\"caption-attachment-150161\" style=\"width: 1024px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-150161\" src=\"https:\/\/kimgsta.com\/wp-content\/uploads\/2023\/03\/edit-functionsphp-ftp-1024x830.jpg\" alt=\"Come modificare il file functions.php con FileZilla.\" width=\"1024\" height=\"830\"><figcaption id=\"caption-attachment-150161\" class=\"wp-caption-text\">Come modificare il file functions.php con FileZilla.<\/figcaption><\/figure>\n<p>Questo dovrebbe scaricare il file sul vostro computer locale e aprirlo automaticamente in un editor di testo. Ora potete aggiungere i frammenti di codice al file.<\/p>\n<figure id=\"attachment_150159\" aria-describedby=\"caption-attachment-150159\" style=\"width: 1024px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-150159\" src=\"https:\/\/kimgsta.com\/wp-content\/uploads\/2023\/03\/edit-functionsphp-ftp-code-editor-1024x560.jpg\" alt=\"FileZilla aprir\u00e0 il file in un editor di testo locale, ad esempio Sublime Text.\" width=\"1024\" height=\"560\"><figcaption id=\"caption-attachment-150159\" class=\"wp-caption-text\">FileZilla aprir\u00e0 il file in un editor di testo locale, ad esempio Sublime Text.<\/figcaption><\/figure>\n<p>Quando avrete finito, salvate le modifiche e chiudete il file.<\/p>\n<p>FileZilla dovrebbe quindi mostrare un prompt per ricaricare la versione modificata sul vostro server.<\/p>\n<figure id=\"attachment_150160\" aria-describedby=\"caption-attachment-150160\" style=\"width: 1024px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-150160\" src=\"https:\/\/kimgsta.com\/wp-content\/uploads\/2023\/03\/edit-functionsphp-ftp-reupload-1024x590.jpg\" alt=\"Assicurarsi di ricaricare il file functions.php una volta apportate le modifiche.\" width=\"1024\" height=\"590\"><figcaption id=\"caption-attachment-150160\" class=\"wp-caption-text\">Assicurarsi di ricaricare il file functions.php una volta apportate le modifiche.<\/figcaption><\/figure>\n<h2>Le Funzioni pi\u00f9 Utili da Aggiungere al File functions.php di WordPress<\/h2>\n<p>Ora che sapete come modificare il file functions.php di WordPress, vediamo alcuni degli snippet di codice functions.php pi\u00f9 utili da aggiungere al sito.<\/p>\n<h3>Mostrare la Data dell&#8217;Ultima Modifica negli Articoli del Blog<\/h3>\n<p>Per impostazione predefinita, la maggior parte dei temi mostra la data di pubblicazione di un articolo del blog. Se per\u00f2 aggiornate e rinfrescate regolarmente i vecchi contenuti, potreste voler mostrare anche l&#8217;ultima data di modifica (o sostituire la data di pubblicazione con l&#8217;ultima data di modifica).<\/p>\n<p>In questo modo non solo i visitatori sapranno che state aggiornando i contenuti, ma lo sapr\u00e0 anche Google.<\/p>\n<pre><code class=\"language-php\">function show_last_updated( $content ) {\n$u_time = get_the_time('U');\n$u_modified_time = get_the_modified_time('U');\nif ($u_modified_time &gt;= $u_time + 86400) {\n$updated_date = get_the_modified_time('F jS, Y');\n$updated_time = get_the_modified_time('h:i a');\n$custom_content .= '&lt;p class=\"last-updated-date\"&gt;Recently updated on '. $updated_date . ' at '. $updated_time .'&lt;\/p&gt;';\n}\n$custom_content .= $content;\nreturn $custom_content;\n}\nadd_filter( 'the_content', 'show_last_updated' );<\/code><\/pre>\n<p>Per maggiori dettagli, consultate il nostro articolo su <a href=\"https:\/\/kimgsta.com\/it\/blog\/ultimo-aggiornamento\/\">come mostrare la data di ultima modifica su WordPress<\/a>.<\/p>\n<h3>Disabilitare la Barra degli Strumenti di WordPress per Alcuni Utenti<\/h3>\n<p>Per impostazione predefinita, WordPress mostra la barra degli strumenti di WordPress a tutti gli utenti che hanno effettuato l&#8217;accesso utilizzando i <a href=\"https:\/\/kimgsta.com\/it\/blog\/ruoli-utente-wordpress\/\">ruoli utente di WordPress<\/a>. <em>Questo non vale necessariamente per i ruoli personalizzati, come ad esempio il ruolo utente Cliente per i <\/em><a href=\"https:\/\/kimgsta.com\/it\/blog\/tutorial-woocommerce\/\"><em>Negozi WooCommerce<\/em><\/a><em>.<\/em><\/p>\n<p>Per effettuare questa modifica, potete usare uno snippet di codice functions.php per nascondere la barra degli strumenti di WordPress per alcuni ruoli utente.<\/p>\n<p>Questo esempio prevede di nascondere la barra degli strumenti di amministrazione per gli utenti con il ruolo di autore.<\/p>\n<pre><code class=\"language-php\">add_filter( 'show_admin_bar', function( $show ) {\nif ( current_user_can( 'author' ) ) {\nreturn false;\n}\nreturn $show;\n} );<\/code><\/pre>\n<h3>Ritardare la Visualizzazione dei Post nel Feed RSS<\/h3>\n<p>Per impostazione predefinita, i contenuti appaiono nel feed RSS non appena vengono pubblicati. Questo pu\u00f2 dare la possibilit\u00e0 agli <a href=\"https:\/\/kimgsta.com\/it\/blog\/scraping-contenuti\/\">scraper di &#8220;raschiare&#8221;<\/a> i <a href=\"https:\/\/kimgsta.com\/it\/blog\/web-scraping\/\">vostri contenuti<\/a> e <a href=\"https:\/\/kimgsta.com\/it\/blog\/segnalare-sito-web-motori-ricerca\/\">indicizzarli su Google<\/a> prima ancora che Google indicizzi il post originale.<\/p>\n<p>Per evitare che qualcun altro si prenda il merito dei vostri contenuti, \u00e8 possibile ritardare la comparsa dei post nel feed RSS.<\/p>\n<p>Anche se questo non fermer\u00e0 completamente gli scraper di contenuti, almeno darete a Google il tempo di indicizzarli prima.<\/p>\n<p>Ecco lo snippet di codice: si pu\u00f2 cambiare il numero &#8211; &#8220;30&#8221; in questo esempio &#8211; con il numero di minuti di ritardo desiderato:<\/p>\n<pre><code class=\"language-php\">function kinsta_delay_feed_content($where) {\n\nglobal $wpdb;\n\nif ( is_feed() ) {\n\/\/ timestamp in WP-format\n$now = gmdate('Y-m-d H:i:s');\n\n\/\/ value for wait; + device\n$wait = '30'; \/\/ integer\n\n\/\/ http:\/\/dev.mysql.com\/doc\/refman\/5.0\/en\/date-and-time-functions.html#function_timestampdiff\n$device = 'MINUTE'; \/\/MINUTE, HOUR, DAY, WEEK, MONTH, YEAR\n\n\/\/ add SQL-sytax to default $where\n$where .= \" AND TIMESTAMPDIFF($device, $wpdb-&gt;posts.post_date_gmt, '$now') &gt; $wait \";\n}\nreturn $where;\n}\n\nadd_filter('posts_where', 'kinsta_delay_feed_content');<\/code><\/pre>\n<h3>Escludere Alcune Categorie dal Feed RSS<\/h3>\n<p>Oltre a ritardare la comparsa dei contenuti nel feed RSS, magari volete anche escludere intere categorie di post dal feed RSS del sito.<\/p>\n<p>Per ottenere questo risultato, utilizzate il seguente frammento di codice functions.php:<\/p>\n<pre><code class=\"language-php\">function kinsta_exclude_category_rss($query) {\nif ($query-&gt;is_feed) {\n$query-&gt;set('cat','-38');\n}\nreturn $query;\n}\nadd_filter('pre_get_posts','kinsta_exclude_category_rss');<\/code><\/pre>\n<p>Assicuratevi di sostituire l&#8217;ID della categoria di esempio &#8211; &#8220;38&#8221; &#8211; con gli ID delle categorie che volete escludere (e di non rimuovere il segno meno)<\/p>\n<p>Ecco come trovare il numero ID:<\/p>\n<ol>\n<li>Andate su <strong>Messaggi \u2192 Categorie<\/strong> per vedere l&#8217;elenco di tutte le categorie del sito.<\/li>\n<li>Cliccate su <strong>Modifica<\/strong> sotto la categoria che volete escludere.<\/li>\n<li>Guardate l&#8217;URL della pagina di modifica nella barra degli indirizzi del browser. L&#8217;ID della categoria \u00e8 il numero che viene dopo <strong>?taxonomy=category&#038;tag_ID=X<\/strong>.<\/li>\n<\/ol>\n<p>Ad esempio, se l&#8217;URL \u00e8 <strong>https:\/\/yoursite.com\/wp-admin\/term.php?taxonomy=category&#038;tag_ID=38&#038;post_type=post,<\/strong> allora l&#8217;ID della categoria \u00e8 <b>38<\/b>.<\/p>\n<h3>Limitare le Revisioni di WordPress per Tipo di Post<\/h3>\n<p>Per evitare di gonfiare il database del sito, si pu\u00f2 limitare il numero di revisioni dei post da salvare.<\/p>\n<p>Sebbene un modo per limitare le <a href=\"https:\/\/kimgsta.com\/it\/blog\/revisioni-wordpress\/\">revisioni dei post di WordPress<\/a> in tutto il sito sia quello di modificare il <a href=\"https:\/\/kimgsta.com\/it\/blog\/wp-config-php\/\">file wp-config.php del sito<\/a>, magari preferite memorizzare un numero diverso di revisioni per diversi tipi di post, ad esempio per gli articoli del blog o per i prodotti di WooCommerce.<\/p>\n<p>Questo frammento di codice functions.php vi permetter\u00e0 di farlo. Per personalizzarlo, cambiate il tipo di post &#8211; &#8220;post&#8221; in questo esempio &#8211; con il tipo di post da controllare e il numero &#8211; &#8220;5&#8221; in questo esempio &#8211; con il numero di revisioni da memorizzare.<\/p>\n<pre><code class=\"language-php\">function kinsta_post_revisions_by_type( $revisions, $post ) {\n\nif( 'post' == $post-&gt;post_type ) {\n$revisions = 5;\n}\n\nreturn $revisions;\n\n}\n\nadd_filter( 'wp_revisions_to_keep', 'kinsta_post_revisions_by_type', 10, 2 );<\/code><\/pre>\n<p>* Nota: state modificando il &#8220;post&#8221; che viene immediatamente dopo l&#8217;istruzione &#8220;if&#8221;. Ad esempio, per puntare ai prodotti, questa riga dovrebbe essere cos\u00ec:<\/p>\n<pre><code class=\"language-php\">if( 'product' == $post-&gt;post_type ) {<\/code><\/pre>\n<h3>Disattivare la Funzione di Ricerca di WordPress<\/h3>\n<p>Se il vostro sito non ha bisogno di funzionalit\u00e0 di ricerca, si pu\u00f2 disabilitare <a href=\"https:\/\/kimgsta.com\/it\/blog\/ricerca-wordpress\/\">la funzione di ricerca di WordPress<\/a> per evitare potenziali abusi.<\/p>\n<p>Infatti, anche se non visualizzate una casella di ricerca sul sito, i bot possono comunque utilizzare la funzione di ricerca aggiungendo ?s=[termine di ricerca] all&#8217;URL.<\/p>\n<p>Per fare ci\u00f2, basta aggiungere il seguente snippet:<\/p>\n<pre><code class=\"language-php\">function kinsta_disable_wp_search( $query, $error = true ) {\n\nif ( is_search() ) {\n$query-&gt;is_search = false;\n$query-&gt;query_vars[s] = false;\n$query-&gt;query[s] = false;\n\n\/\/ to error\nif ( $error == true )\n$query-&gt;is_404 = true;\n}\n}\n\nadd_action( 'parse_query', 'kinsta_disable_wp_search' );\nadd_filter( 'get_search_form', create_function( '$a', \"return null;\" ) );<\/code><\/pre>\n<p>Se qualcuno tenta di utilizzare direttamente la funzione di ricerca, il sito restituir\u00e0 una pagina 404.<\/p>\n<h3>Creare Shortcode Personalizzati (ad es. Anno Corrente)<\/h3>\n<p>Gli <a href=\"https:\/\/kimgsta.com\/it\/blog\/shortcode-wordpress\/\">shortcode di WordPress<\/a> sono delle scorciatoie molto utili che permettono di incorporare contenuti dinamici nel proprio sito.<\/p>\n<p>Sebbene molti plugin di WordPress si affidino agli shortcode per le loro funzionalit\u00e0, \u00e8 anche possibile creare i propri shortcode personalizzati utilizzando il file functions.php di WordPress e la <a href=\"https:\/\/developer.wordpress.org\/reference\/functions\/add_shortcode\/\" target=\"_blank\" rel=\"noopener noreferrer\">funzione add_shortcode()<\/a>.<\/p>\n<p>Ad esempio, un caso d&#8217;uso comune \u00e8 quello di creare uno shortcode che mostri l&#8217;anno corrente. In questo modo si pu\u00f2 mostrare automaticamente l&#8217;anno corrente in tutti i contenuti senza dover aggiornare manualmente tutto il sito ogni 1\u00b0 gennaio.<\/p>\n<p>Per creare uno shortcode di questo tipo, utilizzate il seguente codice:<\/p>\n<pre><code class=\"language-php\">function year_shortcode() {\n$year = date('Y');\nreturn $year;\n}\nadd_shortcode('currentyear', 'year_shortcode');<\/code><\/pre>\n<p>Quando aggiungerete lo shortcode [currentyear] ai vostri contenuti, verr\u00e0 automaticamente sostituito con l&#8217;anno attuale, ad esempio 2023.<\/p>\n<h3>Consentire gli Shortcode nei Titoli dei Post<\/h3>\n<p>Per impostazione predefinita, WordPress non esegue gli shortcode inseriti nel campo del titolo degli articoli. Se volete utilizzare gli shortcode nei titoli dei post di WordPress, potrete abilitare questa funzionalit\u00e0 aggiungendo un semplice frammento di codice al file functions.php di WordPress.<\/p>\n<p>Ad esempio, se combinato con lo snippet di codice precedente, questo vi permetter\u00e0 di includere automaticamente l&#8217;anno corrente nel titolo dell&#8217;articolo aggiungendo lo shortcode [currentyear].<\/p>\n<pre><code class=\"language-php\">add_filter( 'the_title', 'do_shortcode' );<\/code><\/pre>\n<h3>Nascondere gli Errori di Accesso per Migliorare la Sicurezza<\/h3>\n<p>Per impostazione predefinita, WordPress mostra un messaggio esplicativo in caso di tentativi di accesso falliti. Questo messaggio pu\u00f2 fornire alcune informazioni, come ad esempio se un certo indirizzo e-mail \u00e8 registrato sul sito (anche se la password non \u00e8 corretta).<\/p>\n<p>Per evitare di far trapelare informazioni potenzialmente sensibili, \u00e8 possibile nascondere questi errori di accesso aggiungendo il seguente frammento di codice al file functions.php.<\/p>\n<pre><code class=\"language-php\">function kinsta_hide_login_errors(){\nreturn 'These are not valid credentials';\n}\nadd_filter( 'login_errors', 'kinsta_hide_login_errors' );<\/code><\/pre>\n<p>Questo snippet sostituisce il testo predefinito dell&#8217;errore di login con il seguente messaggio &#8211; <strong>These are not valid credentials<\/strong>.<\/p>\n<p>Potrete personalizzare il testo in base alle vostre preferenze, ma cercate di evitare l&#8217;uso di trattini, slash o altri caratteri che potrebbero causare un errore (a meno che non aggiungiate un &#8220;escape&#8221; di questi caratteri),<\/p>\n<h3>Modificare la Lunghezza dell&#8217;Estratto<\/h3>\n<p>Per impostazione predefinita, l&#8217;estratto di WordPress mostra le prime 55 parole di un post.<\/p>\n<p>Per modificare questa impostazione, aggiungete il seguente snippet al file functions.php.<\/p>\n<pre><code class=\"language-php\">function kinsta_change_excerpt_length($length) {\nreturn 90;\n}\nadd_filter('excerpt_length', 'kinsta_change_excerpt_length');<\/code><\/pre>\n<p>Lo snippet di codice qui sopra cambier\u00e0 la lunghezza dell&#8217;estratto in 90 parole. Se preferite un numero diverso, sostituite &#8220;90&#8221; con il numero esatto di parole che volete utilizzare.<\/p>\n<h3>Rimuovere il Numero di Versione di WordPress<\/h3>\n<p>Per rendere pi\u00f9 difficile individuare la versione di WordPress ai malintenzionati, alcuni utenti preferiscono rimuovere il numero di versione di WordPress da qualsiasi parte del codice del frontend del sito.<\/p>\n<p>Per farlo, aggiungete i seguenti snippet al file functions.php.<\/p>\n<pre><code class=\"language-php\">function kinsta_hide_version() {\nreturn '';\n}\nadd_filter('the_generator', 'kinsta_hide_version');<\/code><\/pre>\n<h3>Impostare la Paginazione di WordPress<\/h3>\n<p>Se non siete soddisfatti del funzionamento della paginazione nel vostro tema, uno snippet di codice functions.php pu\u00f2 regolare il comportamento della paginazione o addirittura creare un sistema di paginazione personalizzato.<\/p>\n<p>Se vi interessa questo tipo di modifica, abbiamo <a href=\"https:\/\/kimgsta.com\/it\/blog\/paginazione-di-wordpress\/\">una guida completa sulla paginazione di WordPress<\/a> che include alcuni esempi di snippet functions.php.<\/p>\n<h3>Cambiare il Numero di Risultati da Includere nella Pagina dei Risultati di Ricerca<\/h3>\n<p>WordPress offre un&#8217;opzione nella bacheca per controllare quanti post elencare nelle pagine di archivio (<strong>Impostazioni \u2192 Lettura<\/strong>).<\/p>\n<p>Tuttavia, questa impostazione modifica il numero per <em>tutte<\/em> le pagine di archivio. E se voleste utilizzare un numero diverso solo per la pagina dei risultati di ricerca?<\/p>\n<p>Per farlo, aggiungete questo snippet al file functions.php &#8211; assicuratevi di cambiare il numero (&#8220;12&#8221; in questo esempio) con il numero effettivo di risultati che volete visualizzare prima di impaginare altri risultati.<\/p>\n<pre><code class=\"language-php\">function kinsta_search_results_list() {\nif ( is_search() )\nset_query_var('posts_per_archive_page', 12);\n}\n\nadd_filter('pre_get_posts', 'kinsta_search_results_list');<\/code><\/pre>\n<h3>Includere le Immagini in Primo Piano nel Feed RSS di WordPress<\/h3>\n<p>Per includere le <a href=\"https:\/\/kimgsta.com\/it\/blog\/immagine-in-evidenza-non-visualizzata\/\">immagini in primo piano degli articoli<\/a> nel contenuto del feed RSS, aggiungete il seguente snippet al file functions.php.<\/p>\n<pre><code class=\"language-php\">function kinsta_featured_image_rss($content) {\nglobal $post;\nif ( has_post_thumbnail( $post-&gt;ID ) ){\n$content = '&lt;div&gt;' . get_the_post_thumbnail( $post-&gt;ID, 'full', array( 'style' =&gt; 'margin-bottom: 15px;' ) ) . '&lt;\/div&gt;' . $content;\n}\nreturn $content;\n}\n\nadd_filter('the_excerpt_rss', 'kinsta_featured_image_rss');\nadd_filter('the_content_feed', 'kinsta_featured_image_rss');<\/code><\/pre>\n<p>Cos\u00ec com&#8217;\u00e8 scritto, il frammento di codice inserisce l&#8217;immagine a grandezza naturale. Per utilizzare una miniatura di dimensioni diverse, sostituite &#8220;full&#8221; con una miniatura di dimensioni diverse, ad esempio &#8220;large&#8221; o &#8220;medium&#8221;.<\/p>\n<h3>Aggiungere il supporto per il caricamento di tipi di file (ad esempio SVG)<\/h3>\n<p>Per impostazione predefinita, WordPress impedisce di caricare alcuni tipi di file, come ad esempio i <a href=\"https:\/\/kimgsta.com\/it\/blog\/wordpress-svg\/\">file SVG<\/a>.<\/p>\n<p>Per abilitare il supporto per questi tipi di file bloccati, aggiungete il seguente frammento di codice al file functions.php di WordPress:<\/p>\n<pre><code class=\"language-php\">function kinsta_myme_types($mime_types){\n$mime_types['svg'] = 'image\/svg+xml';\nreturn $mime_types;\n}\nadd_filter('upload_mimes', 'kinsta_myme_types', 1, 1);<\/code><\/pre>\n<p>Questo snippet abilita solo il caricamento di SVG, ma si pu\u00f2 modificare per aggiungere il supporto ad altri tipi di file se necessario.<\/p>\n<h3>Nascondere gli Avvisi di Aggiornamento di WordPress per i Non Amministratori<\/h3>\n<p>Per impostazione predefinita, WordPress mostra a tutti gli utenti con accesso alla bacheca dei messaggi quando \u00e8 <a href=\"https:\/\/kimgsta.com\/it\/blog\/versione-wordpress\/\">disponibile un nuovo aggiornamento<\/a>.<\/p>\n<p>Anche se il ruolo di un utente non consente di applicare l&#8217;aggiornamento, il messaggio della bacheca gli dir\u00e0 di contattare l&#8217;amministratore.<\/p>\n<p>Per modificare questo aspetto, utilizzate questo frammento di codice per nascondere le notifiche di aggiornamento per tutti gli utenti non amministratori:<\/p>\n<pre class=\"language-php\"><code class=\"language-php\"><span class=\"token keyword\">function<\/span> <span class=\"token function-definition function\">kinsta_hide_update_nag<\/span><span class=\"token punctuation\">(<\/span><span class=\"token punctuation\">)<\/span> <span class=\"token punctuation\">{<\/span>\n<span class=\"token keyword\">if<\/span> <span class=\"token punctuation\">(<\/span> <span class=\"token operator\">!<\/span> <span class=\"token function\">current_user_can<\/span><span class=\"token punctuation\">(<\/span> <span class=\"token string single-quoted-string\">'update_core'<\/span> <span class=\"token punctuation\">)<\/span> <span class=\"token punctuation\">)<\/span> <span class=\"token punctuation\">{<\/span>\n<span class=\"token function\">remove_action<\/span><span class=\"token punctuation\">(<\/span> <span class=\"token string single-quoted-string\">'admin_notices'<\/span><span class=\"token punctuation\">,<\/span> <span class=\"token string single-quoted-string\">'update_nag'<\/span><span class=\"token punctuation\">,<\/span> <span class=\"token number\">3<\/span> <span class=\"token punctuation\">)<\/span><span class=\"token punctuation\">;<\/span>\n<span class=\"token punctuation\">}<\/span>\n<span class=\"token punctuation\">}<\/span>\n\n<span class=\"token function\">add_action<\/span><span class=\"token punctuation\">(<\/span><span class=\"token string single-quoted-string\">'admin_menu'<\/span><span class=\"token punctuation\">,<\/span><span class=\"token string single-quoted-string\">'kinsta_hide_update_nag'<\/span><span class=\"token punctuation\">)<\/span><span class=\"token punctuation\">;<\/span><\/code><\/pre>\n<p>Per altre varianti, consultate la nostra <a href=\"https:\/\/kimgsta.com\/it\/blog\/disattivare-notifiche-di-aggiornamento-di-wordpress\/\">guida su come disattivare le notifiche di aggiornamento di WordPress<\/a>.<\/p>\n<h3>Cambiare la Qualit\u00e0 dell&#8217;Ottimizzazione Automatica dei JPEG<\/h3>\n<p>Anche se non tutti conoscono questa funzione, <a href=\"https:\/\/kimgsta.com\/it\/blog\/compressione-lossy\/#wordpress-automatically-compresses-images\">WordPress comprime automaticamente le immagini JPEG<\/a> quando <a href=\"https:\/\/kimgsta.com\/it\/blog\/dimensioni-immagini-wordpress\/\">crea le miniature per il sito<\/a> dopo il caricamento delle immagini.<\/p>\n<p>A partire da WordPress 4.5, WordPress ha impostato il livello di qualit\u00e0 predefinito a 82 (mentre 100 corrisponde a zero compressione).<\/p>\n<p>Per aumentare o diminuire questo livello di qualit\u00e0, aggiungete il seguente frammento di codice al file functions.php &#8211; assicuratevi di cambiare il numero (&#8220;90&#8221; in questo esempio) con l&#8217;effettivo livello di qualit\u00e0 che desiderate utilizzare:<\/p>\n<pre><code class=\"language-php\">add_filter( 'jpeg_quality', create_function( '', 'return 90;' ) );<\/code><\/pre>\n<h2>Best practice per l&#8217;organizzazione del file functions.php di WordPress<\/h2>\n<p>Se state usando il file functions.php di WordPress solo per aggiungere un paio di snippet di codice, probabilmente non \u00e8 necessario preoccuparvi dell&#8217;organizzazione.<\/p>\n<p>Ma se state aggiungendo molti snippet al sito, il tutto pu\u00f2 diventare rapidamente ingombrante e complesso se non si seguono alcune best practice di organizzazione del file functions.php.<\/p>\n<p>Eccone alcune per mantenere organizzati i vostri snippet di codice.<\/p>\n<h3>Aggiungere Commenti al Codice<\/h3>\n<p>Quando aggiungete per la prima volta uno snippet di codice al file functions.php, sapete esattamente cosa fa lo snippet e perch\u00e9 lo avete aggiunto. Ma quando, a distanza di un anno, rivedrete il file functions.php, le cose potrebbero non sembrarvi cos\u00ec chiare.<\/p>\n<p>Per evitare questo inconveniente, dovrete aggiungere dei commenti di codice a ogni snippet che spieghino cosa fa e perch\u00e9 l&#8217;avete aggiunto.<\/p>\n<p><em>I commenti al codice sono testi che non vengono eseguiti da WordPress, ma che gli utenti possono leggere per capire cosa sta facendo il frammento di codice.<\/em><\/p>\n<p>Per aggiungere un commento di codice di una sola riga, si pu\u00f2 utilizzare questo formato:<\/p>\n<pre><code class=\"language-php\">\/\/ This is a single-line code comment<\/code><\/pre>\n<p>Per aggiungere un commento di codice a pi\u00f9 righe, invece, utilizzate questo formato:<\/p>\n<pre><code class=\"language-php\">\/**\n* This is a code comment that spans multiple lines\n* This text is also in the same comment\n* This is the last line in the code comment\n*\/\n<\/code><\/pre>\n<p>Ecco un esempio di come utilizzare i commenti al codice: potete notare che il commento prima di ogni snippet spiega cosa fa lo snippet.<\/p>\n<figure id=\"attachment_150163\" aria-describedby=\"caption-attachment-150163\" style=\"width: 1024px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-150163\" src=\"https:\/\/kimgsta.com\/wp-content\/uploads\/2023\/03\/using-code-comments-1024x777.jpg\" alt=\"Un esempio di utilizzo dei commenti al codice per documentare gli snippet nel file functions.php.\" width=\"1024\" height=\"777\"><figcaption id=\"caption-attachment-150163\" class=\"wp-caption-text\">Un esempio di utilizzo dei commenti al codice per documentare gli snippet nel file functions.php.<\/figcaption><\/figure>\n<h3>Utilizzare l&#8217;Inclusione dei File per Separare gli Snippet in Diversi File<\/h3>\n<p>Se avete davvero molti snippet di codice, potete archiviarli in file separati invece di usare solo il file functions.php.<\/p>\n<p>Poi, potrete includere questi frammenti di codice nel file functions.php utilizzando include o require. <a href=\"https:\/\/wordpress.stackexchange.com\/questions\/1403\/organizing-code-in-your-wordpress-themes-functions-php-file\" target=\"_blank\" rel=\"noopener noreferrer\">Mike Schinkel ha pubblicato un buon esempio<\/a> di come si fa su StackExchange .<\/p>\n<h3>Considerare una delle Alternative al functions.php gi\u00e0 Menzionate<\/h3>\n<p>Se il vostro file functions.php sta diventando un po&#8217; ingombrante, potreste preferire una delle alternative a functions.php che abbiamo descritto in precedenza.<\/p>\n<p>Ad esempio, <a href=\"https:\/\/wordpress.org\/plugins\/code-snippets\/\" target=\"_blank\" rel=\"noopener noreferrer\">il plugin gratuito Code Snippets<\/a> permette di organizzare tutto in modo molto semplice perch\u00e9 \u00e8 possibile aggiungere ogni snippet di codice separatamente, con tanto di titolo e descrizione. Potete anche utilizzare dei tag per organizzare gli snippet.<\/p>\n\n<h2>Riepilogo<\/h2>\n<p>Il file functions.php di WordPress \u00e8 un file specifico per ogni tema che permette di aggiungere snippet di codice PHP al sito web.<\/p>\n<p>Per aggiungere degli snippet di codice al file functions.php, si dovrebbe sempre utilizzare un child theme in modo che le modifiche non vengano sovrascritte quando si aggiorna il tema. Vi consigliamo inoltre di eseguire un backup del sito prima di aggiungere gli snippet e di testarli su un sito di staging quando possibile.<\/p>\n<p>In alternativa all&#8217;uso del file functions.php, si pu\u00f2 anche prendere in considerazione l&#8217;idea di usare un plugin esistente per la gestione del codice, oppure creare un plugin personalizzato per ospitare gli snippet.<\/p>\n<p>Ora che sapete come funziona il file functions.php di WordPress, potete iniziare a personalizzare il vostro sito in tanti modi utili.<\/p>\n<p>Gli esempi di snippet functions.php riportati qui sopra offrono alcuni buoni punti di partenza, ma non c&#8217;\u00e8 davvero alcun limite a quello che si pu\u00f2 realizzare.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sapete cos&#8217;\u00e8 il file functions.php di WordPress o come usarlo? In poche parole, il file functions.php di WordPress permette di aggiungere snippet di codice al sito. &#8230;<\/p>\n","protected":false},"author":199,"featured_media":67806,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_kinsta_gated_content":false,"_kinsta_gated_content_redirect":"","footnotes":""},"tags":[],"topic":[25873],"class_list":["post-67805","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","topic-sviluppo-wordpress"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.6 (Yoast SEO v24.6) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Il File functions.php di WordPress: la Guida Definitiva e Utili Snippet di Codice - Kinsta\u00ae<\/title>\n<meta name=\"description\" content=\"Scopri tutto quello che c&#039;\u00e8 da sapere sul file functions.php di WordPress e come usarlo, con 17 snippet di codice pronti per l&#039;uso.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/kimgsta.com\/it\/blog\/wordpress-functions-php\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Il File functions.php di WordPress: Guida Definitiva e Utili Snippet di Codice\" \/>\n<meta property=\"og:description\" content=\"Scopri tutto quello che c&#039;\u00e8 da sapere sul file functions.php di WordPress e come usarlo, con 17 snippet di codice pronti per l&#039;uso.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kimgsta.com\/it\/blog\/wordpress-functions-php\/\" \/>\n<meta property=\"og:site_name\" content=\"Kinsta\u00ae\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/kinstaitalia\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-04-05T07:50:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-04-14T13:39:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/kimgsta.com\/it\/wp-content\/uploads\/sites\/2\/2023\/04\/wordpress-functions-php.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"3042\" \/>\n\t<meta property=\"og:image:height\" content=\"1521\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jeremy Holcombe\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:description\" content=\"Scopri tutto quello che c&#039;\u00e8 da sapere sul file functions.php di WordPress e come usarlo, con 17 snippet di codice pronti per l&#039;uso.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/kimgsta.com\/it\/wp-content\/uploads\/sites\/2\/2023\/04\/wordpress-functions-php.jpg\" \/>\n<meta name=\"twitter:creator\" content=\"@Kinsta_IT\" \/>\n<meta name=\"twitter:site\" content=\"@Kinsta_IT\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jeremy Holcombe\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"20 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/kimgsta.com\/it\/blog\/wordpress-functions-php\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/kimgsta.com\/it\/blog\/wordpress-functions-php\/\"},\"author\":{\"name\":\"Jeremy Holcombe\",\"@id\":\"https:\/\/kimgsta.com\/it\/#\/schema\/person\/4eee42881d7b5a73ebb4f58dd5223b21\"},\"headline\":\"Il File functions.php di WordPress: Guida Definitiva e Utili Snippet di Codice\",\"datePublished\":\"2023-04-05T07:50:24+00:00\",\"dateModified\":\"2023-04-14T13:39:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/kimgsta.com\/it\/blog\/wordpress-functions-php\/\"},\"wordCount\":3971,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/kimgsta.com\/it\/#organization\"},\"image\":{\"@id\":\"https:\/\/kimgsta.com\/it\/blog\/wordpress-functions-php\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/kimgsta.com\/it\/wp-content\/uploads\/sites\/2\/2023\/04\/wordpress-functions-php.jpg\",\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/kimgsta.com\/it\/blog\/wordpress-functions-php\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/kimgsta.com\/it\/blog\/wordpress-functions-php\/\",\"url\":\"https:\/\/kimgsta.com\/it\/blog\/wordpress-functions-php\/\",\"name\":\"Il File functions.php di WordPress: la Guida Definitiva e Utili Snippet di Codice - Kinsta\u00ae\",\"isPartOf\":{\"@id\":\"https:\/\/kimgsta.com\/it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/kimgsta.com\/it\/blog\/wordpress-functions-php\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/kimgsta.com\/it\/blog\/wordpress-functions-php\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/kimgsta.com\/it\/wp-content\/uploads\/sites\/2\/2023\/04\/wordpress-functions-php.jpg\",\"datePublished\":\"2023-04-05T07:50:24+00:00\",\"dateModified\":\"2023-04-14T13:39:59+00:00\",\"description\":\"Scopri tutto quello che c'\u00e8 da sapere sul file functions.php di WordPress e come usarlo, con 17 snippet di codice pronti per l'uso.\",\"breadcrumb\":{\"@id\":\"https:\/\/kimgsta.com\/it\/blog\/wordpress-functions-php\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/kimgsta.com\/it\/blog\/wordpress-functions-php\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/kimgsta.com\/it\/blog\/wordpress-functions-php\/#primaryimage\",\"url\":\"https:\/\/kimgsta.com\/it\/wp-content\/uploads\/sites\/2\/2023\/04\/wordpress-functions-php.jpg\",\"contentUrl\":\"https:\/\/kimgsta.com\/it\/wp-content\/uploads\/sites\/2\/2023\/04\/wordpress-functions-php.jpg\",\"width\":3042,\"height\":1521},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/kimgsta.com\/it\/blog\/wordpress-functions-php\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/kimgsta.com\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sviluppo di WordPress\",\"item\":\"https:\/\/kimgsta.com\/it\/argomenti\/sviluppo-wordpress\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Il File functions.php di WordPress: Guida Definitiva e Utili Snippet di Codice\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/kimgsta.com\/it\/#website\",\"url\":\"https:\/\/kimgsta.com\/it\/\",\"name\":\"Kinsta\u00ae\",\"description\":\"Soluzioni di hosting premium, veloci e sicure\",\"publisher\":{\"@id\":\"https:\/\/kimgsta.com\/it\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/kimgsta.com\/it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/kimgsta.com\/it\/#organization\",\"name\":\"Kinsta\",\"url\":\"https:\/\/kimgsta.com\/it\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/kimgsta.com\/it\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/kimgsta.com\/it\/wp-content\/uploads\/sites\/2\/2023\/12\/kinsta-logo.jpeg\",\"contentUrl\":\"https:\/\/kimgsta.com\/it\/wp-content\/uploads\/sites\/2\/2023\/12\/kinsta-logo.jpeg\",\"width\":500,\"height\":500,\"caption\":\"Kinsta\"},\"image\":{\"@id\":\"https:\/\/kimgsta.com\/it\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/kinstaitalia\/\",\"https:\/\/x.com\/Kinsta_IT\",\"https:\/\/www.instagram.com\/kinstahosting\/\",\"https:\/\/www.linkedin.com\/company\/kinsta\/\",\"https:\/\/www.pinterest.com\/kinstahosting\/\",\"https:\/\/www.youtube.com\/c\/Kinsta\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/kimgsta.com\/it\/#\/schema\/person\/4eee42881d7b5a73ebb4f58dd5223b21\",\"name\":\"Jeremy Holcombe\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/kimgsta.com\/it\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/0e17001f3bb37dbbe54fceef9bb547fa?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/0e17001f3bb37dbbe54fceef9bb547fa?s=96&d=mm&r=g\",\"caption\":\"Jeremy Holcombe\"},\"description\":\"Senior Editor at Kinsta, WordPress Web Developer, and Content Writer. Outside of all things WordPress, I enjoy the beach, golf, and movies. I also have tall people problems.\",\"sameAs\":[\"https:\/\/www.linkedin.com\/in\/jeremyholcombe\/\"],\"url\":\"https:\/\/kimgsta.com\/it\/blog\/author\/jeremyholcombe\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Il File functions.php di WordPress: la Guida Definitiva e Utili Snippet di Codice - Kinsta\u00ae","description":"Scopri tutto quello che c'\u00e8 da sapere sul file functions.php di WordPress e come usarlo, con 17 snippet di codice pronti per l'uso.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/kimgsta.com\/it\/blog\/wordpress-functions-php\/","og_locale":"it_IT","og_type":"article","og_title":"Il File functions.php di WordPress: Guida Definitiva e Utili Snippet di Codice","og_description":"Scopri tutto quello che c'\u00e8 da sapere sul file functions.php di WordPress e come usarlo, con 17 snippet di codice pronti per l'uso.","og_url":"https:\/\/kimgsta.com\/it\/blog\/wordpress-functions-php\/","og_site_name":"Kinsta\u00ae","article_publisher":"https:\/\/www.facebook.com\/kinstaitalia\/","article_published_time":"2023-04-05T07:50:24+00:00","article_modified_time":"2023-04-14T13:39:59+00:00","og_image":[{"width":3042,"height":1521,"url":"https:\/\/kimgsta.com\/it\/wp-content\/uploads\/sites\/2\/2023\/04\/wordpress-functions-php.jpg","type":"image\/jpeg"}],"author":"Jeremy Holcombe","twitter_card":"summary_large_image","twitter_description":"Scopri tutto quello che c'\u00e8 da sapere sul file functions.php di WordPress e come usarlo, con 17 snippet di codice pronti per l'uso.","twitter_image":"https:\/\/kimgsta.com\/it\/wp-content\/uploads\/sites\/2\/2023\/04\/wordpress-functions-php.jpg","twitter_creator":"@Kinsta_IT","twitter_site":"@Kinsta_IT","twitter_misc":{"Scritto da":"Jeremy Holcombe","Tempo di lettura stimato":"20 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/kimgsta.com\/it\/blog\/wordpress-functions-php\/#article","isPartOf":{"@id":"https:\/\/kimgsta.com\/it\/blog\/wordpress-functions-php\/"},"author":{"name":"Jeremy Holcombe","@id":"https:\/\/kimgsta.com\/it\/#\/schema\/person\/4eee42881d7b5a73ebb4f58dd5223b21"},"headline":"Il File functions.php di WordPress: Guida Definitiva e Utili Snippet di Codice","datePublished":"2023-04-05T07:50:24+00:00","dateModified":"2023-04-14T13:39:59+00:00","mainEntityOfPage":{"@id":"https:\/\/kimgsta.com\/it\/blog\/wordpress-functions-php\/"},"wordCount":3971,"commentCount":0,"publisher":{"@id":"https:\/\/kimgsta.com\/it\/#organization"},"image":{"@id":"https:\/\/kimgsta.com\/it\/blog\/wordpress-functions-php\/#primaryimage"},"thumbnailUrl":"https:\/\/kimgsta.com\/it\/wp-content\/uploads\/sites\/2\/2023\/04\/wordpress-functions-php.jpg","inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/kimgsta.com\/it\/blog\/wordpress-functions-php\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/kimgsta.com\/it\/blog\/wordpress-functions-php\/","url":"https:\/\/kimgsta.com\/it\/blog\/wordpress-functions-php\/","name":"Il File functions.php di WordPress: la Guida Definitiva e Utili Snippet di Codice - Kinsta\u00ae","isPartOf":{"@id":"https:\/\/kimgsta.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/kimgsta.com\/it\/blog\/wordpress-functions-php\/#primaryimage"},"image":{"@id":"https:\/\/kimgsta.com\/it\/blog\/wordpress-functions-php\/#primaryimage"},"thumbnailUrl":"https:\/\/kimgsta.com\/it\/wp-content\/uploads\/sites\/2\/2023\/04\/wordpress-functions-php.jpg","datePublished":"2023-04-05T07:50:24+00:00","dateModified":"2023-04-14T13:39:59+00:00","description":"Scopri tutto quello che c'\u00e8 da sapere sul file functions.php di WordPress e come usarlo, con 17 snippet di codice pronti per l'uso.","breadcrumb":{"@id":"https:\/\/kimgsta.com\/it\/blog\/wordpress-functions-php\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/kimgsta.com\/it\/blog\/wordpress-functions-php\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/kimgsta.com\/it\/blog\/wordpress-functions-php\/#primaryimage","url":"https:\/\/kimgsta.com\/it\/wp-content\/uploads\/sites\/2\/2023\/04\/wordpress-functions-php.jpg","contentUrl":"https:\/\/kimgsta.com\/it\/wp-content\/uploads\/sites\/2\/2023\/04\/wordpress-functions-php.jpg","width":3042,"height":1521},{"@type":"BreadcrumbList","@id":"https:\/\/kimgsta.com\/it\/blog\/wordpress-functions-php\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/kimgsta.com\/it\/"},{"@type":"ListItem","position":2,"name":"Sviluppo di WordPress","item":"https:\/\/kimgsta.com\/it\/argomenti\/sviluppo-wordpress\/"},{"@type":"ListItem","position":3,"name":"Il File functions.php di WordPress: Guida Definitiva e Utili Snippet di Codice"}]},{"@type":"WebSite","@id":"https:\/\/kimgsta.com\/it\/#website","url":"https:\/\/kimgsta.com\/it\/","name":"Kinsta\u00ae","description":"Soluzioni di hosting premium, veloci e sicure","publisher":{"@id":"https:\/\/kimgsta.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/kimgsta.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/kimgsta.com\/it\/#organization","name":"Kinsta","url":"https:\/\/kimgsta.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/kimgsta.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/kimgsta.com\/it\/wp-content\/uploads\/sites\/2\/2023\/12\/kinsta-logo.jpeg","contentUrl":"https:\/\/kimgsta.com\/it\/wp-content\/uploads\/sites\/2\/2023\/12\/kinsta-logo.jpeg","width":500,"height":500,"caption":"Kinsta"},"image":{"@id":"https:\/\/kimgsta.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/kinstaitalia\/","https:\/\/x.com\/Kinsta_IT","https:\/\/www.instagram.com\/kinstahosting\/","https:\/\/www.linkedin.com\/company\/kinsta\/","https:\/\/www.pinterest.com\/kinstahosting\/","https:\/\/www.youtube.com\/c\/Kinsta"]},{"@type":"Person","@id":"https:\/\/kimgsta.com\/it\/#\/schema\/person\/4eee42881d7b5a73ebb4f58dd5223b21","name":"Jeremy Holcombe","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/kimgsta.com\/it\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/0e17001f3bb37dbbe54fceef9bb547fa?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0e17001f3bb37dbbe54fceef9bb547fa?s=96&d=mm&r=g","caption":"Jeremy Holcombe"},"description":"Senior Editor at Kinsta, WordPress Web Developer, and Content Writer. Outside of all things WordPress, I enjoy the beach, golf, and movies. I also have tall people problems.","sameAs":["https:\/\/www.linkedin.com\/in\/jeremyholcombe\/"],"url":"https:\/\/kimgsta.com\/it\/blog\/author\/jeremyholcombe\/"}]}},"acf":[],"_links":{"self":[{"href":"https:\/\/kimgsta.com\/it\/wp-json\/wp\/v2\/posts\/67805","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kimgsta.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/kimgsta.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/kimgsta.com\/it\/wp-json\/wp\/v2\/users\/199"}],"replies":[{"embeddable":true,"href":"https:\/\/kimgsta.com\/it\/wp-json\/wp\/v2\/comments?post=67805"}],"version-history":[{"count":14,"href":"https:\/\/kimgsta.com\/it\/wp-json\/wp\/v2\/posts\/67805\/revisions"}],"predecessor-version":[{"id":68048,"href":"https:\/\/kimgsta.com\/it\/wp-json\/wp\/v2\/posts\/67805\/revisions\/68048"}],"alternate":[{"embeddable":true,"hreflang":"en","title":"English","href":"https:\/\/kimgsta.com\/it\/wp-json\/kinsta\/v1\/posts\/67805\/translations\/en"},{"embeddable":true,"hreflang":"it","title":"Italian","href":"https:\/\/kimgsta.com\/it\/wp-json\/kinsta\/v1\/posts\/67805\/translations\/it"},{"embeddable":true,"hreflang":"pt","title":"Portuguese","href":"https:\/\/kimgsta.com\/it\/wp-json\/kinsta\/v1\/posts\/67805\/translations\/pt"},{"embeddable":true,"hreflang":"fr","title":"French","href":"https:\/\/kimgsta.com\/it\/wp-json\/kinsta\/v1\/posts\/67805\/translations\/fr"},{"embeddable":true,"hreflang":"de","title":"German","href":"https:\/\/kimgsta.com\/it\/wp-json\/kinsta\/v1\/posts\/67805\/translations\/de"},{"embeddable":true,"hreflang":"ja","title":"Japanese","href":"https:\/\/kimgsta.com\/it\/wp-json\/kinsta\/v1\/posts\/67805\/translations\/jp"},{"embeddable":true,"hreflang":"nl","title":"Dutch","href":"https:\/\/kimgsta.com\/it\/wp-json\/kinsta\/v1\/posts\/67805\/translations\/nl"},{"embeddable":true,"hreflang":"es","title":"Spanish","href":"https:\/\/kimgsta.com\/it\/wp-json\/kinsta\/v1\/posts\/67805\/translations\/es"},{"embeddable":true,"hreflang":"sv","title":null,"href":"https:\/\/kimgsta.com\/it\/wp-json\/kinsta\/v1\/posts\/67805\/translations\/se"},{"embeddable":true,"hreflang":"da","title":null,"href":"https:\/\/kimgsta.com\/it\/wp-json\/kinsta\/v1\/posts\/67805\/translations\/dk"},{"href":"https:\/\/kimgsta.com\/it\/wp-json\/kinsta\/v1\/posts\/67805\/tree"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/kimgsta.com\/it\/wp-json\/wp\/v2\/media\/67806"}],"wp:attachment":[{"href":"https:\/\/kimgsta.com\/it\/wp-json\/wp\/v2\/media?parent=67805"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/kimgsta.com\/it\/wp-json\/wp\/v2\/tags?post=67805"},{"taxonomy":"topic","embeddable":true,"href":"https:\/\/kimgsta.com\/it\/wp-json\/wp\/v2\/topic?post=67805"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}