{"id":29932,"date":"2019-11-26T04:49:05","date_gmt":"2019-11-26T12:49:05","guid":{"rendered":"https:\/\/kimgsta.com\/?post_type=knowledgebase&#038;p=10028"},"modified":"2025-10-01T20:52:32","modified_gmt":"2025-10-01T19:52:32","slug":"clonare-sito-wordpress","status":"publish","type":"post","link":"https:\/\/kimgsta.com\/it\/blog\/clonare-sito-wordpress\/","title":{"rendered":"Come clonare facilmente un sito WordPress"},"content":{"rendered":"<p>Ci sono molte ragioni per cui potreste voler clonare il vostro sito WordPress. Forse state lanciando un secondo sito e volete usare il primo come modello di base per risparmiare tempo. O forse avete bisogno di una replica esatta come backup o per fare prove di sviluppo, oltre al tipico <a href=\"https:\/\/kimgsta.com\/it\/docs\/hosting-wordpress\/ambienti-di-staging\/\" target=\"_blank\" rel=\"noopener noreferrer\">ambiente di staging<\/a>.<\/p>\n<p>Qualunque siano le vostre motivazioni, con Kinsta \u00e8 davvero un gioco da ragazzi. Seguite i passaggi qui sotto e scoprite come clonare un sito WordPress in pochi clic!<\/p>\n<div><\/div><kinsta-auto-toc heading=\"Table of Contents\" exclude=\"last\" list-style=\"arrow\" selector=\"h2\" count-number=\"-1\"><\/kinsta-auto-toc>\n<h2>Clonare un sito WordPress in MyKinsta<\/h2>\n<p>La funzione di clonazione di Kinsta copia l&#8217;intero <a href=\"https:\/\/kimgsta.com\/it\/blog\/database-wordpress\/\" target=\"_blank\" rel=\"noopener noreferrer\">database WordPress<\/a>, inclusi tutti i contenuti e i file. Nuove credenziali di accesso, come SFTP, SSH, SSH, nome utente e password del database vengono generate automaticamente per il nuovo sito clonato e saranno accessibili dalla bacheca.<\/p>\n<h3>Passo 1<\/h3>\n<p>Sfogliate i siti nella dashboard <a href=\"https:\/\/my.kimgsta.com\/?lang=it\" target=\"_blank\" rel=\"noopener noreferrer\">MyKinsta<\/a> e cliccate su &#8220;Aggiungi sito&#8221; in alto a destra.<\/p>\n<figure id=\"attachment_56714\" aria-describedby=\"caption-attachment-56714\" style=\"width: 2446px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-56714\" src=\"https:\/\/kimgsta.com\/it\/wp-content\/uploads\/sites\/2\/2019\/11\/mykinsta-add-site-option-3.png\" alt=\"Aggiungere un sito su MyKinsta.\" width=\"2446\" height=\"1426\" srcset=\"https:\/\/kimgsta.com\/it\/wp-content\/uploads\/sites\/2\/2019\/11\/mykinsta-add-site-option-3.png 2446w, https:\/\/kimgsta.com\/it\/wp-content\/uploads\/sites\/2\/2019\/11\/mykinsta-add-site-option-3-300x175.png 300w, https:\/\/kimgsta.com\/it\/wp-content\/uploads\/sites\/2\/2019\/11\/mykinsta-add-site-option-3-1024x597.png 1024w, https:\/\/kimgsta.com\/it\/wp-content\/uploads\/sites\/2\/2019\/11\/mykinsta-add-site-option-3-768x448.png 768w, https:\/\/kimgsta.com\/it\/wp-content\/uploads\/sites\/2\/2019\/11\/mykinsta-add-site-option-3-1536x895.png 1536w, https:\/\/kimgsta.com\/it\/wp-content\/uploads\/sites\/2\/2019\/11\/mykinsta-add-site-option-3-2048x1194.png 2048w\" sizes=\"auto, (max-width: 2446px) 100vw, 2446px\" \/><figcaption id=\"caption-attachment-56714\" class=\"wp-caption-text\">Aggiungere di un sito su MyKinsta.<\/figcaption><\/figure>\n<h3>Passo 2<\/h3>\n<p>Selezionate l&#8217;opzione &#8220;Clona un ambiente esistente&#8221; e scegliete un sito da clonare. Assicuratevi di specificare se clonare l&#8217;ambiente live o quello di staging.<\/p>\n<figure id=\"attachment_56716\" aria-describedby=\"caption-attachment-56716\" style=\"width: 1572px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-56716\" src=\"https:\/\/kimgsta.com\/it\/wp-content\/uploads\/sites\/2\/2019\/11\/mykinsta-clone-existing-environment-1.png\" alt=\"Clonazione di un ambiente esistente.\" width=\"1572\" height=\"584\" srcset=\"https:\/\/kimgsta.com\/it\/wp-content\/uploads\/sites\/2\/2019\/11\/mykinsta-clone-existing-environment-1.png 1572w, https:\/\/kimgsta.com\/it\/wp-content\/uploads\/sites\/2\/2019\/11\/mykinsta-clone-existing-environment-1-300x111.png 300w, https:\/\/kimgsta.com\/it\/wp-content\/uploads\/sites\/2\/2019\/11\/mykinsta-clone-existing-environment-1-1024x380.png 1024w, https:\/\/kimgsta.com\/it\/wp-content\/uploads\/sites\/2\/2019\/11\/mykinsta-clone-existing-environment-1-768x285.png 768w, https:\/\/kimgsta.com\/it\/wp-content\/uploads\/sites\/2\/2019\/11\/mykinsta-clone-existing-environment-1-1536x571.png 1536w\" sizes=\"auto, (max-width: 1572px) 100vw, 1572px\" \/><figcaption id=\"caption-attachment-56716\" class=\"wp-caption-text\">Clonazione di un ambiente esistente.<\/figcaption><\/figure>\n<p>Se avete gi\u00e0 un nome di dominio in mente, potrete inserirlo in questo momento. Altrimenti, il sito verr\u00e0 clonato con un dominio kinsta.cloud. Infine, inserite un nome per il sito clonato. Da notare: la localit\u00e0 non pu\u00f2 essere modificata durante il processo di clonazione. Se desiderate che il sito clonato venga posizionato in una localit\u00e0 diversa, contattate il nostro team di supporto per spostare il sito al termine del processo di clonazione.<\/p>\n<figure id=\"attachment_128267\" aria-describedby=\"caption-attachment-128267\" style=\"width: 1200px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-128267 size-full\" src=\"https:\/\/kimgsta.com\/wp-content\/uploads\/2017\/10\/add-site.png\" alt=\"Scegliere l'ambiente da clonare e aggiungere il sito\" width=\"1200\" height=\"764\"><figcaption id=\"caption-attachment-128267\" class=\"wp-caption-text\">Scegliere l&#8217;ambiente da clonare e aggiungere il sito<\/figcaption><\/figure>\n<p>E questo \u00e8 tutto!\u00a0Il processo di clonazione richiede in genere da 10 a 20 minuti a seconda delle dimensioni del sito WordPress e del database. Apparir\u00e0 quindi nell&#8217;elenco dei siti nel vostro cruscotto MyKinsta. Nota: se il processo di clonazione richiede pi\u00f9 di un&#8217;ora, si consiglia di contattare il nostro team di supporto.<\/p>\n<figure id=\"attachment_56720\" aria-describedby=\"caption-attachment-56720\" style=\"width: 2712px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-56720\" src=\"https:\/\/kimgsta.com\/it\/wp-content\/uploads\/sites\/2\/2019\/11\/mykinsta-cloned-site-3.png\" alt=\"Un sito clonato su MyKinsta.\" width=\"2712\" height=\"882\" srcset=\"https:\/\/kimgsta.com\/it\/wp-content\/uploads\/sites\/2\/2019\/11\/mykinsta-cloned-site-3.png 2712w, https:\/\/kimgsta.com\/it\/wp-content\/uploads\/sites\/2\/2019\/11\/mykinsta-cloned-site-3-300x98.png 300w, https:\/\/kimgsta.com\/it\/wp-content\/uploads\/sites\/2\/2019\/11\/mykinsta-cloned-site-3-1024x333.png 1024w, https:\/\/kimgsta.com\/it\/wp-content\/uploads\/sites\/2\/2019\/11\/mykinsta-cloned-site-3-768x250.png 768w, https:\/\/kimgsta.com\/it\/wp-content\/uploads\/sites\/2\/2019\/11\/mykinsta-cloned-site-3-1536x500.png 1536w, https:\/\/kimgsta.com\/it\/wp-content\/uploads\/sites\/2\/2019\/11\/mykinsta-cloned-site-3-2048x666.png 2048w\" sizes=\"auto, (max-width: 2712px) 100vw, 2712px\" \/><figcaption id=\"caption-attachment-56720\" class=\"wp-caption-text\">Un sito clonato su MyKinsta.<\/figcaption><\/figure>\n<h3>Dopo la clonazione del sito WordPress<\/h3>\n<p>Se non avete inserito un dominio personalizzato durante il processo di clonazione, allora gli verr\u00e0 automaticamente assegnato un <a href=\"https:\/\/kimgsta.com\/it\/docs\/hosting-wordpress\/wordpress-domini\/url-temporaneo-wordpress\/\" target=\"_blank\" rel=\"noopener noreferrer\">URL temporaneo<\/a> per potervi accedere, come <strong>myclone.kinsta.cloud<\/strong>.\u00a0Se si dispone di un altro dominio che si desidera utilizzare, \u00e8 possibile fare clic sulla sezione &#8220;Domini&#8221; e aggiungerlo.<\/p>\n<p>Sar\u00e0 quindi necessario <a href=\"https:\/\/kimgsta.com\/it\/docs\/hosting-wordpress\/wordpress-domini\/url-temporaneo-wordpress\/#fix-site-redirecting-to-sitenamekinstacloud\" target=\"_blank\" rel=\"noopener noreferrer\">aggiornare l&#8217;indirizzo WordPress URL e l&#8217;indirizzo del sito URL<\/a>. E se avete aggiunto i vostri indirizzi URL tramite hardcode nel file <code>wp-config.php<\/code>, anche questo dovr\u00e0 essere aggiornato.<\/p>\n<p>Dopo aver assegnato un dominio personalizzato al sito, <a href=\"https:\/\/kimgsta.com\/it\/docs\/hosting-wordpress\/wordpress-domini\/certificati-ssl-wordpress\/\">potete generare un certificato SSL gratuito<\/a> e <a href=\"https:\/\/kimgsta.com\/it\/docs\/hosting-wordpress\/wordpress-cdn\/kinsta-cdn\/\">distribuire Kinsta CDN<\/a> in MyKinsta. Per ulteriori informazioni su come andare live con un sito su Kinsta, consultate <a href=\"https:\/\/kimgsta.com\/it\/docs\/hosting-wordpress\/wordpress-cdn\/kinsta-cdn\/\">questo articolo<\/a>.<\/p>\n<h3>Note aggiuntive<\/h3>\n<ul style=\"margin-left: 30px\">\n<li>Se avete dei plugin CDN abilitati o plugin di terze parti con URL codificati, assicuratevi di aggiornarli per riflettere il nuovo indirizzo del sito. In caso contrario, il contenuto potrebbe apparire danneggiato, mentre in realt\u00e0 \u00e8 semplicemente puntato a un indirizzo errato.<\/li>\n<li>A differenza dei siti di staging, i siti WordPress clonati sono completamente separati, il che significa che contano sul numero totale di siti consentiti dal piano e saranno fatturati per l&#8217;utilizzo della larghezza di banda. Ci\u00f2 significa anche che la funzione di clonazione \u00e8 disponibile solo per piani WP 2 o superiori (che permettono di avere pi\u00f9 di un sito).<\/li>\n<li>Se utilizzate plugin di programmazione social come CoSchedule o Social Networks Auto Poster, ricordate che potrebbero iniziare a condividere il contenuto del vostro sito clonato. Quindi assicuratevi di aggiornare i vostri indirizzi URL o disattivare questi plugin, altrimenti questo potrebbe falsare le vostre statistiche.<\/li>\n<\/ul>\n<aside role=\"note\" class=\"wp-block-kinsta-notice is-style-info\">\n            <h3>Info<\/h3>\n        <p>Si noti che gli ambienti di staging e premium non vengono clonati.<\/p>\n<\/aside>\n\n<h2>Clonare il proprio sito WordPress con l\u2019API di Kinsta<\/h2>\n<p>Con l&#8217;<a href=\"https:\/\/kimgsta.com\/it\/docs\/kinsta-api\/\">API di Kinsta<\/a>, \u00e8 possibile clonare programmaticamente l&#8217;intero <a href=\"https:\/\/kimgsta.com\/it\/blog\/database-wordpress\/\">database WordPress<\/a>, inclusi i contenuti e i file. Ci\u00f2 significa che \u00e8 possibile eseguire tutte le azioni offerte da MyKinsta attraverso l&#8217;API di Kinsta.<\/p>\n<p>Per avviare il processo di clonazione con l&#8217;API di Kinsta, sono necessarie le seguenti informazioni:<\/p>\n<ul>\n<li>Una chiave API<\/li>\n<li>L&#8217;ID dell\u2019azienda, e<\/li>\n<li>L&#8217;ID dell&#8217;ambiente del sito che si desidera clonare<\/li>\n<\/ul>\n<p>Esaminiamo i passaggi per clonare un sito WordPress esistente con Kinsta API:<\/p>\n<h3>Fase 1: generare una chiave API<\/h3>\n<p>Per utilizzare l&#8217;API di Kinsta, \u00e8 necessario generare una chiave API. Questa viene utilizzata per autenticarsi e accedere al proprio account. Ecco come generare una chiave API:<\/p>\n<ol start=\"1\">\n<li>Accedere al cruscotto <a href=\"https:\/\/my.kimgsta.com\/?lang=it\">MyKinsta<\/a>.<\/li>\n<li>Accedere alla pagina\u00a0<strong>Chiavi API<\/strong> cliccando sul\u00a0proprio nome, poi selezionare <strong>Impostazioni Azienda<\/strong> e infine <strong>Chiavi API<\/strong>.<\/li>\n<li>Fare clic sul pulsante\u00a0<strong>Crea chiave API<\/strong>.<\/li>\n<li>Scegliere una data di scadenza o impostare una data di inizio personalizzata e specificare il numero di ore di validit\u00e0 della chiave.<\/li>\n<li>Assegnare alla chiave un nome univoco e descrittivo.<\/li>\n<li>Cliccare su\u00a0<strong>Genera<\/strong>\u00a0per creare la chiave API.<\/li>\n<\/ol>\n<figure style=\"width: 1600px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/kimgsta.com\/wp-content\/uploads\/2023\/07\/create-api-key-on-mykinsta.jpg\" alt=\"Creare una chiave API in MyKinsta.\" width=\"1600\" height=\"225\"><figcaption class=\"wp-caption-text\">Creare una chiave API in MyKinsta.<\/figcaption><\/figure>\n<p>Quando create una chiave API, copiatela e conservatela in un luogo sicuro, poich\u00e9\u00a0<strong>questo \u00e8 l&#8217;unico momento in cui \u00e8 possibile visualizzarla<\/strong>. \u00c8 possibile generare pi\u00f9 chiavi API, che saranno elencate nella pagina\u00a0<strong>Chiavi API<\/strong>. Per revocare una chiave API, fate clic su\u00a0<strong>Revoca<\/strong>\u00a0accanto a quella che desiderate revocare.<\/p>\n<h3>Fase 2: copiare l&#8217;ID dell\u2019Azienda<\/h3>\n<p>L&#8217;ID dell&#8217;azienda si trova in MyKinsta in\u00a0<strong>Azienda<\/strong>\u00a0&gt;\u00a0<strong>Dati Fatturazione<\/strong>\u00a0&gt;\u00a0<strong>ID<\/strong>.<\/p>\n<figure style=\"width: 1600px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/kimgsta.com\/wp-content\/uploads\/2023\/07\/copy-company-id.jpg\" alt=\"Copiare l'ID dell\u2019Azienda.\" width=\"1600\" height=\"225\"><figcaption class=\"wp-caption-text\">Copiare l&#8217;ID dell\u2019Azienda.<\/figcaption><\/figure>\n<h3>Fase 3: ricavare l&#8217;ID ambiente del sito che si vuole clonare<\/h3>\n<p>Esistono due metodi per ottenere l&#8217;ID ambiente di un sito: recupero manuale dall&#8217;<a href=\"https:\/\/kimgsta.com\/it\/blog\/cosa-e-un-url\/\">URL<\/a> o programmatico tramite una richiesta API<\/p>\n<p>Per recuperare manualmente l&#8217;ID ambiente, \u00e8 possibile aprire il sito su MyKinsta e copiare le informazioni dell&#8217;ID ambiente come indicato di seguito:<\/p>\n<figure style=\"width: 1999px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/kimgsta.com\/wp-content\/uploads\/2023\/07\/get-the-site-environment-id.jpg\" alt=\"Ottenere manualmente l'ID ambiente del sito\" width=\"1999\" height=\"551\"><figcaption class=\"wp-caption-text\">Ottenere manualmente l&#8217;ID ambiente del sito<\/figcaption><\/figure>\n<p>In alternativa, \u00e8 possibile recuperare programmaticamente l&#8217;ID dell&#8217;ambiente utilizzando l&#8217;API di Kinsta. Ci\u00f2 consiste nel recuperare un elenco di tutti i siti utilizzando l&#8217;endpoint <code>\/sites<\/code>. Ecco un esempio in cui si utilizza il metodo <a href=\"https:\/\/kimgsta.com\/it\/blog\/richieste-http-javascript\/#4-how-to-make-an-http-request-in-javascript-using-the-fetch-api\">JavaScript Fetch API<\/a>:<\/p>\n<pre><code class=\"language-js\">const fetchAllSites = async () =&gt; {\n  const query = new URLSearchParams({\n    company: \"YOUR_COMPANY_ID\"\n  }).toString();\n\n  const resp = await fetch(`https:\/\/api.kimgsta.com\/v2\/sites?${query}`, {\n    method: \"GET\",\n    headers: {\n      Authorization: \"Bearer &lt;YOUR_TOKEN_HERE&gt;\"\n    }\n  });\n\n  const data = await resp.json();\n  console.log(data);\n};\n\nfetchAllSites();<\/code><\/pre>\n<p>Nel codice precedente, viene definita una funzione asincrona denominata <code>fetchAllSites<\/code>. Esegue una richiesta GET all&#8217;endpoint <code>\/sites<\/code> con l&#8217;ID dell\u2019azienda specificato. Assicuratevi di aggiungere il token API per gestire l&#8217;autorizzazione. I dati della risposta vengono quindi registrati nella console.<\/p>\n<aside role=\"note\" class=\"wp-block-kinsta-notice is-style-info\">\n            <h3>Info<\/h3>\n        <p>Questo \u00e8 un esempio di utilizzo dell&#8217;API Kinsta in JavaScript; la <a href=\"https:\/\/api-docs.kimgsta.com\/\">documentazione dell&#8217;API di Kinsta<\/a> fornisce esempi pi\u00f9 completi e dettagli su come effettuare richieste API.<\/p>\n<\/aside>\n\n<p>Dopo aver recuperato tutti i siti, riceverete un array di oggetti, dove ogni oggetto rappresenta un sito e contiene dettagli come ID, nome, stato ed etichette del sito. Ecco un esempio della struttura JSON:<\/p>\n<pre><code class=\"language-json\">{\n    \"company\": {\n        \"sites\": [\n            {\n                \"id\": \"YOUR_SITE_ID\",\n                \"name\": \"my-test-site\",\n                \"display_name\": \"Test site\",\n                \"status\": \"live\",\n                \"site_labels\": []\n            }\n        ]\n    }\n}<\/code><\/pre>\n<p>Per ottenere programmaticamente l&#8217;ID ambiente di un sito specifico utilizzando l&#8217;API di Kinsta, copiare l&#8217;ID del sito che si desidera clonare. Quindi, utilizzare tale ID per recuperare gli ambienti associati a quel sito.<\/p>\n<p>Ecco un esempio che dimostra come recuperare l&#8217;ID dell&#8217;ambiente:<\/p>\n<pre><code class=\"language-js\">const fetchEnvironmentId = async () =&gt; {\n  const siteId = \"YOUR_site_id\";\n  const resp = await fetch(\n    `https:\/\/api.kimgsta.com\/v2\/sites\/${siteId}\/environments`,\n    {\n      method: \"GET\",\n      headers: {\n        Authorization: \"Bearer &lt;YOUR_TOKEN_HERE&gt;\"\n      }\n    }\n  );\n\n  const data = await resp.json();\n  console.log(data);\n};\n\nfetchEnvironmentId();<\/code><\/pre>\n<p>Assicuratevi di sostituire &#8220;<code>YOUR_SITE_ID<\/code>&#8221; con l&#8217;effettivo ID del sito che volete clonare e <code>&lt;YOUR_TOKEN_HERE&gt;<\/code> con la chiave API di Kinsta.<\/p>\n<p>Quando la funzione <code>fetchEnvironmentId<\/code> viene eseguita, la risposta conterr\u00e0 i dettagli dell&#8217;ambiente del sito, compreso l&#8217;ID dell&#8217;ambiente. Ecco un esempio di risposta:<\/p>\n<pre><code class=\"language-json\">{\n    \"site\": {\n        \"environments\": [\n            {\n                \"id\": \"54fb80af-576c-4fdc-ba4f-b596c83f15a1\",\n                \"name\": \"first-site\",\n                \"display_name\": \"First site\",\n                \"is_blocked\": false,\n                \"id_edge_cache\": \"54fb80af-576c-4fdc-ba4f-b596c83f15a1\",\n                \"is_premium\": false,\n                \"domains\": [],\n                \"primaryDomain\": {},\n                \"ssh_connection\": {}\n            }\n        ]\n    }\n}<\/code><\/pre>\n<h3>Fase 4: clonare un sito esistente con Kinsta API<\/h3>\n<p>A questo punto, avrete tutti i requisiti necessari per clonare un sito con l&#8217;API di KInsta. Procedete all&#8217;invio di una richiesta API POST all\u2019endpoint <a href=\"https:\/\/api-docs.kimgsta.com\/tag\/WordPress-Sites#operation\/cloneWordPressSite\"><code>\/sites\/clone<\/code><\/a> passando i seguenti dati come payload:<\/p>\n<ul>\n<li>Il nome visualizzato del sito<\/li>\n<li>L&#8217;ID dell&#8217;azienda<\/li>\n<li>L&#8217;ID dell&#8217;ambiente del sito che si desidera clonare<\/li>\n<\/ul>\n<p>Ecco come apparir\u00e0 la richiesta API:<\/p>\n<pre><code class=\"language-js\">const cloneExistingSite = async () =&gt; {\n  const resp = await fetch(`https:\/\/api.kimgsta.com\/v2\/sites\/clone`, {\n    method: \"POST\",\n    headers: {\n      \"Content-Type\": \"application\/json\",\n      Authorization: \"Bearer &lt;YOUR_TOKEN_HERE&gt;\"\n    },\n    body: JSON.stringify({\n      company: \"COMPANY_ID\",\n      display_name: \"Copy of First WP Site\",\n      source_env_id: \"ENVIRONMENT_ID\"\n    })\n  });\n\n  const data = await resp.json();\n  console.log(data);\n};\n\ncloneExistingSite();<\/code><\/pre>\n<p>Nel codice qui sopra, la funzione <code>cloneExistingSite<\/code> invia una richiesta POST all\u2019endpoint <code>\/sites\/clone<\/code>. La richiesta include gli <code>headers<\/code> necessari, come il tipo di contenuto e il token API per l&#8217;autorizzazione. Il corpo della richiesta contiene i dati richiesti, come l&#8217;ID della societ\u00e0, il nome visualizzato per il nuovo sito e l&#8217;ID dell&#8217;ambiente di origine del sito che si desidera clonare.<\/p>\n<p>La risposta dell&#8217;API viene quindi registrata nella console e mostra che l&#8217;operazione di clonazione del sito \u00e8 in corso:<\/p>\n<pre><code class=\"language-json\">{\n  \"operation_id\": \"site:clone-54fb80af-576c-4fdc-ba4f-b596c83f15a1\",\n  \"message\": \"Cloning site in progress\",\n  \"status\": 202\n}<\/code><\/pre>\n<p>\u00c8 possibile usare l\u2019endpoint <a href=\"https:\/\/api-docs.kimgsta.com\/tag\/Operations\"><code>\/operations<\/code><\/a> per monitorare lo stato di un&#8217;operazione e sapere quando un&#8217;operazione come questa \u00e8 stata completata.<\/p>\n<h2>Clonare un sito WordPress con un plugin<\/h2>\n<p>Se il vostro fornitore di hosting, a differenza di Kinsta, non d\u00e0 la possibilit\u00e0 di clonare facilmente un sito dal cruscotto di hosting, sar\u00e0 necessario utilizzare un plugin per farlo.<\/p>\n<p>Il plugin <a href=\"https:\/\/wordpress.org\/plugins\/duplicator\/\" target=\"_blank\" rel=\"noopener noreferrer\">Duplicator<\/a> consente di creare un duplicato del proprio sito da poter utilizzare per creare un nuovo sito. Ecco come fare.<\/p>\n<aside role=\"note\" class=\"wp-block-kinsta-notice is-style-info\">\n            <h3>Info<\/h3>\n        <p>I passaggi che seguono funzionano con la versione gratuita di Duplicator, linkata sopra. Tuttavia, Duplicator Pro fa parte del nostro elenco di <a href=\"https:\/\/kimgsta.com\/it\/docs\/hosting-wordpress\/temi-plugin-wordpress\/\">plugin vietati e incompatibili<\/a>, quindi la versione pro non funzioner\u00e0.<\/p>\n<\/aside>\n\n<h3>Creare un duplicato del sito<\/h3>\n<p>Andate su <strong>Duplicator<\/strong> nel menu di amministrazione e cliccate sul pulsante <strong>Create new<\/strong>. Questo creer\u00e0 un &#8220;pacchetto&#8221; che conterr\u00e0 un duplicato del sito.<\/p>\n<figure style=\"width: 1265px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/kimgsta.com\/it\/wp-content\/uploads\/sites\/2\/2017\/03\/pllugin-duplicator.jpg\" alt=\"Pagina di configurazione del plugin Duplicator\" width=\"1265\" height=\"609\"><figcaption class=\"wp-caption-text\">Pagina di configurazione del plugin Duplicator<\/figcaption><\/figure>\n<p>Nella schermata <strong>Setup<\/strong>, specificate quali file e quali tabelle del database volete duplicare, oppure lasciate tutto al valore predefinito, che includer\u00e0 tutte le tabelle e i file del database. Apportate modifiche nella sezione <strong>Installer<\/strong> se volete personalizzare la nuova installazione o lasciarla alle impostazioni predefinite. Fate clic sul pulsante <strong>Next<\/strong>.<\/p>\n<p>Il plugin eseguir\u00e0 la scansione del sito e fornir\u00e0 eventuali avvisi prima di effettuare la duplicazione. Se ci sono problemi, prendetevi il tempo di risolverli ora. Se c&#8217;\u00e8 un avviso, \u00e8 necessario selezionare la casella di controllo sotto l&#8217;elenco degli elementi di scansione prima di procedere.<\/p>\n<p>Fate clic sul pulsante <strong>Build<\/strong> per continuare. Il plugin costruir\u00e0 il &#8220;pacchetto&#8221; che contiene tutto nel sito: temi, plugin, uploads, e anche WordPress stesso. Scaricate il pacchetto sul computer cliccando sul link <strong>One-click Download<\/strong>. Ci saranno due file: installer.php e archive.zip.<\/p>\n<h3>Installazione del duplicato in una nuova posizione<\/h3>\n<p>Per installare il pacchetto in un nuovo sito, \u00e8 necessario caricare i due file appena scaricati sul nuovo sito, utilizzando l&#8217;<a href=\"https:\/\/kimgsta.com\/it\/blog\/come-utilizzare-sftp\/\" target=\"_blank\" rel=\"noopener noreferrer\">SFTP<\/a>. Caricateli nella directory principale del vostro sito o nella directory dove volete installare WordPress. <strong>Non installate WordPress<\/strong>: il programma di installazione lo far\u00e0 per voi.<\/p>\n<p>A questo punto, accedete al file di installazione nel browser all&#8217;indirizzo yoursite.com\/installer.php, dove yoursite.com \u00e8 il <a href=\"https:\/\/kimgsta.com\/it\/blog\/quanto-costa-un-nome-di-dominio\/\" target=\"_blank\" rel=\"noopener noreferrer\">nome di dominio<\/a> del nuovo sito.<\/p>\n<p>Sarete quindi guidati attraverso una <a href=\"https:\/\/snapcreek.com\/duplicator\/docs\/quick-start\/?utm_source=duplicator_free&#038;utm_medium=wordpress_plugin&#038;utm_content=package_built_install_help&#038;utm_campaign=duplicator_free#quick-040-q\" target=\"_blank\" rel=\"noopener noreferrer\">serie di passaggi<\/a> per caricare e installare i file dal vostro duplicato. Una volta terminato, avrete un duplicato del vostro sito presso il nuovo dominio.<\/p>\n<h2>Clonare un sito in una rete Multisito WordPress con un plugin<\/h2>\n<p>Se il sito che volete clonare fa parte di una rete <a href=\"https:\/\/kimgsta.com\/it\/hosting-wordpress\/multisito\/\" target=\"_blank\" rel=\"noopener noreferrer\">WordPress Multisite,<\/a> non sar\u00e0 possibile clonarlo utilizzando la dashboard MyKinsta, ma sar\u00e0 necessario utilizzare un plugin.<\/p>\n<p>I due plugin qui sotto sono progettati per semplificare il processo di clonazione di un sito.<\/p>\n<aside role=\"note\" class=\"wp-block-kinsta-notice is-style-important\">\n            <h3>Important<\/h3>\n        <p>Non permettiamo la clonazione di interi siti su Kinsta con il plugin All-in-One WP Migration. Per migrare un sito completo, utilizzare il cruscotto MyKinsta, seguendo i passi precedenti.<\/p>\n<\/aside>\n\n<h3>NS Cloner \u2013 Site Copier<\/h3>\n<p>Con il plugin <a href=\"https:\/\/wordpress.org\/plugins\/ns-cloner-site-copier\/\" target=\"_blank\" rel=\"noopener noreferrer\">NS Cloner &#8211; Site Copier<\/a>, \u00e8 possibile creare rapidamente una copia esatta di un sito con un solo clic oppure personalizzare il modo in cui il sito viene duplicato in modo molto pi\u00f9 dettagliato acquistando un componente aggiuntivo premium.<\/p>\n<p>Nella sezione di amministrazione della rete, installare il plugin e attivarlo.<\/p>\n<p>Ora avete due modi per clonare i siti:<\/p>\n<ol>\n<li>Si pu\u00f2 andare alla schermata Siti e fare clic su <strong>Clone<\/strong> sotto il nome del sito che si desidera clonare.<\/li>\n<li>Oppure \u00e8 possibile utilizzare la voce <strong>NS Cloner V3<\/strong> nel menu di amministrazione della rete.<\/li>\n<\/ol>\n<p>Facendo clic su <strong>Clone<\/strong> nella schermata Sites, il sito viene clonato in un clic esattamente come \u00e8 senza alcuna personalizzazione. Pertanto, se volete un duplicato esatto del sito, questo \u00e8 un modo molto rapido per farlo. Se invece preferite apportare delle personalizzazioni al nuovo sito, fate clic sulla voce di menu NS Cloner V3.<\/p>\n<figure style=\"width: 1500px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/kimgsta.com\/it\/wp-content\/uploads\/sites\/2\/2017\/10\/ns-cloner-plugin.jpg\" alt=\"Plugin NS Clone WordPress\" width=\"1500\" height=\"823\"><figcaption class=\"wp-caption-text\">Plugin NS Clone WordPress<\/figcaption><\/figure>\n<p>Qui \u00e8 possibile specificare esattamente cosa viene copiato sul nuovo sito:<\/p>\n<ul>\n<li><strong>Select source<\/strong>: selezionare il sito da clonare dall&#8217;elenco a discesa.<\/li>\n<li><strong>Create New Site:<\/strong> dare al nuovo sito un titolo e un URL.<\/li>\n<li><strong>Clone Tables\/Copy Users\/Copy Media Files:<\/strong> specificare quali tabelle, file e utenti da clonare acquistando un componente aggiuntivo premium.<\/li>\n<li><strong><a href=\"https:\/\/kimgsta.com\/it\/blog\/cerca-e-sostituisci-in-wordpress\/\">Search and Replace<\/a>:<\/strong> di nuovo con un componente aggiuntivo, \u00e8 possibile cercare nel database e sostituire i contenuti, come il nome di dominio del sito.<\/li>\n<li><strong>Additional settings:<\/strong> spuntare questa casella per creare un registro del clone da controllare nel caso in cui non funzioni come dovrebbe.<\/li>\n<\/ul>\n<p>Una volta soddisfatti delle impostazioni, fate clic sul pulsante <strong>Clone<\/strong> nell&#8217;area verde nella parte inferiore dello schermo e il plugin creer\u00e0 il clone per voi.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ci sono molte ragioni per cui potreste voler clonare il vostro sito WordPress. Forse state lanciando un secondo sito e volete usare il primo come modello &#8230;<\/p>\n","protected":false},"author":38,"featured_media":29965,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_kinsta_gated_content":false,"_kinsta_gated_content_redirect":"","footnotes":""},"tags":[67,3],"topic":[25872],"class_list":["post-29932","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","tag-webdev","tag-wordpress","topic-suggerimenti-wordpress"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.6 (Yoast SEO v24.6) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Come Clonare Facilmente un Sito WordPress (3 Semplici Passi)<\/title>\n<meta name=\"description\" content=\"Con Kinsta, clonare un sito \u00e8 un gioco da ragazzi! Dai un&#039;occhiata a questo tutorial su come clonare un sito WordPress con pochi clic.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/kimgsta.com\/it\/blog\/clonare-sito-wordpress\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Come clonare facilmente un sito WordPress\" \/>\n<meta property=\"og:description\" content=\"Con Kinsta, clonare un sito \u00e8 un gioco da ragazzi! Dai un&#039;occhiata a questo tutorial su come clonare un sito WordPress con pochi clic.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kimgsta.com\/it\/blog\/clonare-sito-wordpress\/\" \/>\n<meta property=\"og:site_name\" content=\"Kinsta\u00ae\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/kinstaitalia\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/fm.brianleejackson\" \/>\n<meta property=\"article:published_time\" content=\"2019-11-26T12:49:05+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-01T19:52:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/kimgsta.com\/it\/wp-content\/uploads\/sites\/2\/2019\/11\/clone-wordpress-sito.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1460\" \/>\n\t<meta property=\"og:image:height\" content=\"730\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Brian Jackson\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:description\" content=\"Con Kinsta, clonare un sito \u00e8 un gioco da ragazzi! Dai un&#039;occhiata a questo tutorial su come clonare un sito WordPress con pochi clic.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/kimgsta.com\/it\/wp-content\/uploads\/sites\/2\/2019\/11\/clone-wordpress-sito.jpg\" \/>\n<meta name=\"twitter:creator\" content=\"@brianleejackson\" \/>\n<meta name=\"twitter:site\" content=\"@Kinsta_IT\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Brian Jackson\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"14 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/kimgsta.com\/it\/blog\/clonare-sito-wordpress\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/kimgsta.com\/it\/blog\/clonare-sito-wordpress\/\"},\"author\":{\"name\":\"Brian Jackson\",\"@id\":\"https:\/\/kimgsta.com\/it\/#\/schema\/person\/079824c00ccc2b7141504f27ea63bef7\"},\"headline\":\"Come clonare facilmente un sito WordPress\",\"datePublished\":\"2019-11-26T12:49:05+00:00\",\"dateModified\":\"2025-10-01T19:52:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/kimgsta.com\/it\/blog\/clonare-sito-wordpress\/\"},\"wordCount\":2144,\"publisher\":{\"@id\":\"https:\/\/kimgsta.com\/it\/#organization\"},\"image\":{\"@id\":\"https:\/\/kimgsta.com\/it\/blog\/clonare-sito-wordpress\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/kimgsta.com\/it\/wp-content\/uploads\/sites\/2\/2019\/11\/clone-wordpress-sito.jpg\",\"keywords\":[\"webdev\",\"WordPress\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/kimgsta.com\/it\/blog\/clonare-sito-wordpress\/\",\"url\":\"https:\/\/kimgsta.com\/it\/blog\/clonare-sito-wordpress\/\",\"name\":\"Come Clonare Facilmente un Sito WordPress (3 Semplici Passi)\",\"isPartOf\":{\"@id\":\"https:\/\/kimgsta.com\/it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/kimgsta.com\/it\/blog\/clonare-sito-wordpress\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/kimgsta.com\/it\/blog\/clonare-sito-wordpress\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/kimgsta.com\/it\/wp-content\/uploads\/sites\/2\/2019\/11\/clone-wordpress-sito.jpg\",\"datePublished\":\"2019-11-26T12:49:05+00:00\",\"dateModified\":\"2025-10-01T19:52:32+00:00\",\"description\":\"Con Kinsta, clonare un sito \u00e8 un gioco da ragazzi! Dai un'occhiata a questo tutorial su come clonare un sito WordPress con pochi clic.\",\"breadcrumb\":{\"@id\":\"https:\/\/kimgsta.com\/it\/blog\/clonare-sito-wordpress\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/kimgsta.com\/it\/blog\/clonare-sito-wordpress\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/kimgsta.com\/it\/blog\/clonare-sito-wordpress\/#primaryimage\",\"url\":\"https:\/\/kimgsta.com\/it\/wp-content\/uploads\/sites\/2\/2019\/11\/clone-wordpress-sito.jpg\",\"contentUrl\":\"https:\/\/kimgsta.com\/it\/wp-content\/uploads\/sites\/2\/2019\/11\/clone-wordpress-sito.jpg\",\"width\":1460,\"height\":730,\"caption\":\"Clone WordPress sito\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/kimgsta.com\/it\/blog\/clonare-sito-wordpress\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/kimgsta.com\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Suggerimenti per WordPress\",\"item\":\"https:\/\/kimgsta.com\/it\/argomenti\/suggerimenti-wordpress\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Come clonare facilmente un sito WordPress\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/kimgsta.com\/it\/#website\",\"url\":\"https:\/\/kimgsta.com\/it\/\",\"name\":\"Kinsta\u00ae\",\"description\":\"Soluzioni di hosting premium, veloci e sicure\",\"publisher\":{\"@id\":\"https:\/\/kimgsta.com\/it\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/kimgsta.com\/it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/kimgsta.com\/it\/#organization\",\"name\":\"Kinsta\",\"url\":\"https:\/\/kimgsta.com\/it\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/kimgsta.com\/it\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/kimgsta.com\/it\/wp-content\/uploads\/sites\/2\/2023\/12\/kinsta-logo.jpeg\",\"contentUrl\":\"https:\/\/kimgsta.com\/it\/wp-content\/uploads\/sites\/2\/2023\/12\/kinsta-logo.jpeg\",\"width\":500,\"height\":500,\"caption\":\"Kinsta\"},\"image\":{\"@id\":\"https:\/\/kimgsta.com\/it\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/kinstaitalia\/\",\"https:\/\/x.com\/Kinsta_IT\",\"https:\/\/www.instagram.com\/kinstahosting\/\",\"https:\/\/www.linkedin.com\/company\/kinsta\/\",\"https:\/\/www.pinterest.com\/kinstahosting\/\",\"https:\/\/www.youtube.com\/c\/Kinsta\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/kimgsta.com\/it\/#\/schema\/person\/079824c00ccc2b7141504f27ea63bef7\",\"name\":\"Brian Jackson\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/kimgsta.com\/it\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/79623d815f4ed4c8c2457392d728cb16?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/79623d815f4ed4c8c2457392d728cb16?s=96&d=mm&r=g\",\"caption\":\"Brian Jackson\"},\"description\":\"Brian has a huge passion for WordPress, has been using it for over a decade, and even develops a couple of premium plugins. Brian enjoys blogging, movies, and hiking. Connect with Brian on Twitter.\",\"sameAs\":[\"https:\/\/www.facebook.com\/fm.brianleejackson\",\"https:\/\/www.linkedin.com\/in\/brianleejackson\",\"https:\/\/x.com\/brianleejackson\"],\"url\":\"https:\/\/kimgsta.com\/it\/blog\/author\/brianjackson\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Come Clonare Facilmente un Sito WordPress (3 Semplici Passi)","description":"Con Kinsta, clonare un sito \u00e8 un gioco da ragazzi! Dai un'occhiata a questo tutorial su come clonare un sito WordPress con pochi clic.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/kimgsta.com\/it\/blog\/clonare-sito-wordpress\/","og_locale":"it_IT","og_type":"article","og_title":"Come clonare facilmente un sito WordPress","og_description":"Con Kinsta, clonare un sito \u00e8 un gioco da ragazzi! Dai un'occhiata a questo tutorial su come clonare un sito WordPress con pochi clic.","og_url":"https:\/\/kimgsta.com\/it\/blog\/clonare-sito-wordpress\/","og_site_name":"Kinsta\u00ae","article_publisher":"https:\/\/www.facebook.com\/kinstaitalia\/","article_author":"https:\/\/www.facebook.com\/fm.brianleejackson","article_published_time":"2019-11-26T12:49:05+00:00","article_modified_time":"2025-10-01T19:52:32+00:00","og_image":[{"width":1460,"height":730,"url":"https:\/\/kimgsta.com\/it\/wp-content\/uploads\/sites\/2\/2019\/11\/clone-wordpress-sito.jpg","type":"image\/jpeg"}],"author":"Brian Jackson","twitter_card":"summary_large_image","twitter_description":"Con Kinsta, clonare un sito \u00e8 un gioco da ragazzi! Dai un'occhiata a questo tutorial su come clonare un sito WordPress con pochi clic.","twitter_image":"https:\/\/kimgsta.com\/it\/wp-content\/uploads\/sites\/2\/2019\/11\/clone-wordpress-sito.jpg","twitter_creator":"@brianleejackson","twitter_site":"@Kinsta_IT","twitter_misc":{"Scritto da":"Brian Jackson","Tempo di lettura stimato":"14 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/kimgsta.com\/it\/blog\/clonare-sito-wordpress\/#article","isPartOf":{"@id":"https:\/\/kimgsta.com\/it\/blog\/clonare-sito-wordpress\/"},"author":{"name":"Brian Jackson","@id":"https:\/\/kimgsta.com\/it\/#\/schema\/person\/079824c00ccc2b7141504f27ea63bef7"},"headline":"Come clonare facilmente un sito WordPress","datePublished":"2019-11-26T12:49:05+00:00","dateModified":"2025-10-01T19:52:32+00:00","mainEntityOfPage":{"@id":"https:\/\/kimgsta.com\/it\/blog\/clonare-sito-wordpress\/"},"wordCount":2144,"publisher":{"@id":"https:\/\/kimgsta.com\/it\/#organization"},"image":{"@id":"https:\/\/kimgsta.com\/it\/blog\/clonare-sito-wordpress\/#primaryimage"},"thumbnailUrl":"https:\/\/kimgsta.com\/it\/wp-content\/uploads\/sites\/2\/2019\/11\/clone-wordpress-sito.jpg","keywords":["webdev","WordPress"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/kimgsta.com\/it\/blog\/clonare-sito-wordpress\/","url":"https:\/\/kimgsta.com\/it\/blog\/clonare-sito-wordpress\/","name":"Come Clonare Facilmente un Sito WordPress (3 Semplici Passi)","isPartOf":{"@id":"https:\/\/kimgsta.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/kimgsta.com\/it\/blog\/clonare-sito-wordpress\/#primaryimage"},"image":{"@id":"https:\/\/kimgsta.com\/it\/blog\/clonare-sito-wordpress\/#primaryimage"},"thumbnailUrl":"https:\/\/kimgsta.com\/it\/wp-content\/uploads\/sites\/2\/2019\/11\/clone-wordpress-sito.jpg","datePublished":"2019-11-26T12:49:05+00:00","dateModified":"2025-10-01T19:52:32+00:00","description":"Con Kinsta, clonare un sito \u00e8 un gioco da ragazzi! Dai un'occhiata a questo tutorial su come clonare un sito WordPress con pochi clic.","breadcrumb":{"@id":"https:\/\/kimgsta.com\/it\/blog\/clonare-sito-wordpress\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/kimgsta.com\/it\/blog\/clonare-sito-wordpress\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/kimgsta.com\/it\/blog\/clonare-sito-wordpress\/#primaryimage","url":"https:\/\/kimgsta.com\/it\/wp-content\/uploads\/sites\/2\/2019\/11\/clone-wordpress-sito.jpg","contentUrl":"https:\/\/kimgsta.com\/it\/wp-content\/uploads\/sites\/2\/2019\/11\/clone-wordpress-sito.jpg","width":1460,"height":730,"caption":"Clone WordPress sito"},{"@type":"BreadcrumbList","@id":"https:\/\/kimgsta.com\/it\/blog\/clonare-sito-wordpress\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/kimgsta.com\/it\/"},{"@type":"ListItem","position":2,"name":"Suggerimenti per WordPress","item":"https:\/\/kimgsta.com\/it\/argomenti\/suggerimenti-wordpress\/"},{"@type":"ListItem","position":3,"name":"Come clonare facilmente un sito WordPress"}]},{"@type":"WebSite","@id":"https:\/\/kimgsta.com\/it\/#website","url":"https:\/\/kimgsta.com\/it\/","name":"Kinsta\u00ae","description":"Soluzioni di hosting premium, veloci e sicure","publisher":{"@id":"https:\/\/kimgsta.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/kimgsta.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/kimgsta.com\/it\/#organization","name":"Kinsta","url":"https:\/\/kimgsta.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/kimgsta.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/kimgsta.com\/it\/wp-content\/uploads\/sites\/2\/2023\/12\/kinsta-logo.jpeg","contentUrl":"https:\/\/kimgsta.com\/it\/wp-content\/uploads\/sites\/2\/2023\/12\/kinsta-logo.jpeg","width":500,"height":500,"caption":"Kinsta"},"image":{"@id":"https:\/\/kimgsta.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/kinstaitalia\/","https:\/\/x.com\/Kinsta_IT","https:\/\/www.instagram.com\/kinstahosting\/","https:\/\/www.linkedin.com\/company\/kinsta\/","https:\/\/www.pinterest.com\/kinstahosting\/","https:\/\/www.youtube.com\/c\/Kinsta"]},{"@type":"Person","@id":"https:\/\/kimgsta.com\/it\/#\/schema\/person\/079824c00ccc2b7141504f27ea63bef7","name":"Brian Jackson","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/kimgsta.com\/it\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/79623d815f4ed4c8c2457392d728cb16?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/79623d815f4ed4c8c2457392d728cb16?s=96&d=mm&r=g","caption":"Brian Jackson"},"description":"Brian has a huge passion for WordPress, has been using it for over a decade, and even develops a couple of premium plugins. Brian enjoys blogging, movies, and hiking. Connect with Brian on Twitter.","sameAs":["https:\/\/www.facebook.com\/fm.brianleejackson","https:\/\/www.linkedin.com\/in\/brianleejackson","https:\/\/x.com\/brianleejackson"],"url":"https:\/\/kimgsta.com\/it\/blog\/author\/brianjackson\/"}]}},"acf":[],"_links":{"self":[{"href":"https:\/\/kimgsta.com\/it\/wp-json\/wp\/v2\/posts\/29932","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kimgsta.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/kimgsta.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/kimgsta.com\/it\/wp-json\/wp\/v2\/users\/38"}],"replies":[{"embeddable":true,"href":"https:\/\/kimgsta.com\/it\/wp-json\/wp\/v2\/comments?post=29932"}],"version-history":[{"count":18,"href":"https:\/\/kimgsta.com\/it\/wp-json\/wp\/v2\/posts\/29932\/revisions"}],"predecessor-version":[{"id":80015,"href":"https:\/\/kimgsta.com\/it\/wp-json\/wp\/v2\/posts\/29932\/revisions\/80015"}],"alternate":[{"embeddable":true,"hreflang":"es","title":"Spanish","href":"https:\/\/kimgsta.com\/it\/wp-json\/kinsta\/v1\/posts\/29932\/translations\/es"},{"embeddable":true,"hreflang":"en","title":"English","href":"https:\/\/kimgsta.com\/it\/wp-json\/kinsta\/v1\/posts\/29932\/translations\/en"},{"embeddable":true,"hreflang":"pt","title":"Portuguese","href":"https:\/\/kimgsta.com\/it\/wp-json\/kinsta\/v1\/posts\/29932\/translations\/pt"},{"embeddable":true,"hreflang":"fr","title":"French","href":"https:\/\/kimgsta.com\/it\/wp-json\/kinsta\/v1\/posts\/29932\/translations\/fr"},{"embeddable":true,"hreflang":"de","title":"German","href":"https:\/\/kimgsta.com\/it\/wp-json\/kinsta\/v1\/posts\/29932\/translations\/de"},{"embeddable":true,"hreflang":"it","title":"Italian","href":"https:\/\/kimgsta.com\/it\/wp-json\/kinsta\/v1\/posts\/29932\/translations\/it"},{"embeddable":true,"hreflang":"nl","title":"Dutch","href":"https:\/\/kimgsta.com\/it\/wp-json\/kinsta\/v1\/posts\/29932\/translations\/nl"},{"href":"https:\/\/kimgsta.com\/it\/wp-json\/kinsta\/v1\/posts\/29932\/tree"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/kimgsta.com\/it\/wp-json\/wp\/v2\/media\/29965"}],"wp:attachment":[{"href":"https:\/\/kimgsta.com\/it\/wp-json\/wp\/v2\/media?parent=29932"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/kimgsta.com\/it\/wp-json\/wp\/v2\/tags?post=29932"},{"taxonomy":"topic","embeddable":true,"href":"https:\/\/kimgsta.com\/it\/wp-json\/wp\/v2\/topic?post=29932"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}