{"id":30106,"date":"2019-12-04T23:57:17","date_gmt":"2019-12-05T07:57:17","guid":{"rendered":"https:\/\/kimgsta.com\/?p=57372"},"modified":"2025-09-01T16:28:08","modified_gmt":"2025-09-01T15:28:08","slug":"email-adressen-finden","status":"publish","type":"post","link":"https:\/\/kimgsta.com\/de\/blog\/email-adressen-finden\/","title":{"rendered":"13 M\u00f6glichkeiten, die E-Mail-Adresse von jemandem zu finden (Bring deine Outreach Kampagnen auf ein neues Level)"},"content":{"rendered":"<p>Du willst also die E-Mail-Adresse von jemandem finden.<\/p>\n<p>M\u00f6glicherweise willst du einen <a href=\"https:\/\/kimgsta.com\/de\/blog\/instagram-statistiken\/#staggering-stats-of-instagrams-influencer-marketing\" target=\"_blank\" rel=\"noopener noreferrer\">Influencer<\/a> erreichen, eine Liste potenzieller Kundenkontakte erstellen oder einfach nur jemandem eine kurze Frage stellen.<\/p>\n<p>Es gibt viele Gr\u00fcnde, warum du nach einer bestimmten E-Mail-Adresse suchen m\u00f6chtest. Gl\u00fccklicherweise gibt es auch viele verschiedene (intelligente) Wege, sie zu finden.<\/p>\n<p><strong>Willst du lieber die <a href=\"https:\/\/www.youtube.com\/watch?v=6MLQpmuvX7s\">Videoversion<\/a> sehen?<\/strong><\/p>\n<kinsta-video src=\"https:\/\/www.youtube.com\/watch?v=6MLQpmuvX7s\"><\/kinsta-video>\n<h2>Warum es wichtig ist, die richtige E-Mail-Adresse zu finden.<\/h2>\n<p>Wenn du eine wichtige E-Mail schickst, musst du die richtigen Person einreichen. Warum? Weil es verdammt schwer ist, die Aufmerksamkeit der Leute auf sich zu ziehen. Beachte, dass <a href=\"https:\/\/backlinko.com\/email-outreach-study\" target=\"_blank\" rel=\"noopener noreferrer\">nur 8,5% der Outreach-E-Mails<\/a> eine Antwort erhalten.<\/p>\n<p>Die richtige Person zum Lesen deiner E-Mails zu finden, verbessert deine Chancen, die gew\u00fcnschte Antwort zu erhalten. <strong>Es lohnt sich also zu 100%, Zeit damit zu verbringen, die E-Mail-Adresse von jemandem zu finden und deine Nachricht zu optimieren.<\/strong><\/p>\n<p>Dies gilt insbesondere, wenn du versuchst, jemanden zu erreichen, den du nicht kennst oder mit dem du noch nie gesprochen hast.<\/p>\n<p>Nun, gehen wir auf E-Mail-Jagd\u2026<\/p>\n<h2 id=\"how-to-find-someones-email-address\">Wie finde ich die E-Mail Adresse von jemandem?<\/h2>\n<p>Hier sind einige der solidesten Taktiken und Tools, die ich in der Vergangenheit verwendet habe &#8211; und immer noch benutze -, um die E-Mail-Adresse einer Person zu finden. Lasst uns anfangen!<\/p>\n<div><\/div><kinsta-auto-toc list-style=\"decimal\" selector=\"h3\" count-number=\"13\" sub-toc=\"true\"><\/kinsta-auto-toc>\n<h3>1. Verwenden eines E-Mail-Suchwerkzeugs<\/h3>\n<p>Eine der einfachsten M\u00f6glichkeiten, eine E-Mail-Adresse zu finden, ist die Verwendung eines E-Mail-Suchdienstes. Alles, was du tun musst, ist den Namen einer Person und\/oder eine Website einzugeben, und das Tool sucht nach der entsprechenden Adresse f\u00fcr dich.<\/p>\n<figure id=\"attachment_30108\" aria-describedby=\"caption-attachment-30108\" style=\"width: 1500px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-30108\" src=\"https:\/\/kimgsta.com\/de\/wp-content\/uploads\/sites\/5\/2019\/12\/email-suchdienst.png\" alt=\"Nutze einen Email Suchdienst (wie Hunter)\" width=\"1500\" height=\"447\" srcset=\"https:\/\/kimgsta.com\/de\/wp-content\/uploads\/sites\/5\/2019\/12\/email-suchdienst.png 1500w, https:\/\/kimgsta.com\/de\/wp-content\/uploads\/sites\/5\/2019\/12\/email-suchdienst-300x89.png 300w, https:\/\/kimgsta.com\/de\/wp-content\/uploads\/sites\/5\/2019\/12\/email-suchdienst-768x229.png 768w, https:\/\/kimgsta.com\/de\/wp-content\/uploads\/sites\/5\/2019\/12\/email-suchdienst-1024x305.png 1024w\" sizes=\"auto, (max-width: 1500px) 100vw, 1500px\" \/><figcaption id=\"caption-attachment-30108\" class=\"wp-caption-text\">Nutze einen Email Suchdienst (wie Hunter)<\/figcaption><\/figure>\n<p>Obwohl sie unglaublich n\u00fctzlich sein k\u00f6nnen, ist es nicht garantiert, dass du jedes Mal, wenn du sie benutzt, ein erfolgreiches Ergebnis erh\u00e4ltst. Die kostenlosen Suchanfragen sind begrenzt und die bezahlten Optionen k\u00f6nnen am Ende recht teuer werden, besonders wenn du nicht die Adressen bekommst, nach denen du suchst.<\/p>\n<p>Die gute Nachricht ist, dass es eine fast endlose Liste von E-Mail-Suchwerkzeugen im Web gibt, so dass du viele Optionen hast, um zu sehen, was f\u00fcr dich funktioniert.<\/p>\n<p>E-Mail-Lookup-Dienste funktionieren alle im Wesentlichen auf die gleiche Weise: Du gibst einen Namen ein, versuchst, ihn so weit wie m\u00f6glich zu verfeinern, und das Tool geht und findet die beste E-Mail.<\/p>\n<p>Allerdings gibt es einige verschiedene Preisoptionen und Arten von Tools.<\/p>\n<p>Hier sind einige der beliebtesten E-Mail-Suchwerkzeuge, um dir den Einstieg zu erleichtern (zusammen mit den Kosten):<\/p>\n<ul>\n<li><a href=\"https:\/\/findthat.email\/\" target=\"_blank\" rel=\"noopener noreferrer\">Find That Email<\/a> &#8211; 50 kostenlose Suchanfragen\/Monat. Kostenpflichtige Konten ab 29 $\/Monat f\u00fcr 500 Suchen (0,058 $\/Suche).<\/li>\n<li><a href=\"https:\/\/hunter.io\/email-finder\">E-Mail Finder<\/a> von Hunter &#8211; 50 kostenlose Suchen\/Monat. Kostenpflichtige Konten ab $49\/Monat f\u00fcr 1.000 Suchen ($0,049\/Suche).<\/li>\n<li><a href=\"https:\/\/finder.expert\/\" target=\"_blank\" rel=\"noopener noreferrer\">Finder Expert<\/a> &#8211; 300 kostenlose Suchen\/Monat. Kostenpflichtige Konten von 39 $ pro Monat f\u00fcr 5.000 Suchen (0,008 $\/Suche).<\/li>\n<li><a href=\"https:\/\/snov.io\/\">Snov.io<\/a> &#8211; 50 kostenlose Suchen\/Monat. Kostenpflichtige Konten ab 29 $ f\u00fcr 1.000 Einzelrecherchen oder 500 Massenrecherchen (0,029 $\/Suche).<\/li>\n<li><a href=\"https:\/\/www.voilanorbert.com\/\" target=\"_blank\" rel=\"noopener noreferrer\">Voila Norbert<\/a> &#8211; Kostenloser Test von 50 kostenlosen Suchanfragen. Kostenpflichtige Konten ab 49 $\/Monat f\u00fcr 1.000 Suchen (0,049 $\/Suche).<\/li>\n<li><a href=\"https:\/\/findthatlead.com\/en\" target=\"_blank\" rel=\"noopener noreferrer\">FindThatLead<\/a> &#8211; 50 kostenlose Suchen\/Monat. Kostenpflichtige Konten ab 49 $\/Monat f\u00fcr 5.000 Suchen (0,0098 $\/Suche).<\/li>\n<li><a href=\"https:\/\/www.egrabber.com\/emailprospector\/\" target=\"_blank\" rel=\"noopener noreferrer\">eMail-Prospector Pro<\/a> &#8211; Kostenlose Testversion mit 50 kostenlosen Suchanfragen. Kostenpflichtige Konten ab 1.195 $ pro Jahr, begrenzt auf 4.000 Suchanfragen (0,299 $\/Suche).<\/li>\n<li><a href=\"https:\/\/www.findemails.com\/\" target=\"_blank\" rel=\"noopener noreferrer\">FindEmails.com<\/a> &#8211; Kostenlose Testversion von 50 kostenlosen Suchanfragen. Kostenpflichtige Konten ab 19 $\/Monat f\u00fcr 500 Suchen (0,038 $\/Suche).<\/li>\n<li><a href=\"https:\/\/contactout.com\/email-finder\">ContactOut<\/a> &#8211; 40 kostenlose Suchanfragen\/Monat. Kostenpflichtige Konten ab 29 $\/Monat f\u00fcr 1800 Suchanfragen (0,0161 $\/Suche).<\/li>\n<\/ul>\n<h4>Wie finde ich die E-Mail-Adresse von jemandem kostenlos?<\/h4>\n<p>Wenn du ein knappes Budget hast, gibt es hier drei schnelle M\u00f6glichkeiten, E-Mails kostenlos zu finden:<\/p>\n<ul>\n<li><a href=\"https:\/\/connect.clearbit.com\/\" target=\"_blank\" rel=\"noopener noreferrer\">Clearbit Connect<\/a> ist ein Add-on f\u00fcr Google Mail und Outlook, das nach den E-Mails einer Person aus verschiedenen Quellen und ihrer eigenen Datenbank sucht. (auch Interessant: schau dir <a href=\"https:\/\/kimgsta.com\/de\/blog\/gmail-add-ons\/\">die besten Gmail-Add-ons und -Erweiterungen<\/a> an, um deine Produktivit\u00e4t zu verbessern.)<\/li>\n<li><a href=\"https:\/\/getprospect.io\/\" target=\"_blank\" rel=\"noopener noreferrer\">GetProspect<\/a> ist eine Chrome-Erweiterung, mit der du die E-Mail-Adresse einer Person anhand ihres Namens und ihrer Domain finden kannst.<\/li>\n<li><a href=\"https:\/\/rocketreach.co\/\" target=\"_blank\" rel=\"noopener noreferrer\">RocketReach<\/a> kann schnell E-Mails f\u00fcr dich finden, besonders wenn dein Ziel ein ziemlich hohes Ansehen hat. Melde dich einfach f\u00fcr ein kostenloses Konto an und starte die E-Mail-Suche.<\/li>\n<\/ul>\n<h3>2. Benutze &#8222;@domainname.com&#8220; auf DuckDuckGo<\/h3>\n<p>Dieser wenig bekannte Trick ist eine gute M\u00f6glichkeit, E-Mail-Adressen einfach \u00fcber eine <a href=\"https:\/\/kimgsta.com\/de\/blog\/alternative-suchmaschinen\/\" target=\"_blank\" rel=\"noopener noreferrer\">alternative Suchmaschine<\/a> zu finden.<\/p>\n<p>Wenn du in DuckDuckGo eine exakte \u00dcbereinstimmungssuche nach &#8222;@domainname.com&#8220; durchf\u00fchrst, erh\u00e4ltst du Ergebnisse f\u00fcr alle an die Domain angeh\u00e4ngten E-Mail-Adressen, die \u00f6ffentlich zug\u00e4nglich sind.<\/p>\n<p>Du kannst den Namen deines potenziellen Kunden in die Suche einbeziehen, wenn du jemanden kontaktieren m\u00f6chtest, oder ihn einfach allgemein halten.<\/p>\n<figure style=\"width: 1500px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/kimgsta.com\/de\/wp-content\/uploads\/sites\/5\/2019\/10\/emails-auf-duckduckgo-finden.png\" alt=\"Emails auf DuckDuckGo finden\" width=\"1500\" height=\"648\"><figcaption class=\"wp-caption-text\">Emails auf DuckDuckGo finden<\/figcaption><\/figure>\n<p>Es ist ein praktischer Trick, der in DuckDuckGo und mehreren anderen Suchmaschinen hervorragend funktioniert. Leider verwendet Google &#8222;@&#8220; f\u00fcr Social Media Tags, so dass dieser Trick nicht funktioniert und auch bei <a href=\"https:\/\/kimgsta.com\/de\/blog\/bing-webmaster-tools\/\" target=\"_blank\" rel=\"noopener noreferrer\">Bing<\/a> funktioniert das nicht.<\/p>\n<h3>3. Twitter verwenden<\/h3>\n<p>Leute geben manchmal ihre E-Mail-Adressen in ihren Tweets oder <a href=\"https:\/\/kimgsta.com\/de\/blog\/twitter-statistiken\/\">Twitter<\/a>-Bio ein, versuchen aber, sie vor Bots zu verstecken, indem sie &#8222;dot&#8220; und &#8222;at&#8220; anstelle von &#8222;.&#8220; und &#8222;@&#8220; verwenden.<\/p>\n<p>Gehe zur <a href=\"https:\/\/twitter.com\/search-advanced\" target=\"_blank\" rel=\"noopener noreferrer\">erweiterten Twitter-Suche<\/a> und suche in den Tweets deines potenziellen Kunden nach &#8222;at&#8220; und &#8222;dot&#8220;.<\/p>\n<p>Du kannst nach genauen Phrasen suchen, W\u00f6rter ignorieren, Hashtags, bestimmte Konten und Zeitrahmen ausw\u00e4hlen. Spiele hier mit den Inputs herum. Versuche, W\u00f6rter wie &#8222;E-Mail&#8220;, &#8222;Reichweite&#8220; oder &#8222;Kontakt&#8220; aufzunehmen, um die Ergebnisse besser zu filtern.<\/p>\n<figure style=\"width: 1500px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/kimgsta.com\/de\/wp-content\/uploads\/sites\/5\/2019\/10\/erweiterte-twittersuche.png\" alt=\"Verwende die erweiterte Twittersuche um Emails zu finden\" width=\"1500\" height=\"845\"><figcaption class=\"wp-caption-text\">Verwende die erweiterte Twittersuche um Emails zu finden<\/figcaption><\/figure>\n<p>Es klingt mutig, aber du kannst auch versuchen, sie einfach auf Twitter nach ihrer E-Mail-Adresse zu fragen.<\/p>\n<p>Um deinem Tweet die beste Chance zu geben, wahrgenommen zu werden und eine Antwort zu erhalten, halte ihn kurz und schlie\u00dfe einen zwingenden Grund f\u00fcr seine Antwort ein:<\/p>\n<figure style=\"width: 587px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/kimgsta.com\/de\/wp-content\/uploads\/sites\/5\/2019\/11\/email-finden.png\" alt=\"Manchmal muss man nur direkt fragen, um die E-Mail-Adresse zu erhalten\" width=\"587\" height=\"765\"><figcaption class=\"wp-caption-text\">Manchmal muss man nur direkt fragen, um die E-Mail-Adresse zu erhalten<\/figcaption><\/figure>\n<p>Du kannst sie auch durch ihre direkten Nachrichten ansprechen, die deine potenzielle Kunden eher ansehen als durch ihre Antworten oder Erw\u00e4hnungen. Abh\u00e4ngig von den Datenschutzeinstellungen musst du dich m\u00f6glicherweise zuerst gegenseitig folgen, bevor du ihnen ein DM schicken kannst.<\/p>\n<h4>Wie kann ich alte Tweets von jemandem \u00fcberpr\u00fcfen?<\/h4>\n<p>Es gibt tats\u00e4chlich eine letzte Taktik, die du mit Twitter nutzen kannst, um die vergangenen Tweets der Benutzer zu \u00fcberpr\u00fcfen. Mit der <a href=\"https:\/\/www.allmytweets.net\/connect\/\">All My Tweets<\/a> App kannst du eine Liste von bis zu 3200 fr\u00fcheren Tweets von jedem kostenlos erstellen.<\/p>\n<p>So benutzt man es:<\/p>\n<p>Gehe zu <a href=\"https:\/\/www.allmytweets.net\/connect\/\">All My Tweets<\/a> und melde dich mit deinem Twitter-Account an.<\/p>\n<figure style=\"width: 1500px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/kimgsta.com\/wp-content\/uploads\/2019\/10\/all-my-tweets.png\" alt=\"Alle Tweets eines Benutzers auf einer Seite anzeigen \u00fcber All My Tweets\" width=\"1500\" height=\"715\"><figcaption class=\"wp-caption-text\">Alle Tweets eines Benutzers auf einer Seite anzeigen \u00fcber All My Tweets<\/figcaption><\/figure>\n<p>Gib dann den Twitter-Handle der Webseite oder Person ein, mit der du dich verbinden m\u00f6chtest, um ihre Tweets zu erhalten.<\/p>\n<figure style=\"width: 1500px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/kimgsta.com\/de\/wp-content\/uploads\/sites\/5\/2019\/10\/fuge-einen-benutzernamen-hinzu.png\" alt=\"F\u00fcge einen Benutzernamen hinzu, um alle Tweets anzuzeigen\" width=\"1500\" height=\"504\"><figcaption class=\"wp-caption-text\">F\u00fcge einen Benutzernamen hinzu, um alle Tweets anzuzeigen<\/figcaption><\/figure>\n<p>Sobald du diese aufgelistet hast, dr\u00fccke einfach Strg\/Cmd+F und suche nach Dingen wie <em>@domainname<\/em>, <em>&#8222;contact&#8220;<\/em>, <em>&#8222;email&#8220;<\/em>, <em>&#8222;you can reach me at&#8220;<\/em> und anderen Varianten, die eine E-Mail-Adresse anzeigen k\u00f6nnten.<\/p>\n<h3>4. Abonniere die E-Mail-Liste f\u00fcr potenzielle Kunden<\/h3>\n<p>Die meisten Webseiten haben eine <a href=\"https:\/\/kimgsta.com\/de\/blog\/wie-man-eine-e-mail-liste\/\" target=\"_blank\" rel=\"noopener noreferrer\">E-Mail-Liste<\/a>.<\/p>\n<figure style=\"width: 1500px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/kimgsta.com\/de\/wp-content\/uploads\/sites\/5\/2019\/10\/sich-bei-einer-email-liste-anmelden-1.png\" alt=\"Sich bei einer Email Liste anmelden\" width=\"1500\" height=\"357\"><figcaption class=\"wp-caption-text\">Sich bei einer E-Mail Liste anmelden<\/figcaption><\/figure>\n<p>Wenn die Webseite oder der Blog deines potenziellen Kunden einen <a href=\"https:\/\/kimgsta.com\/de\/wordpress-newsletter\/\" target=\"_blank\" rel=\"noopener noreferrer\">Newsletter<\/a> enth\u00e4lt, melde dich bei seiner Mailingliste an, da viele Newsletter von einer pers\u00f6nlichen E-Mail-Adresse gesendet werden. Dies kann ein schneller und einfacher Weg sein, um die gesuchte E-Mail-Adresse zu erhalten.<\/p>\n<p>Selbst wenn es von einer allgemeinen info@-Adresse gesendet wird, versuche, auf einen der Newsletter zu antworten, um eine Meinung zu \u00e4u\u00dfern oder eine aufschlussreiche Frage zu stellen, und du erh\u00e4ltst m\u00f6glicherweise eine Antwort.<\/p>\n<p>Dies kann dir helfen, eine Beziehung mit dem potenziellen Kunden aufzubauen und gibt dir eine bessere Chance, in Zukunft seine pers\u00f6nlichen E-Mail-Adressen zu erhalten.<\/p>\n<h3>5. Frage \u00fcber die allgemeine E-Mail-Adresse oder das Kontaktformular.<\/h3>\n<p>Die meisten Webseiten haben ein <a href=\"https:\/\/kimgsta.com\/de\/blog\/wordpress-kontaktformular-plugins\/\" target=\"_blank\" rel=\"noopener noreferrer\">Kontaktformular<\/a> auf ihrer Webseite oder bieten eine allgemeine info@-E-Mail-Adresse f\u00fcr allgemeine Anfragen.<\/p>\n<figure style=\"width: 1500px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/kimgsta.com\/de\/wp-content\/uploads\/sites\/5\/2019\/10\/standardkontaktformular-beispiel.png\" alt=\"Ein Beispiel f\u00fcr ein Standardkontaktformular\" width=\"1500\" height=\"1161\"><figcaption class=\"wp-caption-text\">Ein Beispiel f\u00fcr ein Standardkontaktformular<\/figcaption><\/figure>\n<p>W\u00e4hrend diese wahrscheinlich mit Verwaltungspersonal besetzt sind, kannst du versuchen, sie zu verwenden, um zu fragen, wie du mit deinem idealen Interessenten in Kontakt treten kannst.<\/p>\n<h3>6. Schaut euch die Kontakt- und \u00dcber uns Seiten an.<\/h3>\n<p>Manchmal sind die einfachsten L\u00f6sungen die besten. Viele Webseiten enthalten pers\u00f6nliche E-Mail-Adressen im <a href=\"https:\/\/kimgsta.com\/de\/kontaktiere-uns\/\" target=\"_blank\" rel=\"noopener noreferrer\">Kontakt<\/a>, <a href=\"https:\/\/kimgsta.com\/de\/uber-uns\/\" target=\"_blank\" rel=\"noopener noreferrer\">\u00fcber uns<\/a> oder auf den Teamseiten.<\/p>\n<p>H\u00e4ufig sind diese Seiten jedoch in der Navigation der Website schwierig zu finden. Wenn du nicht sehen kannst, wonach du suchst, schau in der Fu\u00dfzeile nach oder probiere diese g\u00e4ngigen URL-Formate aus:<\/p>\n<ul>\n<li><em>example.com\/contact<\/em><\/li>\n<li><em>example.com\/contact-us<\/em><\/li>\n<li><em>example.com\/contact-me<\/em><\/li>\n<li><em>example.com\/about<\/em><\/li>\n<li><em>example.com\/about-me<\/em><\/li>\n<li><em>example.com\/about-us<\/em><\/li>\n<li><em>example.com\/team<\/em><\/li>\n<li><em>example.com\/our-team<\/em><\/li>\n<li><em>example.com\/meet-the-team<\/em><\/li>\n<\/ul>\n<h3>7. Autorenseiten ansehen<\/h3>\n<p>Ein weiterer einfacher Ausgangspunkt ist die Autorenseite auf dem Blog oder der Website des potenziellen Kunden, die von ihrem Namen auf jedem Artikel, den sie geschrieben haben, verlinkt ist.<\/p>\n<p>Es kann oft eine Menge Informationen auf dieser Seite geben, besonders wenn sie Standard WordPress Themes und Einstellungen verwendet haben.<\/p>\n<h3>8. Mache ein WHOIS Lookup<\/h3>\n<p>Wenn du versuchst, eine E-Mail-Adresse von jemandem mit einer Webseite zu finden (vielleicht ein <a href=\"https:\/\/kimgsta.com\/de\/blog\/website-ideen\/\" target=\"_blank\" rel=\"noopener noreferrer\">unabh\u00e4ngiger Gesch\u00e4ftsinhaber<\/a>, <a href=\"https:\/\/kimgsta.com\/de\/blog\/wiederkehrende-umsatzmodell\/\" target=\"_blank\" rel=\"noopener noreferrer\">Entrepreneur<\/a> oder <a href=\"https:\/\/kimgsta.com\/de\/blog\/grammatik-checker-tools\/\" target=\"_blank\" rel=\"noopener noreferrer\">Autor<\/a>), kannst du manchmal seine Kontaktinformationen in den <a href=\"https:\/\/kimgsta.com\/de\/blog\/beste-domainregister\/#free-whois-protection\" target=\"_blank\" rel=\"noopener noreferrer\">WHOIS-Informationen<\/a> seiner Webseite finden.<\/p>\n<p>WHOIS-Daten werden bei der Registrierung einer Domain verwendet und sind \u00f6ffentlich zug\u00e4nglich, so dass du Informationen dar\u00fcber hast, wer die Domain besitzt. Jeder, der eine Webseite hat, ist gesetzlich verpflichtet, seine Kontaktdaten mitzuteilen. Gehe einfach zu <a href=\"https:\/\/who.is\/\" target=\"_blank\" rel=\"noopener noreferrer\">who.is<\/a> und suche die Domain der gesuchten E-Mail:<\/p>\n<figure style=\"width: 1500px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/kimgsta.com\/de\/wp-content\/uploads\/sites\/5\/2019\/10\/whois-lookup.png\" alt=\"WHOIS Lookup\" width=\"1500\" height=\"786\"><figcaption class=\"wp-caption-text\">WHOIS Lookup<\/figcaption><\/figure>\n<p>\u00dcbrigens gibt es auch andere WHOIS-Lookup-Tools, wie z.B.:<\/p>\n<ul>\n<li><a href=\"https:\/\/kimgsta.com\/de\/blog\/wie-viel-kostet-ein-domainname\/#namecheap\">NameCheap<\/a><\/li>\n<li><a href=\"https:\/\/whois.domaintools.com\/\">DomainTools<\/a><\/li>\n<li><a href=\"https:\/\/www.nominet.uk\/lookup\/\">Nominet<\/a><\/li>\n<li><a href=\"https:\/\/kimgsta.com\/de\/blog\/dmca-takedown-notice\/#1-find-the-person\">DMCA0s free WHOIS tool<\/a><\/li>\n<\/ul>\n<p>Es spielt keine Rolle, welches Werkzeug du verwendest. Wenn du Gl\u00fcck hast, kannst du die E-Mail sehen, mit der diese Domain registriert wurde. WHOIS bietet jedoch die M\u00f6glichkeit, <a href=\"https:\/\/kimgsta.com\/de\/blog\/beste-domainregister\/#free-whois-protection\" target=\"_blank\" rel=\"noopener noreferrer\">deine \u00f6ffentlichen Informationen vor ihren \u00f6ffentlichen Daten zu verstecken<\/a>, so dass dies nicht immer funktioniert.<\/p>\n<h3>9. Verwende Google (und Suchmaschinenbetreiber)<\/h3>\n<p>Entschuldigung: Dies ist offensichtlich, kann aber trotzdem \u00fcbersehen werden. Verwende Google f\u00fcr den vorgesehenen Zweck: die Suche.<\/p>\n<p>Gib den Namen deines potenziellen Kunden zusammen mit der &#8222;E-Mail-Adresse&#8220; ein und du hast vielleicht Gl\u00fcck.<\/p>\n<p>Wenn die gesuchte Person jedoch einen allgemeinen Namen hat, kann sich dies als schwierig erweisen. Selbst wenn sie einen eindeutigen Namen haben, kommst du vielleicht nicht sehr weit.<\/p>\n<p>Du kannst helfen, die Suche mit einigen Google-Suchoperatoren einzugrenzen. Diese sind super einfach zu bedienen. Gib einfach den Operator in Google ein und suche weiter:<\/p>\n<ul>\n<li>[Name] + E-Mail (oder) E-Mail-Adresse<\/li>\n<li>[Name] + Kontakt (oder) Kontaktinformationen (oder) Kontakt mit mir aufnehmen<\/li>\n<li>[Name] + &#8220; Heimatstadt &#8222;.<\/li>\n<li>[Name] + &#8222;Firma, f\u00fcr die sie arbeiten&#8220;.<\/li>\n<li>[Name] + LinkedIn<\/li>\n<li>[Name] + ZoomInfo<\/li>\n<li>[Name] + E-Mail<\/li>\n<li>[Name] + Kontakt<\/li>\n<\/ul>\n<p>Wenn du ein wenig \u00fcber mehr Informationen \u00fcber deine potenzielle Kunden wei\u00dft (z.B. wo sie arbeiten), kannst du diese ausprobieren:<\/p>\n<ul>\n<li>site:companywebsite.com + [name] + email<\/li>\n<li>site:companywebsite.com + [name] + Kontakt<\/li>\n<li>site:companywebsite.com + vorname.nachname[at] firmenname.com<\/li>\n<li>site:companywebsite.com + vornamelastname[at] companyname.com<\/li>\n<li>site:companywebsite.com + Vorname[at] Firmenname.com<\/li>\n<li>site:companywebsite.com + vorname_nachname[at] firmenname.com<\/li>\n<\/ul>\n<h3>10. Facebook Verwenden<\/h3>\n<p><a href=\"https:\/\/kimgsta.com\/de\/blog\/wie-man-eine-facebook-seite-erstellt\/\" target=\"_blank\" rel=\"noopener noreferrer\">Beim Einrichten einer Facebook-Seite<\/a> geben die Leute oft so viele Informationen wie m\u00f6glich ein und vergessen es dann.<\/p>\n<p>Gehe einfach auf die Info-Seite im Profil und du kannst die E-Mail-Adresse sehen, wenn sie hinzugef\u00fcgt wurde:<\/p>\n<figure style=\"width: 1500px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/kimgsta.com\/de\/wp-content\/uploads\/sites\/5\/2019\/10\/emails-auf-facebook-finden.png\" alt=\"Emails auf Facebook finden\" width=\"1500\" height=\"516\"><figcaption class=\"wp-caption-text\">E-Mails auf Facebook finden<\/figcaption><\/figure>\n<p>Dies macht Facebook zu einem gro\u00dfartigen Ort, um nach E-Mail-Adressen f\u00fcr deine potenziellen Kunden zu suchen, und wird dir wahrscheinlich ihre am h\u00e4ufigsten verwendete E-Mail-Adresse anstelle von etwas Generischem geben.<\/p>\n<h3>11. \u00dcberpr\u00fcfe deine eigene E-Mail-Liste<\/h3>\n<p>Abh\u00e4ngig von deiner eigenen Sichtbarkeit in deiner Branche kannst du feststellen, dass einige deiner potenziellen Kunden bereits deinen Newsletter abonniert haben.<\/p>\n<p>Eine schnelle Suche in deiner E-Mail-Liste k\u00f6nnte ohne gro\u00dfen Aufwand genau das enth\u00fcllen, was du suchst.<\/p>\n<p>Die meisten <a href=\"https:\/\/kimgsta.com\/de\/blog\/e-mail-marketing-software\/\" target=\"_blank\" rel=\"noopener noreferrer\">E-Mail-Marketing-Software<\/a> wird es dir erm\u00f6glichen, Ihre Liste nach Kontakten zu durchsuchen. So sieht es zum Beispiel in <a href=\"https:\/\/kimgsta.com\/de\/blog\/wie-man-mailchimp-verwendet\/\" target=\"_blank\" rel=\"noopener noreferrer\">Mailchimp<\/a> aus:<\/p>\n<figure style=\"width: 1500px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/kimgsta.com\/de\/wp-content\/uploads\/sites\/5\/2019\/10\/emails-in-mailchimp-finden.png\" alt=\"Suche nach E-Mails in deiner E-Mail-Marketing-Software\" width=\"1500\" height=\"909\"><figcaption class=\"wp-caption-text\">Suche nach E-Mails in deiner E-Mail-Marketing-Software (wie MailChimp)<\/figcaption><\/figure>\n<h3>12. Exportiere deine LinkedIn Kontakte<\/h3>\n<p>Wusstest du, dass <a href=\"https:\/\/kimgsta.com\/de\/blog\/linkedin-marketing\/\">LinkedIn<\/a> es dir erlaubt, deine Kontakte zu exportieren?<\/p>\n<p>Wenn du also mit deinem potenziellen Kunden in Verbindung stehst, kannst du vielleicht dessen E-Mail-Adresse einsehen.<\/p>\n<h4>Wie exportiere ich LinkedIn-Verbindungen?<\/h4>\n<p><strong>Schritt 1 <\/strong>&#8211; Klicke oben auf deiner LinkedIn-Homepage auf <strong>Mich<\/strong> und w\u00e4hle dann <strong>Einstellungen &#038; Datenschutz<\/strong> aus der Dropdown-Liste.<\/p>\n<figure style=\"width: 721px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/kimgsta.com\/de\/wp-content\/uploads\/sites\/5\/2019\/11\/emails-von-linkedin-exportieren.png\" alt=\"Emails von LinkedIn exportieren\" width=\"721\" height=\"273\"><figcaption class=\"wp-caption-text\">Emails von LinkedIn exportieren<\/figcaption><\/figure>\n<p><strong>Schritt 2<\/strong> &#8211; Klicke auf die Registerkarte <strong>Datenschutz<\/strong> und scrolle nach unten zum Abschnitt <strong>Eine Kopie deiner Daten erhalten<\/strong> (unter dem Abschnitt Wie LinkedIn deine Daten verwendet):<\/p>\n<figure style=\"width: 1500px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/kimgsta.com\/de\/wp-content\/uploads\/sites\/5\/2019\/10\/email-daten-aus-linkedin-downloaden.png\" alt=\"Email Daten aus LinkedIn downloaden\" width=\"1500\" height=\"598\"><figcaption class=\"wp-caption-text\">Email Daten aus LinkedIn downloaden<\/figcaption><\/figure>\n<p><strong>Schritt 3<\/strong> &#8211; Aktiviere das Kontrollk\u00e4stchen Verbindungen und klicke auf <strong>Archiv anfordern<\/strong>.<\/p>\n<figure style=\"width: 1500px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/kimgsta.com\/de\/wp-content\/uploads\/sites\/5\/2019\/10\/kopiere-linkedin-daten.png\" alt=\"Kopiere LinkedIn-Daten, um E-Mail-Adressen zu erhalten.\" width=\"1500\" height=\"1112\"><figcaption class=\"wp-caption-text\">Kopiere LinkedIn-Daten, um E-Mail-Adressen zu erhalten.<\/figcaption><\/figure>\n<p>In etwa 10 Minuten oder so bekommst du eine E-Mail mit allen E-Mail-Adressen deiner Verbindungen in einer praktischen Tabelle.<\/p>\n<p>Diese Methode sollte verantwortungsbewusst eingesetzt werden, um zu verhindern, dass du dein <a href=\"https:\/\/kimgsta.com\/de\/blog\/linkedin-statistiken\/\" target=\"_blank\" rel=\"noopener noreferrer\">LinkedIn-Konto<\/a> verlierst.<\/p>\n<h3>13. Denk schlau dr\u00fcber nach<\/h3>\n<p>Wenn du dar\u00fcber nachdenkst, folgen so ziemlich alle E-Mail-Adressen den gleichen wenigen Mustern. Sie basieren oft auf ganz einfachen Formaten.<\/p>\n<p>Wenn du also Vorname, Nachname und <a href=\"https:\/\/kimgsta.com\/de\/blog\/wie-viel-kostet-ein-domainname\/\" target=\"_blank\" rel=\"noopener noreferrer\">Domain<\/a> deines potenziellen Kunden kennst, kannst du vielleicht dessen E-Mail-Adresse erraten.<\/p>\n<p>Wenn du bereits die E-Mail-Adresse einer anderen Person im selben Unternehmen hast, kannst du wahrscheinlich herausfinden, welche Struktur sie verwendet.<\/p>\n<p>Wenn nicht, versuche diese allgemeinen Formeln:<\/p>\n<ul>\n<li>[name]@example.com<\/li>\n<li>[name].[surname]@example.com<\/li>\n<li>[name][surname]@example.com<\/li>\n<li>[initial].[surname]@example.com<\/li>\n<\/ul>\n\n<h2>Zusammenfassung<\/h2>\n<p>Da haben wir es, wie man die E-Mail-Adressen von jemandem findet. Denke nur daran: Mit gro\u00dfer Macht kommt gro\u00dfe Verantwortung.<\/p>\n<p>Verwende also diese E-Mail-Findungsmethoden sinnvoll. <a href=\"https:\/\/kimgsta.com\/de\/blog\/e-mail-authentifizierung\/\" target=\"_blank\" rel=\"noopener noreferrer\">Spamme nicht<\/a>! Verkaufe keine E-Mail-Adressen von Personen. Und nerve nicht die Leute, die du erreicht hast&#8230; du verpasst die einzige gro\u00dfe Gelegenheit, dich zu verbinden und (Gesch\u00e4fts-)Verbindungen aufzubauen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Du willst also die E-Mail-Adresse von jemandem finden. M\u00f6glicherweise willst du einen Influencer erreichen, eine Liste potenzieller Kundenkontakte erstellen oder einfach nur jemandem eine kurze Frage &#8230;<\/p>\n","protected":false},"author":103,"featured_media":30123,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_kinsta_gated_content":false,"_kinsta_gated_content_redirect":"","footnotes":""},"tags":[88,232],"topic":[940],"class_list":["post-30106","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","tag-emailmarketing","tag-outreach","topic-e-mail-marketing-tipps"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.6 (Yoast SEO v24.6) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>13 M\u00f6glichkeiten, die E-Mail-Adresse von jemandem zu finden<\/title>\n<meta name=\"description\" content=\"Dieser Leitfaden zeigt dir 13 M\u00f6glichkeiten + Tools, um die (echte) E-Mail-Adresse von jemandem zu finden.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/kimgsta.com\/de\/blog\/email-adressen-finden\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"13 M\u00f6glichkeiten, die E-Mail-Adresse von jemandem zu finden (Bring deine Outreach Kampagnen auf ein neues Level)\" \/>\n<meta property=\"og:description\" content=\"Dieser Leitfaden zeigt dir 13 M\u00f6glichkeiten + Tools, um die (echte) E-Mail-Adresse von jemandem zu finden.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kimgsta.com\/de\/blog\/email-adressen-finden\/\" \/>\n<meta property=\"og:site_name\" content=\"Kinsta\u00ae\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Kinsta-Deutschland-207459890108303\/\" \/>\n<meta property=\"article:published_time\" content=\"2019-12-05T07:57:17+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-01T15:28:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/kimgsta.com\/de\/wp-content\/uploads\/sites\/5\/2019\/12\/email-adresse-finden.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1460\" \/>\n\t<meta property=\"og:image:height\" content=\"730\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Matteo Du\u00f2\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:description\" content=\"Dieser Leitfaden zeigt dir 13 M\u00f6glichkeiten + Tools, um die (echte) E-Mail-Adresse von jemandem zu finden.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/kimgsta.com\/de\/wp-content\/uploads\/sites\/5\/2019\/12\/email-adresse-finden.jpg\" \/>\n<meta name=\"twitter:creator\" content=\"@matteoduo\" \/>\n<meta name=\"twitter:site\" content=\"@Kinsta_DE\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Matteo Du\u00f2\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"13\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/kimgsta.com\/de\/blog\/email-adressen-finden\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/kimgsta.com\/de\/blog\/email-adressen-finden\/\"},\"author\":{\"name\":\"Matteo Du\u00f2\",\"@id\":\"https:\/\/kimgsta.com\/de\/#\/schema\/person\/9d811e805493f00205e6409451055174\"},\"headline\":\"13 M\u00f6glichkeiten, die E-Mail-Adresse von jemandem zu finden (Bring deine Outreach Kampagnen auf ein neues Level)\",\"datePublished\":\"2019-12-05T07:57:17+00:00\",\"dateModified\":\"2025-09-01T15:28:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/kimgsta.com\/de\/blog\/email-adressen-finden\/\"},\"wordCount\":2327,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/kimgsta.com\/de\/#organization\"},\"image\":{\"@id\":\"https:\/\/kimgsta.com\/de\/blog\/email-adressen-finden\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/kimgsta.com\/de\/wp-content\/uploads\/sites\/5\/2019\/12\/email-adresse-finden.jpg\",\"keywords\":[\"emailmarketing\",\"outreach\"],\"articleSection\":[\"Unternehmenswachstumstrategien\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/kimgsta.com\/de\/blog\/email-adressen-finden\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/kimgsta.com\/de\/blog\/email-adressen-finden\/\",\"url\":\"https:\/\/kimgsta.com\/de\/blog\/email-adressen-finden\/\",\"name\":\"13 M\u00f6glichkeiten, die E-Mail-Adresse von jemandem zu finden\",\"isPartOf\":{\"@id\":\"https:\/\/kimgsta.com\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/kimgsta.com\/de\/blog\/email-adressen-finden\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/kimgsta.com\/de\/blog\/email-adressen-finden\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/kimgsta.com\/de\/wp-content\/uploads\/sites\/5\/2019\/12\/email-adresse-finden.jpg\",\"datePublished\":\"2019-12-05T07:57:17+00:00\",\"dateModified\":\"2025-09-01T15:28:08+00:00\",\"description\":\"Dieser Leitfaden zeigt dir 13 M\u00f6glichkeiten + Tools, um die (echte) E-Mail-Adresse von jemandem zu finden.\",\"breadcrumb\":{\"@id\":\"https:\/\/kimgsta.com\/de\/blog\/email-adressen-finden\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/kimgsta.com\/de\/blog\/email-adressen-finden\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/kimgsta.com\/de\/blog\/email-adressen-finden\/#primaryimage\",\"url\":\"https:\/\/kimgsta.com\/de\/wp-content\/uploads\/sites\/5\/2019\/12\/email-adresse-finden.jpg\",\"contentUrl\":\"https:\/\/kimgsta.com\/de\/wp-content\/uploads\/sites\/5\/2019\/12\/email-adresse-finden.jpg\",\"width\":1460,\"height\":730,\"caption\":\"E-Mail-Adresse von jemandem zu finden\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/kimgsta.com\/de\/blog\/email-adressen-finden\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/kimgsta.com\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tipps zum E-Mail-Marketing\",\"item\":\"https:\/\/kimgsta.com\/de\/thema\/e-mail-marketing-tipps\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"13 M\u00f6glichkeiten, die E-Mail-Adresse von jemandem zu finden (Bring deine Outreach Kampagnen auf ein neues Level)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/kimgsta.com\/de\/#website\",\"url\":\"https:\/\/kimgsta.com\/de\/\",\"name\":\"Kinsta\u00ae\",\"description\":\"Schnelle, sichere und hochwertige Hosting-L\u00f6sungen\",\"publisher\":{\"@id\":\"https:\/\/kimgsta.com\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/kimgsta.com\/de\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/kimgsta.com\/de\/#organization\",\"name\":\"Kinsta\",\"url\":\"https:\/\/kimgsta.com\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/kimgsta.com\/de\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/kimgsta.com\/de\/wp-content\/uploads\/sites\/5\/2023\/12\/kinsta-logo.jpeg\",\"contentUrl\":\"https:\/\/kimgsta.com\/de\/wp-content\/uploads\/sites\/5\/2023\/12\/kinsta-logo.jpeg\",\"width\":500,\"height\":500,\"caption\":\"Kinsta\"},\"image\":{\"@id\":\"https:\/\/kimgsta.com\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/Kinsta-Deutschland-207459890108303\/\",\"https:\/\/x.com\/Kinsta_DE\",\"https:\/\/www.instagram.com\/kinstahosting\/\",\"https:\/\/www.linkedin.com\/company\/kinsta\/\",\"https:\/\/www.pinterest.com\/kinstahosting\/\",\"https:\/\/www.youtube.com\/c\/Kinsta\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/kimgsta.com\/de\/#\/schema\/person\/9d811e805493f00205e6409451055174\",\"name\":\"Matteo Du\u00f2\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/kimgsta.com\/de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/78636e34d9c125b93efb7e0893a776f8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/78636e34d9c125b93efb7e0893a776f8?s=96&d=mm&r=g\",\"caption\":\"Matteo Du\u00f2\"},\"description\":\"Head of Content at Kinsta and Content Marketing Consultant for WordPress plugin developers. Connect with Matteo on Twitter.\",\"sameAs\":[\"https:\/\/www.matteoduo.com\",\"https:\/\/www.linkedin.com\/in\/matteoduo\/\",\"https:\/\/x.com\/matteoduo\"],\"url\":\"https:\/\/kimgsta.com\/de\/blog\/author\/matteoduo\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"13 M\u00f6glichkeiten, die E-Mail-Adresse von jemandem zu finden","description":"Dieser Leitfaden zeigt dir 13 M\u00f6glichkeiten + Tools, um die (echte) E-Mail-Adresse von jemandem zu finden.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/kimgsta.com\/de\/blog\/email-adressen-finden\/","og_locale":"de_DE","og_type":"article","og_title":"13 M\u00f6glichkeiten, die E-Mail-Adresse von jemandem zu finden (Bring deine Outreach Kampagnen auf ein neues Level)","og_description":"Dieser Leitfaden zeigt dir 13 M\u00f6glichkeiten + Tools, um die (echte) E-Mail-Adresse von jemandem zu finden.","og_url":"https:\/\/kimgsta.com\/de\/blog\/email-adressen-finden\/","og_site_name":"Kinsta\u00ae","article_publisher":"https:\/\/www.facebook.com\/Kinsta-Deutschland-207459890108303\/","article_published_time":"2019-12-05T07:57:17+00:00","article_modified_time":"2025-09-01T15:28:08+00:00","og_image":[{"width":1460,"height":730,"url":"https:\/\/kimgsta.com\/de\/wp-content\/uploads\/sites\/5\/2019\/12\/email-adresse-finden.jpg","type":"image\/jpeg"}],"author":"Matteo Du\u00f2","twitter_card":"summary_large_image","twitter_description":"Dieser Leitfaden zeigt dir 13 M\u00f6glichkeiten + Tools, um die (echte) E-Mail-Adresse von jemandem zu finden.","twitter_image":"https:\/\/kimgsta.com\/de\/wp-content\/uploads\/sites\/5\/2019\/12\/email-adresse-finden.jpg","twitter_creator":"@matteoduo","twitter_site":"@Kinsta_DE","twitter_misc":{"Verfasst von":"Matteo Du\u00f2","Gesch\u00e4tzte Lesezeit":"13\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/kimgsta.com\/de\/blog\/email-adressen-finden\/#article","isPartOf":{"@id":"https:\/\/kimgsta.com\/de\/blog\/email-adressen-finden\/"},"author":{"name":"Matteo Du\u00f2","@id":"https:\/\/kimgsta.com\/de\/#\/schema\/person\/9d811e805493f00205e6409451055174"},"headline":"13 M\u00f6glichkeiten, die E-Mail-Adresse von jemandem zu finden (Bring deine Outreach Kampagnen auf ein neues Level)","datePublished":"2019-12-05T07:57:17+00:00","dateModified":"2025-09-01T15:28:08+00:00","mainEntityOfPage":{"@id":"https:\/\/kimgsta.com\/de\/blog\/email-adressen-finden\/"},"wordCount":2327,"commentCount":0,"publisher":{"@id":"https:\/\/kimgsta.com\/de\/#organization"},"image":{"@id":"https:\/\/kimgsta.com\/de\/blog\/email-adressen-finden\/#primaryimage"},"thumbnailUrl":"https:\/\/kimgsta.com\/de\/wp-content\/uploads\/sites\/5\/2019\/12\/email-adresse-finden.jpg","keywords":["emailmarketing","outreach"],"articleSection":["Unternehmenswachstumstrategien"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/kimgsta.com\/de\/blog\/email-adressen-finden\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/kimgsta.com\/de\/blog\/email-adressen-finden\/","url":"https:\/\/kimgsta.com\/de\/blog\/email-adressen-finden\/","name":"13 M\u00f6glichkeiten, die E-Mail-Adresse von jemandem zu finden","isPartOf":{"@id":"https:\/\/kimgsta.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/kimgsta.com\/de\/blog\/email-adressen-finden\/#primaryimage"},"image":{"@id":"https:\/\/kimgsta.com\/de\/blog\/email-adressen-finden\/#primaryimage"},"thumbnailUrl":"https:\/\/kimgsta.com\/de\/wp-content\/uploads\/sites\/5\/2019\/12\/email-adresse-finden.jpg","datePublished":"2019-12-05T07:57:17+00:00","dateModified":"2025-09-01T15:28:08+00:00","description":"Dieser Leitfaden zeigt dir 13 M\u00f6glichkeiten + Tools, um die (echte) E-Mail-Adresse von jemandem zu finden.","breadcrumb":{"@id":"https:\/\/kimgsta.com\/de\/blog\/email-adressen-finden\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/kimgsta.com\/de\/blog\/email-adressen-finden\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/kimgsta.com\/de\/blog\/email-adressen-finden\/#primaryimage","url":"https:\/\/kimgsta.com\/de\/wp-content\/uploads\/sites\/5\/2019\/12\/email-adresse-finden.jpg","contentUrl":"https:\/\/kimgsta.com\/de\/wp-content\/uploads\/sites\/5\/2019\/12\/email-adresse-finden.jpg","width":1460,"height":730,"caption":"E-Mail-Adresse von jemandem zu finden"},{"@type":"BreadcrumbList","@id":"https:\/\/kimgsta.com\/de\/blog\/email-adressen-finden\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/kimgsta.com\/de\/"},{"@type":"ListItem","position":2,"name":"Tipps zum E-Mail-Marketing","item":"https:\/\/kimgsta.com\/de\/thema\/e-mail-marketing-tipps\/"},{"@type":"ListItem","position":3,"name":"13 M\u00f6glichkeiten, die E-Mail-Adresse von jemandem zu finden (Bring deine Outreach Kampagnen auf ein neues Level)"}]},{"@type":"WebSite","@id":"https:\/\/kimgsta.com\/de\/#website","url":"https:\/\/kimgsta.com\/de\/","name":"Kinsta\u00ae","description":"Schnelle, sichere und hochwertige Hosting-L\u00f6sungen","publisher":{"@id":"https:\/\/kimgsta.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/kimgsta.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/kimgsta.com\/de\/#organization","name":"Kinsta","url":"https:\/\/kimgsta.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/kimgsta.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/kimgsta.com\/de\/wp-content\/uploads\/sites\/5\/2023\/12\/kinsta-logo.jpeg","contentUrl":"https:\/\/kimgsta.com\/de\/wp-content\/uploads\/sites\/5\/2023\/12\/kinsta-logo.jpeg","width":500,"height":500,"caption":"Kinsta"},"image":{"@id":"https:\/\/kimgsta.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Kinsta-Deutschland-207459890108303\/","https:\/\/x.com\/Kinsta_DE","https:\/\/www.instagram.com\/kinstahosting\/","https:\/\/www.linkedin.com\/company\/kinsta\/","https:\/\/www.pinterest.com\/kinstahosting\/","https:\/\/www.youtube.com\/c\/Kinsta"]},{"@type":"Person","@id":"https:\/\/kimgsta.com\/de\/#\/schema\/person\/9d811e805493f00205e6409451055174","name":"Matteo Du\u00f2","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/kimgsta.com\/de\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/78636e34d9c125b93efb7e0893a776f8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/78636e34d9c125b93efb7e0893a776f8?s=96&d=mm&r=g","caption":"Matteo Du\u00f2"},"description":"Head of Content at Kinsta and Content Marketing Consultant for WordPress plugin developers. Connect with Matteo on Twitter.","sameAs":["https:\/\/www.matteoduo.com","https:\/\/www.linkedin.com\/in\/matteoduo\/","https:\/\/x.com\/matteoduo"],"url":"https:\/\/kimgsta.com\/de\/blog\/author\/matteoduo\/"}]}},"acf":[],"_links":{"self":[{"href":"https:\/\/kimgsta.com\/de\/wp-json\/wp\/v2\/posts\/30106","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kimgsta.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/kimgsta.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/kimgsta.com\/de\/wp-json\/wp\/v2\/users\/103"}],"replies":[{"embeddable":true,"href":"https:\/\/kimgsta.com\/de\/wp-json\/wp\/v2\/comments?post=30106"}],"version-history":[{"count":13,"href":"https:\/\/kimgsta.com\/de\/wp-json\/wp\/v2\/posts\/30106\/revisions"}],"predecessor-version":[{"id":73945,"href":"https:\/\/kimgsta.com\/de\/wp-json\/wp\/v2\/posts\/30106\/revisions\/73945"}],"alternate":[{"embeddable":true,"hreflang":"en","title":"English","href":"https:\/\/kimgsta.com\/de\/wp-json\/kinsta\/v1\/posts\/30106\/translations\/en"},{"embeddable":true,"hreflang":"it","title":"Italian","href":"https:\/\/kimgsta.com\/de\/wp-json\/kinsta\/v1\/posts\/30106\/translations\/it"},{"embeddable":true,"hreflang":"pt","title":"Portuguese","href":"https:\/\/kimgsta.com\/de\/wp-json\/kinsta\/v1\/posts\/30106\/translations\/pt"},{"embeddable":true,"hreflang":"es","title":"Spanish","href":"https:\/\/kimgsta.com\/de\/wp-json\/kinsta\/v1\/posts\/30106\/translations\/es"},{"embeddable":true,"hreflang":"fr","title":"French","href":"https:\/\/kimgsta.com\/de\/wp-json\/kinsta\/v1\/posts\/30106\/translations\/fr"},{"embeddable":true,"hreflang":"nl","title":"Dutch","href":"https:\/\/kimgsta.com\/de\/wp-json\/kinsta\/v1\/posts\/30106\/translations\/nl"},{"embeddable":true,"hreflang":"de","title":"German","href":"https:\/\/kimgsta.com\/de\/wp-json\/kinsta\/v1\/posts\/30106\/translations\/de"},{"embeddable":true,"hreflang":"sv","title":null,"href":"https:\/\/kimgsta.com\/de\/wp-json\/kinsta\/v1\/posts\/30106\/translations\/se"},{"embeddable":true,"hreflang":"ja","title":"Japanese","href":"https:\/\/kimgsta.com\/de\/wp-json\/kinsta\/v1\/posts\/30106\/translations\/jp"},{"embeddable":true,"hreflang":"da","title":null,"href":"https:\/\/kimgsta.com\/de\/wp-json\/kinsta\/v1\/posts\/30106\/translations\/dk"},{"href":"https:\/\/kimgsta.com\/de\/wp-json\/kinsta\/v1\/posts\/30106\/tree"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/kimgsta.com\/de\/wp-json\/wp\/v2\/media\/30123"}],"wp:attachment":[{"href":"https:\/\/kimgsta.com\/de\/wp-json\/wp\/v2\/media?parent=30106"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/kimgsta.com\/de\/wp-json\/wp\/v2\/tags?post=30106"},{"taxonomy":"topic","embeddable":true,"href":"https:\/\/kimgsta.com\/de\/wp-json\/wp\/v2\/topic?post=30106"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}